{"id":6351,"date":"2026-03-20T12:06:32","date_gmt":"2026-03-20T10:06:32","guid":{"rendered":"https:\/\/nhrclb.org\/protocol-additional-geneva-conventions-12-august-1949"},"modified":"2026-04-05T19:20:19","modified_gmt":"2026-04-05T16:20:19","slug":"protocol-additional-geneva-conventions-12-august-1949","status":"publish","type":"page","link":"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949","title":{"rendered":"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I)"},"content":{"rendered":"<p><strong>ADOPT\u00c9 08 juin 1977 PAR la Conf\u00e9rence diplomatique sur la r\u00e9affirmation et le d\u00e9veloppement du droit international humanitaire<\/strong><\/p>\n<p><strong>Entr\u00e9e en vigueur : le 7 d\u00e9cembre 1978, conform\u00e9ment aux dispositions de l&rsquo;Article 95<\/strong><\/p>\n<h3>Pr\u00e9ambule<\/h3>\n<p>Les Hautes Parties contractantes<\/p>\n<p>Proclamant leur d\u00e9sir ardent de voir la paix r\u00e9gner entre les peuples,<\/p>\n<p>Rappelant que tout Etat a le devoir, conform\u00e9ment \u00e0 la Charte des Nations Unies, de s&rsquo;abstenir dans ses relations internationales de recourir \u00e0 la menace ou \u00e0 l&#8217;emploi de la force, soit contre la souverainet\u00e9, l&rsquo;int\u00e9grit\u00e9 territoriale ou l&rsquo;ind\u00e9pendance politique de tout Etat, soit de toute autre mani\u00e8re incompatible avec les buts des Nations Unies,<\/p>\n<p>Jugeant toutefois n\u00e9cessaire de r\u00e9affirmer et de d\u00e9velopper les dispositions qui prot\u00e8gent les victimes des conflits arm\u00e9s et de compl\u00e9ter les mesures propres \u00e0 en renforcer l&rsquo;application,<\/p>\n<p>Exprimant leur conviction qu&rsquo;aucune disposition du pr\u00e9sent Protocole ou des Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 ne peut \u00eatre interpr\u00e9t\u00e9e comme l\u00e9gitimant ou autorisant tout acte d&rsquo;agression ou tout autre emploi de la force incompatible avec la Charte des Nations Unies,<\/p>\n<p>R\u00e9affirmant, en outre, que les dispositions des Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 et du pr\u00e9sent Protocole doivent \u00eatre pleinement appliqu\u00e9es en toutes circonstances \u00e0 toutes les personnes prot\u00e9g\u00e9es par ces instruments, sans aucune distinction d\u00e9favorable fond\u00e9e sur la nature ou l&rsquo;origine du conflit arm\u00e9 ou sur les causes soutenues par les Parties au conflit, ou attribu\u00e9es \u00e0 celles-ci,<\/p>\n<p>Sont convenues de ce qui suit :<\/p>\n<h3>Titre I &#8211; Dispositions g\u00e9n\u00e9rales<\/h3>\n<h6 id=\"article-1--general-principles-and-scope-of-application\">Article premier &#8211; Principes g\u00e9n\u00e9raux et champ d&rsquo;application<\/h6>\n<p>1. Les Hautes Parties contractantes s&rsquo;engagent \u00e0 respecter et \u00e0 faire respecter le pr\u00e9sent Protocole en toutes circonstances.<\/p>\n<p>2. Dans les cas non pr\u00e9vus par le pr\u00e9sent Protocole ou par d&rsquo;autres accords internationaux, les personnes civiles et les combattants restent sous la sauvegarde et sous l&#8217;empire des principes du droit des gens, tels qu&rsquo;ils r\u00e9sultent des usages \u00e9tablis, des principes de l&rsquo;humanit\u00e9 et des exigences de la conscience publique.<\/p>\n<p>3. Le pr\u00e9sent Protocole, qui compl\u00e8te les Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 pour la protection des victimes de la guerre, s&rsquo;applique dans les situations pr\u00e9vues par l&rsquo;article 2 commun \u00e0 ces Conventions.<\/p>\n<p>4. Dans les situations vis\u00e9es au paragraphe pr\u00e9c\u00e9dent sont compris les conflits arm\u00e9s dans lesquels les peuples luttent contre la domination coloniale et l&rsquo;occupation \u00e9trang\u00e8re et contre les r\u00e9gimes racistes dans l&rsquo;exercice du droit des peuples \u00e0 disposer d&rsquo;eux-m\u00eames, consacr\u00e9 dans la Charte des Nations Unies et dans la D\u00e9claration relative aux principes du droit international touchant les relations amicales et la coop\u00e9ration entre les Etats conform\u00e9ment \u00e0 la Charte des Nations Unies.<\/p>\n<h6 id=\"article-2--definitions\">Article 2 &#8211; D\u00e9finitions<\/h6>\n<p>Aux fins du pr\u00e9sent Protocole :<\/p>\n<p>a) les expressions \u00ab\u00a0Ire Convention\u00a0\u00bb, \u00ab\u00a0IIe Convention\u00a0\u00bb, \u00ab\u00a0IIIe Convention\u00a0\u00bb et \u00ab\u00a0IVe Convention\u00a0\u00bb s&rsquo;entendent, respectivement, de la Convention de Gen\u00e8ve pour l&rsquo;am\u00e9lioration du sort des bless\u00e9s et des malades dans les forces arm\u00e9es en campagne, du 12 ao\u00fbt 1949; de la Convention de Gen\u00e8ve pour l&rsquo;am\u00e9lioration du sort des bless\u00e9s, des malades et des naufrag\u00e9s des forces arm\u00e9es sur mer, du 12 ao\u00fbt 1949; de la Convention de Gen\u00e8ve relative au traitement des prisonniers de guerre, du 12 ao\u00fbt 1949; de la Convention de Gen\u00e8ve relative \u00e0 la protection des personnes civiles en temps de guerre, du 12 ao\u00fbt 1949; l&rsquo;expression \u00ab\u00a0les Conventions\u00a0\u00bb s&rsquo;entend des quatre Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 pour la protection des victimes de la guerre;<\/p>\n<p>b) l&rsquo;expression \u00ab\u00a0r\u00e8gles du droit international applicable dans les conflits arm\u00e9s\u00a0\u00bb s&rsquo;entend des r\u00e8gles \u00e9nonc\u00e9es dans les accords internationaux auxquels participent les Parties au conflit ainsi que des principes et r\u00e8gles du droit international g\u00e9n\u00e9ralement reconnus qui sont applicables aux conflits arm\u00e9s;<\/p>\n<p>c) l&rsquo;expression \u00ab\u00a0Puissance protectrice\u00a0\u00bb s&rsquo;entend d&rsquo;un Etat neutre ou d&rsquo;un autre Etat non Partie au conflit qui, d\u00e9sign\u00e9 par une Partie au conflit et accept\u00e9 par la Partie adverse, est dispos\u00e9 \u00e0 exercer les fonctions assign\u00e9es \u00e0 la Puissance protectrice aux termes des Conventions et du pr\u00e9sent Protocole;<\/p>\n<p>d) l&rsquo;expression \u00ab\u00a0substitut\u00a0\u00bb s&rsquo;entend d&rsquo;une organisation qui remplace la Puissance protectrice conform\u00e9ment \u00e0 l&rsquo;article 5.<\/p>\n<h6 id=\"article-3--beginning-and-end-of-application\">Article 3 &#8211; D\u00e9but et fin de l&rsquo;application<\/h6>\n<p>Sans pr\u00e9judice des dispositions applicables en tout temps :<\/p>\n<p>a) les Conventions et le pr\u00e9sent Protocole s&rsquo;appliquent d\u00e8s le d\u00e9but de toute situation vis\u00e9e \u00e0 l&rsquo;article premier du pr\u00e9sent Protocole;<\/p>\n<p>b) l&rsquo;application des Conventions et du pr\u00e9sent Protocole cesse, sur le territoire des Parties au conflit, \u00e0 la fin g\u00e9n\u00e9rale des op\u00e9rations militaires et, dans le cas des territoires occup\u00e9s, \u00e0 la fin de l&rsquo;occupation, sauf, dans les deux cas, pour les cat\u00e9gories de personnes dont la lib\u00e9ration d\u00e9finitive, le rapatriement ou l&rsquo;\u00e9tablissement ont lieu ult\u00e9rieurement. Ces personnes continuent \u00e0 b\u00e9n\u00e9ficier des dispositions pertinentes des Conventions et du pr\u00e9sent Protocole jusqu&rsquo;\u00e0 leur lib\u00e9ration d\u00e9finitive, leur rapatriement ou leur \u00e9tablissement.<\/p>\n<h6 id=\"article-4--legal-status-of-the-parties-to-the-conflict\">Article 4 &#8211; Statut juridique des Parties au conflit<\/h6>\n<p>L&rsquo;application des Conventions et du pr\u00e9sent Protocole ainsi que la conclusion des accords pr\u00e9vus par ces instruments n&rsquo;auront pas d&rsquo;effet sur le statut juridique des Parties au conflit. Ni l&rsquo;occupation d&rsquo;un territoire ni l&rsquo;application des Conventions et du pr\u00e9sent Protocole n&rsquo;affecteront le statut juridique du territoire en question.<\/p>\n<h6 id=\"article-5--appointment-of-protecting-powers-and-of-their-substitute\">Article 5 &#8211; D\u00e9signation des Puissances protectrices et de leur substitut<\/h6>\n<p>1. Il est du devoir des Parties \u00e0 un conflit, d\u00e8s le d\u00e9but de ce conflit, d&rsquo;assurer le respect et la mise en oeuvre des Conventions et du pr\u00e9sent Protocole par l&rsquo;application du syst\u00e8me des Puissances protectrices, y compris notamment la d\u00e9signation et l&rsquo;acceptation de ces Puissances conform\u00e9ment aux paragraphes ci- apr\u00e8s. Les Puissances protectrices seront charg\u00e9es de sauvegarder les int\u00e9r\u00eats des Parties au conflit.<\/p>\n<p>2. D\u00e8s le d\u00e9but d&rsquo;une situation vis\u00e9e \u00e0 l&rsquo;article premier, chacune des Parties au conflit d\u00e9signera sans d\u00e9lai une Puissance protectrice aux fins d&rsquo;application des Conventions et du pr\u00e9sent Protocole et autorisera, \u00e9galement sans d\u00e9lai et aux m\u00eames fins, l&rsquo;activit\u00e9 d&rsquo;une Puissance protectrice que la Partie adverse aura d\u00e9sign\u00e9e et qu&rsquo;elle-m\u00eame aura accept\u00e9e comme telle.<\/p>\n<p>3. Si une Puissance protectrice n&rsquo;a pas \u00e9t\u00e9 d\u00e9sign\u00e9e ou accept\u00e9e d\u00e8s le d\u00e9but d&rsquo;une situation vis\u00e9e \u00e0 l&rsquo;article premier, le Comit\u00e9 international de la Croix-Rouge, sans pr\u00e9judice du droit de toute autre organisation humanitaire impartiale de faire de m\u00eame, offrira ses bons offices aux Parties au conflit en vue de la d\u00e9signation sans d\u00e9lai d&rsquo;une Puissance protectrice agr\u00e9\u00e9e par les Parties au conflit. A cet effet, il pourra notamment demander \u00e0 chaque Partie de lui remettre une liste d&rsquo;au moins cinq Etats que cette Partie estime acceptables pour agir en son nom en qualit\u00e9 de Puissance protectrice vis-\u00e0-vis d&rsquo;une Partie adverse et demander \u00e0 chacune des Parties adverses de remettre une liste d&rsquo;au moins cinq Etats qu&rsquo;elle accepterait comme Puissance protectrice de l&rsquo;autre Partie; ces listes devront \u00eatre communiqu\u00e9es au Comit\u00e9 dans les deux semaines qui suivront la r\u00e9ception de la demande; il les comparera et sollicitera l&rsquo;accord de tout Etat dont le nom figurera sur les deux listes.<\/p>\n<p>4. Si, en d\u00e9pit de ce qui pr\u00e9c\u00e8de, il y a d\u00e9faut de Puissance protectrice, les Parties au conflit devront accepter sans d\u00e9lai l&rsquo;offre que pourrait faire le Comit\u00e9 international de la Croix-Rouge ou toute autre organisation pr\u00e9sentant toutes garanties d&rsquo;impartialit\u00e9 et d&rsquo;efficacit\u00e9, apr\u00e8s dues consultations avec lesdites Parties et compte tenu des r\u00e9sultats de ces consultations, d&rsquo;agir en qualit\u00e9 de substitut. L&rsquo;exercice de ses fonctions par un tel substitut est subordonn\u00e9 au consentement des Parties au conflit; les Parties au conflit mettront tout en oeuvre pour faciliter la t\u00e2che du substitut dans l&rsquo;accomplissement de sa mission conform\u00e9ment aux Conventions et au pr\u00e9sent Protocole.<\/p>\n<p>5. Conform\u00e9ment \u00e0 l&rsquo;article 4, la d\u00e9signation et l&rsquo;acceptation de Puissances protectrices aux fins d&rsquo;application des Conventions et du pr\u00e9sent Protocole n&rsquo;auront pas d&rsquo;effet sur le statut juridique des Parties au conflit ni sur celui d&rsquo;un territoire quelconque, y compris un territoire occup\u00e9.<\/p>\n<p>6. Le maintien des relations diplomatiques entre les Parties au conflit ou le fait de confier \u00e0 un Etat tiers la protection des int\u00e9r\u00eats d&rsquo;une Partie et de ceux de ses ressortissants conform\u00e9ment aux r\u00e8gles du droit international concernant les relations diplomatiques ne fait pas obstacle \u00e0 la d\u00e9signation de Puissances protectrices aux fins d&rsquo;application des Conventions et du pr\u00e9sent Protocole.<\/p>\n<p>7. Toutes les fois qu&rsquo;il est fait mention ci-apr\u00e8s dans le pr\u00e9sent Protocole de la Puissance protectrice, cette mention d\u00e9signe \u00e9galement le substitut.<\/p>\n<h6 id=\"article-6--qualified-persons\">Article 6 &#8211; Personnel qualifi\u00e9<\/h6>\n<p>1. D\u00e8s le temps de paix, les Hautes Parties contractantes s&rsquo;efforceront, avec l&rsquo;aide des Soci\u00e9t\u00e9s nationales de la Croix-Rouge (Croissant-Rouge, Lion-et-Soleil-Rouge), de former un personnel qualifi\u00e9 en vue de faciliter l&rsquo;application des Conventions et du pr\u00e9sent Protocole et notamment l&rsquo;activit\u00e9 des Puissances protectrices.<\/p>\n<p>2. Le recrutement et la formation de ce personnel rel\u00e8vent de la comp\u00e9tence nationale.<\/p>\n<p>3. Le Comit\u00e9 international de la Croix-Rouge tiendra \u00e0 la disposition des Hautes Parties contractantes les listes des personnes ainsi form\u00e9es que les Hautes Parties contractantes auraient \u00e9tablies et lui auraient communiqu\u00e9es \u00e0 cette fin.<\/p>\n<p>4. Les conditions dans lesquelles ce personnel sera utilis\u00e9 en dehors du territoire national feront, dans chaque cas, l&rsquo;objet d&rsquo;accords sp\u00e9ciaux entre les Parties int\u00e9ress\u00e9es.<\/p>\n<h6 id=\"article-7--meetings\">Article 7 &#8211; R\u00e9unions<\/h6>\n<p>Le d\u00e9positaire du pr\u00e9sent Protocole convoquera, \u00e0 la demande d&rsquo;une ou de plusieurs des Hautes Parties contractantes et avec l&rsquo;approbation de la majorit\u00e9 de celles-ci, une r\u00e9union des Hautes Parties contractantes en vue d&rsquo;examiner les probl\u00e8mes g\u00e9n\u00e9raux relatifs \u00e0 l&rsquo;application des Conventions et du Protocole.<\/p>\n<h3>Titre II &#8211; Bless\u00e9s, malades et naufrag\u00e9s<\/h3>\n<h4 id=\"section-i--general-protection\">Section I &#8211; Protection g\u00e9n\u00e9rale<\/h4>\n<h6 id=\"article-8--terminology\">Article 8 &#8211; Terminologie<\/h6>\n<p>Aux fins du pr\u00e9sent Protocole :<\/p>\n<p>a) les termes \u00ab\u00a0bless\u00e9s\u00a0\u00bb et \u00ab\u00a0malades\u00a0\u00bb s&rsquo;entendent des personnes, militaires ou civiles, qui, en raison d&rsquo;un traumatisme, d&rsquo;une maladie ou d&rsquo;autres incapacit\u00e9s ou troubles physiques ou mentaux, ont besoin de soins m\u00e9dicaux et qui s&rsquo;abstiennent de tout acte d&rsquo;hostilit\u00e9. Ces termes visent aussi les femmes en couches, les nouveau-n\u00e9s, et les autres personnes qui pourraient avoir besoin de soins imm\u00e9diats, telles que les infirmes et les femmes enceintes, et qui s&rsquo;abstiennent de tout acte d&rsquo;hostilit\u00e9;<\/p>\n<p>b) le terme \u00ab\u00a0naufrag\u00e9s\u00a0\u00bb s&rsquo;entend des personnes, militaires ou civiles, se trouvant dans une situation p\u00e9rilleuse en mer ou en d&rsquo;autres eaux par suite de l&rsquo;infortune qui les frappe ou qui frappe le navire ou l&rsquo;a\u00e9ronef les transportant, et qui s&rsquo;abstiennent de tout acte d&rsquo;hostilit\u00e9. Ces personnes, \u00e0 condition qu&rsquo;elles continuent \u00e0 s&rsquo;abstenir de tout acte d&rsquo;hostilit\u00e9, continueront d&rsquo;\u00eatre consid\u00e9r\u00e9es comme des naufrag\u00e9s pendant leur sauvetage jusqu&rsquo;\u00e0 ce qu&rsquo;elles aient acquis un autre statut en vertu des Conventions ou du pr\u00e9sent Protocole;<\/p>\n<p>c) l&rsquo;expression \u00ab\u00a0personnel sanitaire\u00a0\u00bb s&rsquo;entend des personnes exclusivement affect\u00e9es par une Partie au conflit soit aux fins sanitaires \u00e9num\u00e9r\u00e9es \u00e0 l&rsquo;alin\u00e9a e, soit \u00e0 l&rsquo;administration d&rsquo;unit\u00e9s sanitaires, soit encore au fonctionnement ou \u00e0 l&rsquo;administration de moyens de transport sanitaire. Ces affectations peuvent \u00eatre permanentes ou temporaires. L&rsquo;expression couvre :<\/p>\n<p>i) le personnel sanitaire, militaire ou civil, d&rsquo;une Partie au conflit, y compris celui qui est mentionn\u00e9 dans les Ire et IIe Conventions, et celui qui est affect\u00e9 \u00e0 des organismes de protection civile;<\/p>\n<p>ii) le personnel sanitaire des Soci\u00e9t\u00e9s nationales de la Croix-Rouge (Croissant-Rouge, Lion-et-Soleil- Rouge) et autres soci\u00e9t\u00e9s nationales de secours volontaires d\u00fbment reconnues et autoris\u00e9es par une Partie au conflit;<\/p>\n<p>iii) le personnel sanitaire des unit\u00e9s ou moyens de transport sanitaire vis\u00e9s \u00e0 l&rsquo;article 9, paragraphe 2;<\/p>\n<p>d) l&rsquo;expression \u00ab\u00a0personnel religieux\u00a0\u00bb s&rsquo;entend des personnes, militaires ou civiles, telles que les aum\u00f4niers, exclusivement vou\u00e9es \u00e0 leur minist\u00e8re et attach\u00e9es:<\/p>\n<p>i) soit aux forces arm\u00e9es d&rsquo;une Partie au conflit;<\/p>\n<p>ii) soit aux unit\u00e9s sanitaires ou aux moyens de transport sanitaire d&rsquo;une Partie au conflit;<\/p>\n<p>iii) soit aux unit\u00e9s sanitaires ou aux moyens de transport sanitaire vis\u00e9s \u00e0 l&rsquo;article 9, paragraphe 2;<\/p>\n<p>iv) soit aux organismes de protection civile d&rsquo;une Partie au conflit;<\/p>\n<p>le rattachement du personnel religieux \u00e0 ces unit\u00e9s peut \u00eatre permanent ou temporaire et les dispositions pertinentes pr\u00e9vues \u00e0 l&rsquo;alin\u00e9a k s&rsquo;appliquent \u00e0 ce personnel;<\/p>\n<p>e) l&rsquo;expression \u00ab\u00a0unit\u00e9s sanitaires\u00a0\u00bb s&rsquo;entend des \u00e9tablissements et autres formations, militaires ou civils, organis\u00e9s \u00e0 des fins sanitaires, \u00e0 savoir la recherche, l&rsquo;\u00e9vacuation, le transport, le diagnostic ou le traitement &#8211; y compris les premiers secours &#8211; des bless\u00e9s, des malades et des naufrag\u00e9s, ainsi que la pr\u00e9vention des maladies. Elle couvre entre autres les h\u00f4pitaux et autres unit\u00e9s similaires, les centres de transfusion sanguine, les centres et instituts de m\u00e9decine pr\u00e9ventive et les centres d&rsquo;approvisionnement sanitaire, ainsi que les d\u00e9p\u00f4ts de mat\u00e9riel sanitaire et de produits pharmaceutiques de ces unit\u00e9s. Les unit\u00e9s sanitaires peuvent \u00eatre fixes ou mobiles, permanentes ou temporaires;<\/p>\n<p>f) l&rsquo;expression \u00ab\u00a0transport sanitaire\u00a0\u00bb s&rsquo;entend du transport par terre, par eau ou par air des bless\u00e9s, des malades et des naufrag\u00e9s, du personnel sanitaire et religieux et du mat\u00e9riel sanitaire prot\u00e9g\u00e9s par les Conventions et le pr\u00e9sent Protocole;<\/p>\n<p>g) l&rsquo;expression \u00ab\u00a0moyen de transport sanitaire\u00a0\u00bb s&rsquo;entend de tout moyen de transport, militaire ou civil, permanent ou temporaire, affect\u00e9 exclusivement au transport sanitaire et plac\u00e9 sous la direction d&rsquo;une autorit\u00e9 comp\u00e9tente d&rsquo;une Partie au conflit;<\/p>\n<p>h) l&rsquo;expression \u00ab\u00a0v\u00e9hicule sanitaire\u00a0\u00bb s&rsquo;entend de tout moyen de transport sanitaire par terre;<\/p>\n<p>i) l&rsquo;expression \u00ab\u00a0navire et embarcation sanitaires\u00a0\u00bb s&rsquo;entend de tout moyen de transport sanitaire par eau;<\/p>\n<p>j) l&rsquo;expression \u00ab\u00a0a\u00e9ronef sanitaire\u00a0\u00bb s&rsquo;entend de tout moyen de transport sanitaire par air;<\/p>\n<p>k) sont \u00ab\u00a0permanents\u00a0\u00bb le personnel sanitaire, les unit\u00e9s sanitaires et les moyens de transport sanitaire affect\u00e9s exclusivement \u00e0 des fins sanitaires pour une dur\u00e9e ind\u00e9termin\u00e9e. Sont \u00ab\u00a0temporaires\u00a0\u00bb le personnel sanitaire, les unit\u00e9s sanitaires et les moyens de transport sanitaire utilis\u00e9s exclusivement \u00e0 des fins sanitaires pour des p\u00e9riodes limit\u00e9es, pendant toute la dur\u00e9e de ces p\u00e9riodes. A moins qu&rsquo;elles ne soient autrement qualifi\u00e9es, les expressions \u00ab\u00a0personnel sanitaire\u00a0\u00bb, \u00ab\u00a0unit\u00e9 sanitaire\u00a0\u00bb et \u00ab\u00a0moyen de transport sanitaire\u00a0\u00bb couvrent un personnel, des unit\u00e9s ou des moyens de transport qui peuvent \u00eatre soit permanents soit temporaires;<\/p>\n<p>l) l&rsquo;expression \u00ab\u00a0signe distinctif\u00a0\u00bb s&rsquo;entend du signe distinctif de la croix rouge, du croissant rouge ou du lion-et-soleil rouge, sur fond blanc, quand il est utilis\u00e9 pour la protection des unit\u00e9s et moyens de transport sanitaires et du personnel sanitaire et religieux et de son mat\u00e9riel;<\/p>\n<p>m) l&rsquo;expression \u00ab\u00a0signal distinctif\u00a0\u00bb s&rsquo;entend de tout moyen de signalisation destin\u00e9 exclusivement \u00e0 permettre l&rsquo;identification des unit\u00e9s et moyens de transport sanitaires, pr\u00e9vu au Chapitre III de l&rsquo;Annexe I au pr\u00e9sent Protocole.<\/p>\n<h6 id=\"article-9--field-of-application\">Article 9 &#8211; Champ d&rsquo;application<\/h6>\n<p>1. Le pr\u00e9sent Titre, dont les dispositions ont pour but d&rsquo;am\u00e9liorer le sort des bless\u00e9s, malades et naufrag\u00e9s, s&rsquo;applique \u00e0 tous ceux qui sont affect\u00e9s par une situation vis\u00e9e \u00e0 l&rsquo;article premier, sans aucune distinction d\u00e9favorable fond\u00e9e sur la race, la couleur, le sexe, la langue, la religion ou la croyance, les opinions politiques ou autres, l&rsquo;origine nationale ou sociale, la fortune, la naissance ou une autre situation ou tout autre crit\u00e8re analogue.<\/p>\n<p>2. Les dispositions pertinentes des articles 27 et 32 de la Ire Convention s&rsquo;appliquent aux unit\u00e9s et moyens de transport sanitaires permanents (autres que les navires-h\u00f4pitaux, auxquels l&rsquo;article 25 de la IIe Convention s&rsquo;applique), ainsi qu&rsquo;\u00e0 leur personnel, mis \u00e0 la disposition d&rsquo;une Partie au conflit \u00e0 des fins humanitaires :<\/p>\n<p>a) par un Etat neutre ou un autre Etat non Partie \u00e0 ce conflit;<\/p>\n<p>b) par une soci\u00e9t\u00e9 de secours reconnue et autoris\u00e9e de cet Etat;<\/p>\n<p>c) par une organisation internationale impartiale de caract\u00e8re humanitaire.<\/p>\n<h6 id=\"article-10--protection-and-care\">Article 10 &#8211; Protection et soins<\/h6>\n<p>1. Tous les bless\u00e9s, malades et naufrag\u00e9s, \u00e0 quelque Partie qu&rsquo;ils appartiennent, doivent \u00eatre respect\u00e9s et prot\u00e9g\u00e9s.<\/p>\n<p>2. Ils doivent en toute circonstance \u00eatre trait\u00e9s avec humanit\u00e9 et recevoir, dans toute la mesure du possible et dans les d\u00e9lais les plus brefs, les soins m\u00e9dicaux qu&rsquo;exige leur \u00e9tat. Aucune distinction fond\u00e9e sur des crit\u00e8res autres que m\u00e9dicaux ne doit \u00eatre faite entre eux.<\/p>\n<h6 id=\"article-11--protection-of-persons\">Article 11 &#8211; Protection de la personne<\/h6>\n<p>1. La sant\u00e9 et l&rsquo;int\u00e9grit\u00e9 physiques ou mentales des personnes au pouvoir de la Partie adverse ou intern\u00e9es, d\u00e9tenues ou d&rsquo;une autre mani\u00e8re priv\u00e9es de libert\u00e9 en raison d&rsquo;une situation vis\u00e9e \u00e0 l&rsquo;article premier ne doivent \u00eatre compromises par aucun acte ni par aucune omission injustifi\u00e9s. En cons\u00e9quence, il est interdit de soumettre les personnes vis\u00e9es au pr\u00e9sent article \u00e0 un acte m\u00e9dical qui ne serait pas motiv\u00e9 par leur \u00e9tat de sant\u00e9 et qui ne serait pas conforme aux normes m\u00e9dicales g\u00e9n\u00e9ralement reconnues que la Partie responsable de l&rsquo;acte appliquerait dans des circonstances m\u00e9dicales analogues \u00e0 ses propres ressortissants jouissant de leur libert\u00e9.<\/p>\n<p>2. Il et en particulier interdit de pratiquer sur ces personnes, m\u00eame avec leur consentement :<\/p>\n<p>a) des mutilations physiques;<\/p>\n<p>b) des exp\u00e9riences m\u00e9dicales ou scientifiques;<\/p>\n<p>c) des pr\u00e9l\u00e8vements de tissus ou d&rsquo;organes pour des transplantations,<\/p>\n<p>sauf si ces actes sont justifi\u00e9s dans les conditions pr\u00e9vues au paragraphe 1.<\/p>\n<p>3. Il ne peut \u00eatre d\u00e9rog\u00e9 \u00e0 l&rsquo;interdiction vis\u00e9e au paragraphe 2 c que lorsqu&rsquo;il s&rsquo;agit de dons de sang en vue de transfusion ou de peau destin\u00e9e \u00e0 des greffes, \u00e0 la condition que ces dons soient volontaires et ne r\u00e9sultent pas de mesures de coercition ou de persuasion et qu&rsquo;ils soient destin\u00e9s \u00e0 des fins th\u00e9rapeutiques dans des conditions compatibles avec les normes m\u00e9dicales g\u00e9n\u00e9ralement reconnues et avec les contr\u00f4les effectu\u00e9s dans l&rsquo;int\u00e9r\u00eat tant du donneur que du receveur.<\/p>\n<p>4. Tout acte ou omission volontaire qui met gravement en danger la sant\u00e9 ou l&rsquo;int\u00e9grit\u00e9 physiques ou mentales de toute personne au pouvoir d&rsquo;une Partie autre que celle dont elle d\u00e9pend et qui, soit contrevient \u00e0 l&rsquo;une des interdictions \u00e9nonc\u00e9es aux paragraphes 1 et 2, soit ne respecte pas les conditions prescrites au paragraphe 3, constitue une infraction grave au pr\u00e9sent Protocole.<\/p>\n<p>5. Les personnes d\u00e9finies au paragraphe 1 ont le droit de refuser toute intervention chirurgicale. En cas de refus, le personnel sanitaire doit s&rsquo;efforcer d&rsquo;obtenir une d\u00e9claration \u00e9crite \u00e0 cet effet, sign\u00e9e ou reconnue par le patient.<\/p>\n<p>6. Toute Partie au conflit doit tenir un dossier m\u00e9dical pour tout don de sang en vue de transfusion ou de peau destin\u00e9e \u00e0 des greffes par les personnes vis\u00e9es au paragraphe 1, si ce don est effectu\u00e9 sous la responsabilit\u00e9 de cette Partie. En outre, toute Partie au conflit doit s&rsquo;efforcer de tenir un dossier de tous les actes m\u00e9dicaux entrepris \u00e0 l&rsquo;\u00e9gard des personnes intern\u00e9es, d\u00e9tenues ou d&rsquo;une autre mani\u00e8re priv\u00e9es de libert\u00e9 en raison d&rsquo;une situation vis\u00e9e \u00e0 l&rsquo;article premier. Ces dossiers doivent en tout temps \u00eatre \u00e0 la disposition de la Puissance protectrice aux fins d&rsquo;inspection.<\/p>\n<h6 id=\"article-12--protection-of-medical-units\">Article 12 &#8211; Protection des unit\u00e9s sanitaires<\/h6>\n<p>1. Les unit\u00e9s sanitaires doivent en tout temps \u00eatre respect\u00e9es et prot\u00e9g\u00e9es et ne doivent pas \u00eatre l&rsquo;objet d&rsquo;attaques.<\/p>\n<p>2. Le paragraphe 1 s&rsquo;applique aux unit\u00e9s sanitaires civiles pour autant qu&rsquo;elles remplissent l&rsquo;une des conditions suivantes<\/p>\n<p>a) appartenir \u00e0 l&rsquo;une des Parties au conflit;<\/p>\n<p>b) \u00eatre reconnues et autoris\u00e9es par l&rsquo;autorit\u00e9 comp\u00e9tente de l&rsquo;une des Parties au conflit;<\/p>\n<p>c) \u00eatre autoris\u00e9es conform\u00e9ment aux articles 9, paragraphe 2, du pr\u00e9sent Protocole, ou 27 de la Ire Convention.<\/p>\n<p>3. Les Parties au conflit sont invit\u00e9es \u00e0 se communiquer l&#8217;emplacement de leurs unit\u00e9s sanitaires fixes. L&rsquo;absence d&rsquo;une telle notification ne dispense aucune des Parties d&rsquo;observer les dispositions du paragraphe 1.<\/p>\n<p>4. En aucune circonstance, les unit\u00e9s sanitaires ne doivent \u00eatre utilis\u00e9es pour tenter de mettre des objectifs militaires \u00e0 l&rsquo;abri d&rsquo;attaques. Chaque fois que cela sera possible, les Parties au conflit veilleront \u00e0 ce que les unit\u00e9s sanitaires soient situ\u00e9es de telle fa\u00e7on que des attaques contre des objectifs militaires ne mettent pas ces unit\u00e9s sanitaires en danger.<\/p>\n<h6 id=\"article-13--discontinuance-of-protection-of-civilian-medical-units\">Article 13 &#8211; Cessation de la protection des unit\u00e9s sanitaires civiles<\/h6>\n<p>1. La protection due aux unit\u00e9s sanitaires civiles ne peut cesser que si elles sont utilis\u00e9es pour commettre, en dehors de leur destination humanitaire, des actes nuisibles \u00e0 l&rsquo;ennemi. Toutefois, la protection cessera seulement apr\u00e8s qu&rsquo;une sommation fixant, chaque fois qu&rsquo;il y aura lieu, un d\u00e9lai raisonnable, sera demeur\u00e9e sans effet.<\/p>\n<p>2. Ne seront pas consid\u00e9r\u00e9s comme actes nuisibles \u00e0 l&rsquo;ennemi :<\/p>\n<p>a) le fait que le personnel de l&rsquo;unit\u00e9 est dot\u00e9 d&rsquo;armes l\u00e9g\u00e8res individuelles pour sa propre d\u00e9fense ou pour celle des bless\u00e9s et des malades dont il a la charge;<\/p>\n<p>b) le fait que l&rsquo;unit\u00e9 est gard\u00e9e par un piquet, des sentinelles ou une escorte;<\/p>\n<p>c) le fait que se trouvent dans l&rsquo;unit\u00e9 des armes portatives et des munitions retir\u00e9es aux bless\u00e9s et aux malades et n&rsquo;ayant pas encore \u00e9t\u00e9 vers\u00e9es au service comp\u00e9tent;<\/p>\n<p>d) le fait que des membres des forces arm\u00e9es ou autres combattants se trouvent dans ces unit\u00e9s pour des raisons m\u00e9dicales.<\/p>\n<h6 id=\"article-14--limitations-on-requisition-of-civilian-medical-units\">Article 14 &#8211; Limitation \u00e0 la r\u00e9quisition des unit\u00e9s sanitaires civiles<\/h6>\n<p>1. La Puissance occupante a le devoir d&rsquo;assurer que les besoins m\u00e9dicaux de la population civile continuent d&rsquo;\u00eatre satisfaits dans les territoires occup\u00e9s.<\/p>\n<p>2. En cons\u00e9quence, la Puissance occupante ne peut r\u00e9quisitionner les unit\u00e9s sanitaires civiles, leur \u00e9quipement, leur mat\u00e9riel ou leur personnel, aussi longtemps que ces moyens sont n\u00e9cessaires pour satisfaire les besoins m\u00e9dicaux de la population civile et pour assurer la continuit\u00e9 des soins aux bless\u00e9s et malades d\u00e9j\u00e0 sous traitement.<\/p>\n<p>3. La Puissance occupante peut r\u00e9quisitionner les moyens mentionn\u00e9s ci-dessus \u00e0 condition de continuer \u00e0 observer la r\u00e8gle g\u00e9n\u00e9rale \u00e9tablie au paragraphe 2 et sous r\u00e9serve des conditions particuli\u00e8res suivantes :<\/p>\n<p>a) que les moyens soient n\u00e9cessaires pour assurer un traitement m\u00e9dical imm\u00e9diat et appropri\u00e9 aux bless\u00e9s et malades des forces arm\u00e9es de la Puissance occupante ou aux prisonniers de guerre;<\/p>\n<p>b) que la r\u00e9quisition n&rsquo;exc\u00e8de pas la p\u00e9riode o\u00f9 cette n\u00e9cessit\u00e9 existe; et<\/p>\n<p>c) que des dispositions imm\u00e9diates soient prises pour que les besoins m\u00e9dicaux de la population civile, ainsi que ceux des bless\u00e9s et malades sous traitement affect\u00e9s par la r\u00e9quisition, continuent d&rsquo;\u00eatre satisfaits.<\/p>\n<h6 id=\"article-15--protection-of-civilian-medical-and-religious-personnel\">Article 15 &#8211; Protection du personnel sanitaire et religieux civil<\/h6>\n<p>1. Le personnel sanitaire civil sera respect\u00e9 et prot\u00e9g\u00e9.<\/p>\n<p>2. En cas de besoin, toute assistance possible doit \u00eatre donn\u00e9e au personnel sanitaire civil dans une zone o\u00f9 les services sanitaires civils seraient d\u00e9sorganis\u00e9s en raison des combats.<\/p>\n<p>3. La Puissance occupante donnera toute assistance au personnel sanitaire civil dans les territoires occup\u00e9s pour lui permettre d&rsquo;accomplir au mieux sa mission humanitaire. La Puissance occupante ne peut pas exiger de ce personnel que cette mission s&rsquo;accomplisse en priorit\u00e9 au profit de qui que ce soit, sauf pour des raisons m\u00e9dicales. Ce personnel ne sera pas astreint \u00e0 des t\u00e2ches incompatibles avec sa mission humanitaire.<\/p>\n<p>4. Le personnel sanitaire civil pourra se rendre sur les lieux o\u00f9 ses services sont indispensables, sous r\u00e9serve des mesures de contr\u00f4le et de s\u00e9curit\u00e9 que la Partie au conflit int\u00e9ress\u00e9e jugerait n\u00e9cessaires.<\/p>\n<p>5. Le personnel religieux civil sera respect\u00e9 et prot\u00e9g\u00e9. Les dispositions des Conventions et du pr\u00e9sent Protocole relatives \u00e0 la protection et \u00e0 l&rsquo;identification du personnel sanitaire lui sont applicables.<\/p>\n<h6 id=\"article-16--general-protection-of-medical-duties\">Article 16 &#8211; Protection g\u00e9n\u00e9rale de la mission m\u00e9dicale<\/h6>\n<p>1. Nul ne sera puni pour avoir exerc\u00e9 une activit\u00e9 de caract\u00e8re m\u00e9dical conforme \u00e0 la d\u00e9ontologie, quels qu&rsquo;aient \u00e9t\u00e9 les circonstances ou les b\u00e9n\u00e9ficiaires de cette activit\u00e9.<\/p>\n<p>2. Les personnes exer\u00e7ant une activit\u00e9 de caract\u00e8re m\u00e9dical ne peuvent \u00eatre contraintes d&rsquo;accomplir des actes ou d&rsquo;effectuer des travaux contraires \u00e0 la d\u00e9ontologie ou aux autres r\u00e8gles m\u00e9dicales qui prot\u00e8gent les bless\u00e9s et les malades, ou aux dispositions des Conventions ou du pr\u00e9sent Protocole, ni de s&rsquo;abstenir d&rsquo;accomplir des actes exig\u00e9s par ces r\u00e8gles et dispositions.<\/p>\n<p>3. Aucune personne exer\u00e7ant une activit\u00e9 m\u00e9dicale ne doit \u00eatre contrainte de donner \u00e0 quiconque appartenant soit \u00e0 une Partie adverse, soit \u00e0 la m\u00eame Partie qu&rsquo;elle, sauf dans les cas pr\u00e9vus par la loi de cette derni\u00e8re, des renseignements concernant les bless\u00e9s et les malades qu&rsquo;elle soigne ou qu&rsquo;elle a soign\u00e9s si elle estime que de tels renseignements peuvent porter pr\u00e9judice \u00e0 ceux-ci ou \u00e0 leur famille. Les r\u00e8glements r\u00e9gissant la notification obligatoire des maladies transmissibles doivent, n\u00e9anmoins, \u00eatre respect\u00e9s.<\/p>\n<h6 id=\"article-17--role-of-the-civilian-population-and-of-aid-societies\">Article 17 &#8211; R\u00f4le de la population civile et des soci\u00e9t\u00e9s de secours<\/h6>\n<p>1. La population civile doit respecter les bless\u00e9s, malades et naufrag\u00e9s, m\u00eame s&rsquo;ils appartiennent \u00e0 la Partie adverse, et n&rsquo;exercer contre eux aucun acte de violence. La population civile et les soci\u00e9t\u00e9s de secours, telles que les Soci\u00e9t\u00e9s nationales de la Croix-Rouge (Croissant-Rouge, Lion-et-Soleil-Rouge), seront autoris\u00e9es, m\u00eame dans les r\u00e9gions envahies ou occup\u00e9es, \u00e0 recueillir ces bless\u00e9s, malades et naufrag\u00e9s et \u00e0 leur prodiguer des soins, m\u00eame de leur propre initiative. Nul ne sera inqui\u00e9t\u00e9, poursuivi, condamn\u00e9 ou puni pour de tels actes humanitaires.<\/p>\n<p>2. Les Parties au conflit pourront faire appel \u00e0 la population civile et aux soci\u00e9t\u00e9s de secours vis\u00e9es au paragraphe 1 pour recueillir les bless\u00e9s, malades et naufrag\u00e9s et pour leur prodiguer des soins de m\u00eame que pour rechercher les morts et rendre compte du lieu o\u00f9 ils se trouvent; elles accorderont la protection et les facilit\u00e9s n\u00e9cessaires \u00e0 ceux qui auront r\u00e9pondu \u00e0 cet appel. Dans le cas o\u00f9 la Partie adverse viendrait \u00e0 prendre ou \u00e0 reprendre le contr\u00f4le de la r\u00e9gion, elle maintiendra cette protection et ces facilit\u00e9s aussi longtemps qu&rsquo;elles seront n\u00e9cessaires.<\/p>\n<h6 id=\"article-18--identification\">Article 18 &#8211; Identification<\/h6>\n<p>1. Chaque Partie au conflit doit s&rsquo;efforcer de faire en sorte que le personnel sanitaire et religieux, ainsi que les unit\u00e9s et les moyens de transport sanitaires, puissent \u00eatre identifi\u00e9s.<\/p>\n<p>2. Chaque Partie au conflit doit \u00e9galement s&rsquo;efforcer d&rsquo;adopter et de mettre en oeuvre des m\u00e9thodes et des proc\u00e9dures permettant d&rsquo;identifier les unit\u00e9s et les moyens de transport sanitaires qui utilisent le signe distinctif et des signaux distinctifs.<\/p>\n<p>3. Dans les territoires occup\u00e9s et dans les zones o\u00f9 des combats se d\u00e9roulent ou semblent devoir se d\u00e9rouler, le personnel sanitaire civil et le personnel religieux civil se feront en r\u00e8gle g\u00e9n\u00e9rale reconna\u00eetre au moyen du signe distinctif et d&rsquo;une carte d&rsquo;identit\u00e9 attestant leur statut.<\/p>\n<p>4. Avec le consentement de l&rsquo;autorit\u00e9 comp\u00e9tente, les unit\u00e9s et moyens de transport sanitaires seront marqu\u00e9s du signe distinctif. Les navires et embarcations vis\u00e9s \u00e0 l&rsquo;article 22 du pr\u00e9sent Protocole seront marqu\u00e9s conform\u00e9ment aux dispositions de la IIe Convention.<\/p>\n<p>5. En plus du signe distinctif, une Partie au conflit peut, conform\u00e9ment aux Chapitre III de l&rsquo;Annexe I au pr\u00e9sent Protocole, autoriser l&rsquo;usage de signaux distinctifs pour permettre l&rsquo;identification des unit\u00e9s et des moyens de transport sanitaires. A titre exceptionnel, dans les cas particuliers pr\u00e9vus audit Chapitre, les moyens de transport sanitaire peuvent utiliser des signaux distinctifs sans arborer le signe distinctif.<\/p>\n<p>6. L&rsquo;ex\u00e9cution des dispositions pr\u00e9vues aux paragraphes 1 \u00e0 5 est r\u00e9gie par les Chapitres I \u00e0 III de l&rsquo;Annexe I au pr\u00e9sent Protocole.<\/p>\n<p>Les signaux d\u00e9crits au Chapitre III de cette Annexe et destin\u00e9s exclusivement \u00e0 l&rsquo;usage des unit\u00e9s et des moyens de transport sanitaires ne pourront \u00eatre utilis\u00e9s, sauf exceptions pr\u00e9vues audit Chapitre, que pour permettre l&rsquo;identification des unit\u00e9s et moyens de transport sanitaires.<\/p>\n<p>7. Les dispositions du pr\u00e9sent article ne permettent pas d&rsquo;\u00e9tendre l&rsquo;usage, en temps de paix, du signe distinctif au-del\u00e0 de ce qui est pr\u00e9vu par l&rsquo;article 44 de la Ire Convention.<\/p>\n<p>8. Les dispositions des Conventions et du pr\u00e9sent Protocole relatives au contr\u00f4le de l&rsquo;usage du signe distinctif ainsi qu&rsquo;\u00e0 la pr\u00e9vention et \u00e0 la r\u00e9pression de son usage abusif sont applicables aux signaux distinctifs.<\/p>\n<h6 id=\"article-19--neutral-and-other-states-not-parties-to-the-conflict\">Article 19 &#8211; Etats neutres et autres Etats non Parties au conflit<\/h6>\n<p>Les Etats neutres et les autres Etats qui ne sont pas Parties au conflit appliqueront les dispositions pertinentes du pr\u00e9sent Protocole aux personnes prot\u00e9g\u00e9es par le pr\u00e9sent Titre qui peuvent \u00eatre re\u00e7ues ou intern\u00e9es sur leur territoire, ainsi qu&rsquo;aux morts des Parties \u00e0 ce conflit qu&rsquo;ils pourront recueillir.<\/p>\n<h6 id=\"article-20--prohibition-of-reprisals\">Article 20 &#8211; Interdiction des repr\u00e9sailles<\/h6>\n<p>Les repr\u00e9sailles contre les personnes et les biens prot\u00e9g\u00e9s par le pr\u00e9sent Titre sont interdites.<\/p>\n<h4 id=\"section-ii--medical-transportation\">Section II &#8211; Transports sanitaires<\/h4>\n<h6 id=\"article-21--medical-vehicles\">Article 21 &#8211; V\u00e9hicules sanitaires<\/h6>\n<p>les v\u00e9hicules sanitaires seront respect\u00e9s et prot\u00e9g\u00e9s de la mani\u00e8re pr\u00e9vue par les Conventions et le pr\u00e9sent Protocole pour les unit\u00e9s sanitaires mobiles.<\/p>\n<h6 id=\"article-22--hospitals-ships-and-coastal-rescue-craft\">Article 22 &#8211; Navires-h\u00f4pitaux et embarcations de sauvetage c\u00f4ti\u00e8res<\/h6>\n<p>1. Les dispositions des Conventions concernant<\/p>\n<p>a) les navires d\u00e9crits aux articles 22, 24, 25 et 27 de la IIe Convention,<\/p>\n<p>b) leurs canots de sauvetage et leurs embarcations,<\/p>\n<p>c) leur personnel et leur \u00e9quipage,<\/p>\n<p>d) les bless\u00e9s, les malades et les naufrag\u00e9s se trouvant \u00e0 bord,<\/p>\n<p>s&rsquo;appliquent aussi lorsque ces navires, canots ou embarcations transportent des civils bless\u00e9s, malades et naufrag\u00e9s qui n&rsquo;appartiennent pas \u00e0 l&rsquo;une des cat\u00e9gories mentionn\u00e9es \u00e0 l&rsquo;article 13 de la IIe Convention. Toutefois, ces civils ne doivent \u00eatre ni remis \u00e0 une Partie qui n&rsquo;est pas la leur, ni captur\u00e9s en mer. S&rsquo;ils se trouvent au pouvoir d&rsquo;une Partie au conflit qui n&rsquo;est pas la leur, la IVe Convention et le pr\u00e9sent Protocole leur seront applicables.<\/p>\n<p>2. La protection assur\u00e9e par les Conventions pour les navires d\u00e9crits \u00e0 l&rsquo;article 25 de la IIe Convention s&rsquo;\u00e9tend aux navires-h\u00f4pitaux mis \u00e0 la disposition d&rsquo;une Partie au conflit \u00e0 des fins humanitaires :<\/p>\n<p>a) par un Etat neutre ou un autre Etat non Partie \u00e0 ce conflit, ou<\/p>\n<p>b) par une organisation internationale impartiale de caract\u00e8re humanitaire,<\/p>\n<p>sous r\u00e9serve dans les deux cas que les conditions \u00e9nonc\u00e9es dans ledit article soient remplies.<\/p>\n<p>3. Les embarcations d\u00e9crites \u00e0 l&rsquo;article 27 de la IIe Convention seront prot\u00e9g\u00e9es m\u00eame si la notification envisag\u00e9e dans cet article n&rsquo;a pas \u00e9t\u00e9 faite. Les Parties au conflit sont toutefois invit\u00e9es \u00e0 s&rsquo;informer mutuellement de tout \u00e9l\u00e9ment relatif \u00e0 ces embarcations qui permette de les identifier et de les reconna\u00eetre plus facilement.<\/p>\n<h6 id=\"article-23--other-medical-ships-and-craft\">Article 23 &#8211; Autres navires et embarcations sanitaires<\/h6>\n<p>1. Les navires et embarcations sanitaires autres que ceux qui sont vis\u00e9s \u00e0 l&rsquo;article 22 du pr\u00e9sent Protocole et \u00e0 l&rsquo;article 38 de la IIe Convention doivent, que ce soit en mer ou en d&rsquo;autres eaux, \u00eatre respect\u00e9s et prot\u00e9g\u00e9s de la mani\u00e8re pr\u00e9vue pour les unit\u00e9s sanitaires mobiles par les Conventions et le pr\u00e9sent Protocole. La protection de ces bateaux ne pouvant \u00eatre efficace que s&rsquo;ils peuvent \u00eatre identifi\u00e9s et reconnus comme des navires ou embarcations sanitaires, ils devraient \u00eatre marqu\u00e9s du signe distinctif et se conformer, dans la mesure du possible, aux dispositions de l&rsquo;article 43, deuxi\u00e8me alin\u00e9a, de la IIe Convention.<\/p>\n<p>2. Les navires et embarcations vis\u00e9s au paragraphe 1 restent soumis au droit de la guerre. L&rsquo;ordre de stopper, de s&rsquo;\u00e9loigner ou de prendre une route d\u00e9termin\u00e9e pourra leur \u00eatre donn\u00e9 par tout navire de guerre naviguant en surface qui est en mesure de faire ex\u00e9cuter cet ordre imm\u00e9diatement et ils devront ob\u00e9ir \u00e0 tout ordre de cette nature. Ils ne peuvent pas \u00eatre d\u00e9tourn\u00e9s de leur mission sanitaire d&rsquo;une autre mani\u00e8re aussi longtemps qu&rsquo;ils seront n\u00e9cessaires pour les bless\u00e9s, les malades et les naufrag\u00e9s se trouvant \u00e0 leur bord.<\/p>\n<p>3. La protection pr\u00e9vue au paragraphe 1 ne cessera que dans les conditions \u00e9nonc\u00e9es aux articles 34 et 35 de la IIe Convention. Un refus net d&rsquo;ob\u00e9ir \u00e0 un ordre donn\u00e9 conform\u00e9ment au paragraphe 2 constitue un acte nuisible \u00e0 l&rsquo;ennemi au sens de l&rsquo;article 34 de la IIe Convention.<\/p>\n<p>4. Une Partie au conflit pourra notifier \u00e0 une Partie adverse, aussit\u00f4t que possible avant le d\u00e9part, le nom, les caract\u00e9ristiques, l&rsquo;heure de d\u00e9part pr\u00e9vue, la route et la vitesse estim\u00e9e du navire ou de l&#8217;embarcation sanitaires, en particulier s&rsquo;il s&rsquo;agit de navires de plus de 2.000 tonnes brutes, et pourra communiquer tous autres renseignements qui faciliteraient l&rsquo;identification et la reconnaissance. La Partie adverse doit accuser r\u00e9ception de ces renseignements.<\/p>\n<p>5. Les dispositions de l&rsquo;article 37 de la IIe Convention s&rsquo;appliquent au personnel sanitaire et religieux se trouvant \u00e0 bord de ces navires et embarcations.<\/p>\n<p>6. Les dispositions pertinentes de la IIe Convention s&rsquo;appliquent aux bless\u00e9s, aux malades et aux naufrag\u00e9s appartenant aux cat\u00e9gories vis\u00e9es \u00e0 l&rsquo;article 13 de la IIe Convention et \u00e0 l&rsquo;article 44 du pr\u00e9sent Protocole qui se trouvent \u00e0 bord de ces navires et embarcations sanitaires. Les personnes civiles bless\u00e9es, malades et naufrag\u00e9es qui n&rsquo;appartiennent \u00e0 aucune des cat\u00e9gories mentionn\u00e9es \u00e0 l&rsquo;article 13 de la IIe Convention ne doivent, si elles sont en mer, ni \u00eatre remises \u00e0 une Partie qui n&rsquo;est pas la leur, ni \u00eatre oblig\u00e9es \u00e0 quitter le navire; si, n\u00e9anmoins, elles se trouvent au pouvoir d&rsquo;une Partie au conflit qui n&rsquo;est pas la leur, la IVe Convention et le pr\u00e9sent Protocole leur sont applicables.<\/p>\n<h6 id=\"article-24--protection-of-medical-aircraft\">Article 24 &#8211; Protection des a\u00e9ronefs sanitaires<\/h6>\n<p>Les a\u00e9ronefs sanitaires seront respect\u00e9s et prot\u00e9g\u00e9s conform\u00e9ment aux dispositions du pr\u00e9sent Titre.<\/p>\n<h6 id=\"article-25--medical-aircraft-in-areas-not-controlled-by-an-adverse-party\">Article 25 &#8211; A\u00e9ronefs sanitaires dans des zones non domin\u00e9es par la Partie adverse<\/h6>\n<p>Dans des zones terrestres domin\u00e9es en fait par des forces amies ou dans des zones maritimes qui ne sont pas en fait domin\u00e9es par une Partie adverse, et dans leur espace a\u00e9rien, le respect et la protection des a\u00e9ronefs sanitaires d&rsquo;une Partie au conflit ne d\u00e9pendent pas d&rsquo;un accord avec la Partie adverse. Une Partie au conflit qui emploie ainsi ses a\u00e9ronefs sanitaires dans ces zones pourra cependant, afin de renforcer leur s\u00e9curit\u00e9, donner \u00e0 la Partie adverse les notifications pr\u00e9vues par l&rsquo;article 29, en particulier quand ces a\u00e9ronefs effectuent des vols qui les am\u00e8nent \u00e0 port\u00e9e des syst\u00e8mes d&rsquo;armes sol-air de la Partie adverse.<\/p>\n<h6 id=\"article-26--medical-aircraft-in-contact-or-similar-zones\">Article 26 &#8211; A\u00e9ronefs sanitaires dans des zones de contact ou similaires<\/h6>\n<p>1. Dans les Parties de la zone de contact domin\u00e9es en fait par des forces amies, ainsi que dans les zones qu&rsquo;en fait aucune force ne domine clairement, et dans l&rsquo;espace a\u00e9rien correspondant, la protection des a\u00e9ronefs sanitaires ne peut \u00eatre pleinement efficace que si un accord pr\u00e9alable est intervenu entre les autorit\u00e9s militaires comp\u00e9tentes des Parties au conflit ainsi qu&rsquo;il est pr\u00e9vu par l&rsquo;article 29. En l&rsquo;absence d&rsquo;un tel accord, les a\u00e9ronefs sanitaires op\u00e8rent \u00e0 leurs seuls risques; les a\u00e9ronefs sanitaires devront n\u00e9anmoins \u00eatre respect\u00e9s lorsqu&rsquo;ils auront \u00e9t\u00e9 reconnus comme tels.<\/p>\n<p>2. L&rsquo;expression \u00ab\u00a0zone de contact\u00a0\u00bb s&rsquo;entend de toute zone terrestre o\u00f9 les \u00e9l\u00e9ments avanc\u00e9s des forces oppos\u00e9es sont au contact les uns des autres, particuli\u00e8rement l\u00e0 o\u00f9 ils sont expos\u00e9s \u00e0 des tirs directs \u00e0 partir du sol.<\/p>\n<h6 id=\"article-27--medical-aircraft-in-areas-controlled-by-an-adverse-party\">Article 27 &#8211; A\u00e9ronefs sanitaires dans les zones domin\u00e9es par la Partie adverse<\/h6>\n<p>1. Les a\u00e9ronefs sanitaires d&rsquo;une Partie au conflit resteront prot\u00e9g\u00e9s pendant qu&rsquo;ils survolent des zones terrestres ou maritimes domin\u00e9es en fait par une Partie adverse, \u00e0 condition d&rsquo;avoir pr\u00e9alablement obtenu, pour de tels vols, l&rsquo;accord de l&rsquo;autorit\u00e9 comp\u00e9tente de cette Partie adverse.<\/p>\n<p>2. Un a\u00e9ronef sanitaire qui survole une zone domin\u00e9e en fait par une Partie adverse, en l&rsquo;absence de l&rsquo;accord pr\u00e9vu par le paragraphe ou en contrevenant \u00e0 un tel accord, par suite d&rsquo;une erreur de navigation ou d&rsquo;une situation d&rsquo;urgence affectant la s\u00e9curit\u00e9 du vol, doit faire son possible pour se faire identifier et pour en informer la Partie adverse. D\u00e8s que la Partie adverse aura reconnu un tel a\u00e9ronef sanitaire, elle devra faire tous les efforts raisonnables pour donner l&rsquo;ordre d&rsquo;atterrir ou d&rsquo;amerrir vis\u00e9 \u00e0 l&rsquo;article 30, paragraphe 1, ou pour prendre d&rsquo;autres mesures afin de sauvegarder les int\u00e9r\u00eats de cette Partie et pour donner \u00e0 l&rsquo;a\u00e9ronef dans les deux cas le temps d&rsquo;obtemp\u00e9rer, avant de recourir \u00e0 une attaque.<\/p>\n<h6 id=\"article-28--restrictions-on-operations-of-medical-aircraft\">Article 28 &#8211; Restrictions \u00e0 l&#8217;emploi des a\u00e9ronefs sanitaires<\/h6>\n<p>1. Il est interdit aux Parties au conflit d&rsquo;utiliser leurs a\u00e9ronefs sanitaires pour tenter d&rsquo;obtenir un avantage militaire sur une Partie adverse. La pr\u00e9sence d&rsquo;a\u00e9ronefs sanitaires ne doit pas \u00eatre utilis\u00e9e pour tenter de mettre des objectifs militaires \u00e0 l&rsquo;abri d&rsquo;une attaque.<\/p>\n<p>2. Les a\u00e9ronefs sanitaires ne doivent pas \u00eatre utilis\u00e9s pour rechercher ou transmettre des renseignements de caract\u00e8re militaire et ne doivent pas transporter de mat\u00e9riel destin\u00e9 \u00e0 ces fins. Il leur est interdit de transporter des personnes ou un chargement non compris dans la d\u00e9finition donn\u00e9e \u00e0 l&rsquo;article 8, alin\u00e9a f. Le transport \u00e0 bord des effets personnels des occupants ou de mat\u00e9riel exclusivement destin\u00e9 \u00e0 faciliter la navigation, les communications ou l&rsquo;identification n&rsquo;est pas consid\u00e9r\u00e9 comme interdit.<\/p>\n<p>3. Les a\u00e9ronefs sanitaires ne doivent pas transporter d&rsquo;autres armes que les armes portatives et les munitions qui auraient \u00e9t\u00e9 retir\u00e9es aux bless\u00e9s, malades ou naufrag\u00e9s se trouvant \u00e0 bord et qui n&rsquo;auraient pas encore \u00e9t\u00e9 vers\u00e9es au service comp\u00e9tent, et les armes l\u00e9g\u00e8res individuelles n\u00e9cessaires pour permettre au personnel sanitaire se trouvant \u00e0 bord d&rsquo;assurer sa d\u00e9fense et celle des bless\u00e9s, des malades et des naufrag\u00e9s dont il a la charge.<\/p>\n<p>4. En effectuant les vols vis\u00e9s aux articles 26 et 27, les a\u00e9ronefs sanitaires ne doivent pas \u00eatre utilis\u00e9s, sauf accord pr\u00e9alable avec la Partie adverse, pour la recherche des bless\u00e9s, des malades et des naufrag\u00e9s.<\/p>\n<h6 id=\"article-29--notifications-and-agreements-concerning-medical-aircraft\">Article 29 &#8211; Notifications et accords concernant les a\u00e9ronefs sanitaires<\/h6>\n<p>1. Les notifications vis\u00e9es \u00e0 l&rsquo;article 25 ou les demandes d&rsquo;accord pr\u00e9alable vis\u00e9es aux articles 26, 27, 28, paragraphe 4, et 31 doivent indiquer le nombre pr\u00e9vu d&rsquo;a\u00e9ronefs sanitaires, leurs plans de vol et leurs moyens d&rsquo;identification; elles seront interpr\u00e9t\u00e9es comme signifiant que chaque vol s&rsquo;effectuera conform\u00e9ment aux dispositions de l&rsquo;article 28.<\/p>\n<p>2. La Partie qui re\u00e7oit une notification faite en vertu de l&rsquo;article 25 doit en accuser r\u00e9ception sans d\u00e9lai.<\/p>\n<p>3. La Partie qui re\u00e7oit une demande d&rsquo;accord pr\u00e9alable conform\u00e9ment soit aux articles 26, 27 ou 31, soit \u00e0 l&rsquo;article 28, paragraphe 4, doit notifier aussi rapidement que possible \u00e0 la Partie demanderesse :<\/p>\n<p>a) soit l&rsquo;acceptation de la demande;<\/p>\n<p>b) soit le rejet de la demande;<\/p>\n<p>c) soit une proposition raisonnable de modification de la demande. Elle peut aussi proposer d&rsquo;interdire ou de restreindre d&rsquo;autres vols dans la zone pendant la p\u00e9riode consid\u00e9r\u00e9e. Si la Partie qui a pr\u00e9sent\u00e9 la demande accepte les contre-propositions, elle doit notifier \u00e0 l&rsquo;autre Partie son accord.<\/p>\n<p>4. Les Parties prendront les mesures n\u00e9cessaires pour qu&rsquo;il soit possible de faire ces notifications et de conclure ces accords rapidement.<\/p>\n<p>5. Les Parties prendront aussi les mesures n\u00e9cessaires pour que le contenu pertinent de ces notifications et de ces accords soit diffus\u00e9 rapidement aux unit\u00e9s militaires concern\u00e9es et qu&rsquo;elles soient instruites rapidement des moyens d&rsquo;identification utilis\u00e9s par les a\u00e9ronefs sanitaires en question.<\/p>\n<h6 id=\"article-30--landing-and-inspection-of-medical-aircraft\">Article 30 &#8211; Atterrissage et inspection des a\u00e9ronefs sanitaires<\/h6>\n<p>1. Les a\u00e9ronefs sanitaires survolant des zones domin\u00e9es en fait par la Partie adverse, ou des zones qu&rsquo;en fait aucune force ne domine clairement, peuvent \u00eatre somm\u00e9s d&rsquo;atterrir ou d&rsquo;amerrir, selon le cas, pour permettre l&rsquo;inspection pr\u00e9vue aux paragraphes suivants. Les a\u00e9ronefs sanitaires devront ob\u00e9ir \u00e0 toute sommation de ce genre.<\/p>\n<p>2. Si un a\u00e9ronef sanitaire atterrit ou amerrit sur sommation ou pour d&rsquo;autres raisons, il ne peut \u00eatre soumis \u00e0 inspection que pour v\u00e9rifier les points mentionn\u00e9s aux paragraphes 3 et 4. L&rsquo;inspection devra \u00eatre entreprise sans retard et effectu\u00e9e rapidement. La Partie qui proc\u00e8de \u00e0 l&rsquo;inspection ne doit pas exiger que les bless\u00e9s et les malades soient d\u00e9barqu\u00e9s de l&rsquo;a\u00e9ronef, sauf si ce d\u00e9barquement est indispensable \u00e0 l&rsquo;inspection. Elle doit veiller en tout cas \u00e0 ce que cette inspection ou ce d\u00e9barquement n&rsquo;aggrave pas l&rsquo;\u00e9tat des bless\u00e9s et des malades.<\/p>\n<p>3. Si l&rsquo;inspection r\u00e9v\u00e8le que l&rsquo;a\u00e9ronef :<\/p>\n<p>a) est un a\u00e9ronef sanitaire au sens de l&rsquo;article 8, alin\u00e9a j,<\/p>\n<p>b) ne contrevient pas aux conditions prescrites \u00e0 l&rsquo;article 28, et<\/p>\n<p>c) n&rsquo;a pas entrepris son vol en l&rsquo;absence ou en violation d&rsquo;un accord pr\u00e9alable, lorsqu&rsquo;un tel accord est exig\u00e9,<\/p>\n<p>l&rsquo;a\u00e9ronef avec ceux de ses occupants appartenant soit \u00e0 une Partie adverse, soit \u00e0 un Etat neutre ou \u00e0 un autre Etat non Partie au conflit, sera autoris\u00e9 \u00e0 poursuivre son vol sans retard.<\/p>\n<p>4. Si l&rsquo;inspection r\u00e9v\u00e8le que l&rsquo;a\u00e9ronef :<\/p>\n<p>a) n&rsquo;est pas un a\u00e9ronef sanitaire au sens de l&rsquo;article 8, alin\u00e9a j,<\/p>\n<p>b) contrevient aux conditions prescrites \u00e0 l&rsquo;article 28, ou<\/p>\n<p>c) a entrepris son vol en l&rsquo;absence ou en violation d&rsquo;un accord pr\u00e9alable, lorsqu&rsquo;un tel accord est exig\u00e9,<\/p>\n<p>l&rsquo;a\u00e9ronef peut \u00eatre saisi. Ses occupants doivent tous \u00eatre trait\u00e9s conform\u00e9ment aux dispositions pertinentes des Conventions et du pr\u00e9sent Protocole. Au cas o\u00f9 l&rsquo;a\u00e9ronef saisi \u00e9tait affect\u00e9 comme a\u00e9ronef sanitaire permanent, il ne peut \u00eatre utilis\u00e9 ult\u00e9rieurement que comme a\u00e9ronef sanitaire.<\/p>\n<h6 id=\"article-31--neutral-or-other-states-not-parties-to-the-conflict\">Article 31 &#8211; Etats neutres ou autres Etats non Parties au conflit<\/h6>\n<p>1. Les a\u00e9ronefs sanitaires ne doivent ni survoler le territoire d&rsquo;un Etat neutre ou d&rsquo;un autre Etat non Partie au conflit ni atterrir ou amerrir, sauf en vertu d&rsquo;un accord pr\u00e9alable. Cependant, si un tel accord existe, ces a\u00e9ronefs devront \u00eatre respect\u00e9s pendant toute la dur\u00e9e de leur vol et lors des escales \u00e9ventuelles. Ils devront n\u00e9anmoins ob\u00e9ir \u00e0 toute sommation d&rsquo;atterrir ou d&rsquo;amerrir, selon le cas.<\/p>\n<p>2. Un a\u00e9ronef sanitaire qui, en l&rsquo;absence d&rsquo;un accord ou en contravention des dispositions d&rsquo;un accord, survole le territoire d&rsquo;un Etat neutre ou d&rsquo;un autre Etat non Partie au conflit, soit par erreur de navigation, soit en raison d&rsquo;une situation d&rsquo;urgence touchant la s\u00e9curit\u00e9 du vol, doit s&rsquo;efforcer de notifier son vol et de se faire identifier. D\u00e8s que cet Etat aura reconnu un tel a\u00e9ronef sanitaire, il devra faire tous les efforts raisonnables pour donner l&rsquo;ordre d&rsquo;atterrir ou d&rsquo;amerrir, vis\u00e9 \u00e0 l&rsquo;article 30, paragraphe 1, ou pour prendre d&rsquo;autres mesures afin de sauvegarder les int\u00e9r\u00eats de cet Etat et pour donner \u00e0 l&rsquo;a\u00e9ronef dans les deux cas le temps d&rsquo;obtemp\u00e9rer, avant de recourir \u00e0 une attaque.<\/p>\n<p>3. Si un a\u00e9ronef sanitaire, conform\u00e9ment \u00e0 un accord ou dans les conditions indiqu\u00e9es au paragraphe 2, atterrit ou amerrit sur le territoire d&rsquo;un Etat neutre ou d&rsquo;un autre Etat non Partie au conflit, sur sommation ou pour d&rsquo;autres raisons, l&rsquo;a\u00e9ronef pourra \u00eatre soumis \u00e0 une inspection afin de d\u00e9terminer s&rsquo;il s&rsquo;agit bien d&rsquo;un a\u00e9ronef sanitaire. L&rsquo;inspection devra \u00eatre entreprise sans retard et effectu\u00e9e rapidement. La Partie qui proc\u00e8de \u00e0 l&rsquo;inspection ne doit pas exiger que les bless\u00e9s et les malades qui d\u00e9pendent de la Partie employant l&rsquo;a\u00e9ronef soient d\u00e9barqu\u00e9s de l&rsquo;a\u00e9ronef, sauf si ce d\u00e9barquement est indispensable \u00e0 l&rsquo;inspection. Elle veillera en tout cas \u00e0 ce que cette inspection ou ce d\u00e9barquement n&rsquo;aggrave pas l&rsquo;\u00e9tat des bless\u00e9s et des malades. Si l&rsquo;inspection r\u00e9v\u00e8le qu&rsquo;il s&rsquo;agit effectivement d&rsquo;un a\u00e9ronef sanitaire, cet a\u00e9ronef avec ses occupants, exception faite de ceux qui doivent \u00eatre gard\u00e9s en vertu des r\u00e8gles du droit international applicable dans les conflits arm\u00e9s, sera autoris\u00e9 \u00e0 poursuivre son vol et b\u00e9n\u00e9ficiera des facilit\u00e9s appropri\u00e9es. Si l&rsquo;inspection r\u00e9v\u00e8le que cet a\u00e9ronef n&rsquo;est pas un a\u00e9ronef sanitaire, l&rsquo;a\u00e9ronef sera saisi et ses occupants seront trait\u00e9s conform\u00e9ment aux dispositions du paragraphe 4.<\/p>\n<p>4. A l&rsquo;exception de ceux qui sont d\u00e9barqu\u00e9s \u00e0 titre temporaire, les bless\u00e9s, les malades et les naufrag\u00e9s d\u00e9barqu\u00e9s d&rsquo;un a\u00e9ronef sanitaire avec le consentement de l&rsquo;autorit\u00e9 locale sur le territoire d&rsquo;un Etat neutre ou d&rsquo;un autre Etat non Partie au conflit seront, sauf arrangement diff\u00e9rent entre cet Etat et les Parties au conflit, gard\u00e9s par cet Etat lorsque les r\u00e8gles du droit international applicable dans les conflits arm\u00e9s le requi\u00e8rent, de mani\u00e8re qu&rsquo;ils ne puissent pas de nouveau prendre part aux hostilit\u00e9s. Les frais d&rsquo;hospitalisation et d&rsquo;internement sont \u00e0 la charge de l&rsquo;Etat dont ces personnes d\u00e9pendent.<\/p>\n<p>5. Les Etats neutres ou les autres Etats non Parties au conflit appliqueront d&rsquo;une mani\u00e8re \u00e9gale \u00e0 toutes les Parties au conflit les conditions et restrictions \u00e9ventuelles relatives au survol de leur territoire par des a\u00e9ronefs sanitaires ou \u00e0 l&rsquo;atterrissage de ces a\u00e9ronefs.<\/p>\n<h4 id=\"section-iii--missing-and-dead-persons\">Section III &#8211; Personnes disparues et d\u00e9c\u00e9d\u00e9es<\/h4>\n<h6 id=\"article-32--general-principle\">Article 32 &#8211; Principe g\u00e9n\u00e9ral<\/h6>\n<p>dans l&rsquo;application de la pr\u00e9sente Section, l&rsquo;activit\u00e9 des Hautes Parties contractantes, des Parties au conflit et des organisations humanitaires internationales mentionn\u00e9es dans les Conventions et dans le pr\u00e9sent Protocole est motiv\u00e9e au premier chef par le droit qu&rsquo;ont les familles de conna\u00eetre le sort de leurs membres.<\/p>\n<h6 id=\"article-33--missing-persons\">Article 33 &#8211; Personnes disparues<\/h6>\n<p>1. D\u00e8s que les circonstances le permettent et au plus tard d\u00e8s la fin des hostilit\u00e9s actives, chaque Partie au conflit doit rechercher les personnes dont la disparition a \u00e9t\u00e9 signal\u00e9e par une Partie adverse. Ladite Partie adverse doit communiquer tous renseignements utiles sur ces personnes, afin de faciliter les recherches.<\/p>\n<p>2. Afin de faciliter la collecte des renseignements pr\u00e9vus au paragraphe pr\u00e9c\u00e9dent, chaque Partie au conflit doit, en ce qui concerne les personnes qui ne b\u00e9n\u00e9ficieraient pas d&rsquo;un r\u00e9gime plus favorable en vertu des Conventions ou du pr\u00e9sent Protocole :<\/p>\n<p>a) enregistrer les renseignements pr\u00e9vus \u00e0 l&rsquo;article 138 de la IVe Convention sur celles de ces personnes qui ont \u00e9t\u00e9 d\u00e9tenues, emprisonn\u00e9es ou d&rsquo;une autre mani\u00e8re gard\u00e9es en captivit\u00e9 pendant plus de deux semaines en raison des hostilit\u00e9s ou d&rsquo;une occupation, ou qui sont d\u00e9c\u00e9d\u00e9es au cours d&rsquo;une p\u00e9riode de d\u00e9tention;<\/p>\n<p>b) dans toute la mesure du possible, faciliter et, si n\u00e9cessaire, effectuer la recherche et l&rsquo;enregistrement de renseignements sur ces personnes si elles sont d\u00e9c\u00e9d\u00e9es dans d&rsquo;autres circonstances en raison des hostilit\u00e9s ou d&rsquo;une occupation.<\/p>\n<p>3. Les renseignements sur les personnes dont la disparition a \u00e9t\u00e9 signal\u00e9e en application du paragraphe 1 et les demandes relatives \u00e0 ces renseignements sont transmis soit directement, soit par l&rsquo;interm\u00e9diaire de la Puissance protectrice, de l&rsquo;Agence centrale de recherches du Comit\u00e9 international de la Croix-Rouge, ou de Soci\u00e9t\u00e9s nationales de la Croix-Rouge (Croissant-Rouge, Lion-et-Soleil-Rouge). Lorsque ces renseignements ne sont pas transmis par l&rsquo;interm\u00e9diaire du Comit\u00e9 international de la Croix- Rouge et de son Agence centrale de recherches, chaque Partie au conflit fait en sorte qu&rsquo;ils soient aussi fournis \u00e0 l&rsquo;Agence centrale de recherches.<\/p>\n<p>4. Les Parties au conflit s&rsquo;efforceront de s&rsquo;entendre sur des dispositions permettant \u00e0 des \u00e9quipes de rechercher, d&rsquo;identifier et de relever les morts dans les zones des champs de bataille; ces dispositions peuvent pr\u00e9voir, le cas \u00e9ch\u00e9ant, que ces \u00e9quipes soient accompagn\u00e9es par du personnel de la Partie adverse quand elles remplissent leur mission dans les zones qui sont sous le contr\u00f4le de cette Partie adverse. Le personnel de ces \u00e9quipes doit \u00eatre respect\u00e9 et prot\u00e9g\u00e9 lorsqu&rsquo;il se consacre exclusivement \u00e0 de telles missions.<\/p>\n<h6 id=\"article-34--remains-of-deceased\">Article 34 &#8211; Restes des personnes d\u00e9c\u00e9d\u00e9es<\/h6>\n<p>1. Les restes des personnes qui sont d\u00e9c\u00e9d\u00e9es pour des raisons li\u00e9es \u00e0 une occupation ou lors d&rsquo;une d\u00e9tention r\u00e9sultant d&rsquo;une occupation ou d&rsquo;hostilit\u00e9s, et ceux des personnes qui n&rsquo;\u00e9taient pas les ressortissants du pays dans lequel elles sont d\u00e9c\u00e9d\u00e9es en raison d&rsquo;hostilit\u00e9s doivent \u00eatre respect\u00e9s, et les s\u00e9pultures de toutes ces personnes doivent \u00eatre respect\u00e9es, entretenues et marqu\u00e9es comme il est pr\u00e9vu \u00e0 l&rsquo;article 130 de la IVe Convention, pour autant que lesdits restes ou s\u00e9pultures ne rel\u00e8vent pas d&rsquo;un r\u00e9gime plus favorable en vertu des Conventions et du pr\u00e9sent Protocole.<\/p>\n<p>2. D\u00e8s que les circonstances et les relations entre les Parties adverses le permettent, les Hautes Parties contractantes sur le territoire desquelles sont situ\u00e9es les tombes et, le cas \u00e9ch\u00e9ant, d&rsquo;autres lieux o\u00f9 se trouvent les restes des personnes d\u00e9c\u00e9d\u00e9es en raison d&rsquo;hostilit\u00e9s, pendant une occupation ou lors d&rsquo;une d\u00e9tention, doivent conclure des accords en vue :<\/p>\n<p>a) de faciliter l&rsquo;acc\u00e8s des s\u00e9pultures aux membres des familles des personnes d\u00e9c\u00e9d\u00e9es et aux repr\u00e9sentants des services officiels d&rsquo;enregistrement des tombes, et d&rsquo;arr\u00eater les dispositions d&rsquo;ordre pratique concernant cet acc\u00e8s;<\/p>\n<p>b) d&rsquo;assurer en permanence la protection et l&rsquo;entretien de ces s\u00e9pultures;<\/p>\n<p>c) de faciliter le retour des restes des personnes d\u00e9c\u00e9d\u00e9es et de leurs effets personnels dans le pays d&rsquo;origine, \u00e0 la demande de ce pays ou \u00e0 la demande de la famille, \u00e0 moins que ce pays ne s&rsquo;y oppose.<\/p>\n<p>3. En l&rsquo;absence des accords pr\u00e9vus au paragraphe 2, b ou c, et si le pays d&rsquo;origine de ces personnes d\u00e9c\u00e9d\u00e9es n&rsquo;est pas dispos\u00e9 \u00e0 assurer l&rsquo;entretien de ces s\u00e9pultures \u00e0 ses frais, la Haute Partie contractante sur le territoire de laquelle sont situ\u00e9es ces s\u00e9pultures peut offrir de faciliter le retour des restes dans le pays d&rsquo;origine. Si cette offre n&rsquo;a pas \u00e9t\u00e9 accept\u00e9e cinq ans apr\u00e8s avoir \u00e9t\u00e9 faite, la Haute Partie contractante pourra, apr\u00e8s avoir d\u00fbment avis\u00e9 le pays d&rsquo;origine, appliquer les dispositions pr\u00e9vues dans sa l\u00e9gislation en ce qui concerne les cimeti\u00e8res et les s\u00e9pultures.<\/p>\n<p>4. La Haute Partie contractante sur le territoire de laquelle sont situ\u00e9es les s\u00e9pultures vis\u00e9es au pr\u00e9sent article est autoris\u00e9e \u00e0 exhumer les restes uniquement :<\/p>\n<p>a) dans les conditions d\u00e9finies aux paragraphes 2 c et 3, ou<\/p>\n<p>b) lorsque l&rsquo;exhumation s&rsquo;impose pour des motifs d&rsquo;int\u00e9r\u00eat public, y compris dans les cas de n\u00e9cessit\u00e9 sanitaire et d&rsquo;enqu\u00eate, auquel cas la Haute Partie contractante doit, en tout temps, traiter les restes des personnes d\u00e9c\u00e9d\u00e9es avec respect et aviser le pays d&rsquo;origine de son intention de les exhumer, en donnant des pr\u00e9cisions sur l&rsquo;endroit pr\u00e9vu pour la nouvelle inhumation.<\/p>\n<h3>Titre III &#8211; M\u00e9thodes et moyens de guerre<\/h3>\n<h3>Statut de combattant et de prisonnier de guerre<\/h3>\n<h4 id=\"section-i--methods-and-means-of-warfare\">Section I &#8211; M\u00e9thodes et moyens de guerre<\/h4>\n<h6 id=\"article-35--basic-rules\">Article 35 &#8211; R\u00e8gles fondamentales<\/h6>\n<p>1. Dans tout conflit arm\u00e9, le droit des Parties au conflit de choisir des m\u00e9thodes ou moyens de guerre n&rsquo;est pas illimit\u00e9.<\/p>\n<p>2. Il est interdit d&#8217;employer des armes, des projectiles et des mati\u00e8res ainsi que des m\u00e9thodes de guerre de nature \u00e0 causer des maux superflus.<\/p>\n<p>3. Il est interdit d&rsquo;utiliser des m\u00e9thodes ou moyens de guerre qui sont con\u00e7us pour causer, ou dont on peut attendre qu&rsquo;ils causeront, des dommages \u00e9tendus, durables et graves \u00e0 l&rsquo;environnement naturel.<\/p>\n<h6 id=\"article-36--new-weapons\">Article 36 &#8211; Armes nouvelles<\/h6>\n<p>Dans l&rsquo;\u00e9tude, la mise au point, l&rsquo;acquisition ou l&rsquo;adoption d&rsquo;une nouvelle arme, de nouveaux moyens ou d&rsquo;une nouvelle m\u00e9thode de guerre, une Haute Partie contractante a l&rsquo;obligation de d\u00e9terminer si l&#8217;emploi en serait interdit, dans certaines circonstances ou en toutes circonstances, par les dispositions du pr\u00e9sent Protocole ou par toute autre r\u00e8gle du droit international applicable \u00e0 cette Haute Partie contractante.<\/p>\n<h6 id=\"article-37--prohibition-of-perfidy\">Article 37 &#8211; Interdiction de la perfidie<\/h6>\n<p>1. Il est interdit de tuer, blesser ou capturer un adversaire en recourant \u00e0 la perfidie. Constituent une perfidie les actes faisant appel, avec l&rsquo;intention de la tromper, \u00e0 la bonne foi d&rsquo;un adversaire pour lui faire croire qu&rsquo;il a le droit de recevoir ou l&rsquo;obligation d&rsquo;accorder la protection pr\u00e9vue par les r\u00e8gles du droit international applicable dans les conflits arm\u00e9s. Les actes suivants sont des exemples de perfidie :<\/p>\n<p>a) feindre l&rsquo;intention de n\u00e9gocier sous le couvert du pavillon parlementaire, ou feindre la reddition;<\/p>\n<p>b) feindre une incapacit\u00e9 due \u00e0 des blessures ou \u00e0 la maladie;<\/p>\n<p>c) feindre d&rsquo;avoir le statut de civil ou de non-combattant;<\/p>\n<p>d) feindre d&rsquo;avoir un statut prot\u00e9g\u00e9 en utilisant des signes embl\u00e8mes ou uniformes des Nations Unies, d&rsquo;Etats neutres ou d&rsquo;autres Etats non Parties au conflit.<\/p>\n<p>2. Les ruses de guerre ne sont pas interdites. Constituent des ruses de guerre les actes qui ont pour but d&rsquo;induire un adversaire en erreur ou de lui faire commettre des imprudences, mais qui n&rsquo;enfreignent aucune r\u00e8gle du droit international applicable dans les conflits arm\u00e9s et qui, ne faisant pas appel \u00e0 la bonne foi de l&rsquo;adversaire en ce qui concerne la protection pr\u00e9vue par ce droit, ne sont pas perfides. Les actes suivants sont des exemples de ruses de guerre : l&rsquo;usage de camouflages, de leurres, d&rsquo;op\u00e9rations simul\u00e9es et de faux renseignements.<\/p>\n<h6 id=\"article-38--recognized-emblems\">Article 38 &#8211; Embl\u00e8mes reconnus<\/h6>\n<p>1. Il est interdit d&rsquo;utiliser ind\u00fbment le signe distinctif de la croix rouge, du croissant rouge ou du lion-et-soleil rouge ou d&rsquo;autres embl\u00e8mes, signes ou signaux pr\u00e9vus par les Conventions ou par le pr\u00e9sent Protocole. Il est \u00e9galement interdit de faire un usage abusif d\u00e9lib\u00e9r\u00e9, dans un conflit arm\u00e9, d&rsquo;autres embl\u00e8mes, signes ou signaux protecteurs reconnus sur le plan international, y compris le pavillon parlementaire, et de l&#8217;embl\u00e8me protecteur des biens culturels.<\/p>\n<p>2. Il est interdit d&rsquo;utiliser l&#8217;embl\u00e8me distinctif des Nations Unies en dehors des cas o\u00f9 l&rsquo;usage en est autoris\u00e9 par cette Organisation.<\/p>\n<h6 id=\"article-39--emblems-of-nationality\">Article 39 &#8211; Signes de nationalit\u00e9<\/h6>\n<p>1. Il est interdit d&rsquo;utiliser, dans un conflit arm\u00e9, les drapeaux ou pavillons, symboles, insignes ou uniformes militaires d&rsquo;Etats neutres ou d&rsquo;autres Etats non Parties au conflit.<\/p>\n<p>2. Il est interdit d&rsquo;utiliser les drapeaux ou pavillons, symboles, insignes ou uniformes militaires des Parties adverses pendant des attaques ou pour dissimuler, favoriser, prot\u00e9ger ou entraver des op\u00e9rations militaires.<\/p>\n<p>3. Aucune des dispositions du pr\u00e9sent article ou de l&rsquo;article 37, paragraphe 1 d, n&rsquo;affecte les r\u00e8gles existantes g\u00e9n\u00e9ralement reconnues du droit international applicable \u00e0 l&rsquo;espionnage ou \u00e0 l&#8217;emploi des pavillons dans la conduite des conflits arm\u00e9s sur mer.<\/p>\n<h6 id=\"article-40--quarter\">Article 40 &#8211; Quartier<\/h6>\n<p>Il est interdit d&rsquo;ordonner qu&rsquo;il n&rsquo;y ait pas de survivants, d&rsquo;en menacer l&rsquo;adversaire ou de conduire les hostilit\u00e9s en fonction de cette d\u00e9cision.<\/p>\n<h6 id=\"article-41--safeguard-of-an-enemy-hors-de-combat\">Article 41 &#8211; Sauvegarde de l&rsquo;ennemi hors de combat<\/h6>\n<p>1. Aucune personne reconnue, ou devant \u00eatre reconnue, eu \u00e9gard aux circonstances, comme \u00e9tant hors de combat, ne doit \u00eatre l&rsquo;objet d&rsquo;une attaque.<\/p>\n<p>2. Est hors de combat toute personne :<\/p>\n<p>a) qui est au pouvoir d&rsquo;une Partie adverse,<\/p>\n<p>b) qui exprime clairement son intention de se rendre, ou<\/p>\n<p>c) qui a perdu connaissance ou est autrement en \u00e9tat d&rsquo;incapacit\u00e9 du fait de blessures ou de maladie et en cons\u00e9quence incapable de se d\u00e9fendre, \u00e0 condition que, dans tous les cas, elle s&rsquo;abstienne de tout acte d&rsquo;hostilit\u00e9 et ne tente pas de s&rsquo;\u00e9vader.<\/p>\n<p>3. Lorsque des personnes ayant droit \u00e0 la protection des prisonniers de guerre sont tomb\u00e9es au pouvoir d&rsquo;une Partie adverse dans des conditions inhabituelles de combat qui emp\u00eachent de les \u00e9vacuer comme il est pr\u00e9vu au Titre III, Section I, de la IIIe Convention, elles doivent \u00eatre lib\u00e9r\u00e9es et toutes les pr\u00e9cautions utiles doivent \u00eatre prises pour assurer leur s\u00e9curit\u00e9.<\/p>\n<h6 id=\"article-42--occupants-of-aircraft\">Article 42 &#8211; Occupants d&rsquo;a\u00e9ronefs<\/h6>\n<p>1. Aucune personne sautant en parachute d&rsquo;un a\u00e9ronef en perdition ne doit faire l&rsquo;objet d&rsquo;une attaque pendant la descente.<\/p>\n<p>2. En touchant le sol d&rsquo;un territoire contr\u00f4l\u00e9 par une Partie adverse, la personne qui a saut\u00e9 en parachute d&rsquo;un a\u00e9ronef en perdition doit se voir accorder la possibilit\u00e9 de se rendre avant de faire l&rsquo;objet d&rsquo;une attaque, sauf s&rsquo;il est manifeste qu&rsquo;elle se livre \u00e0 un acte d&rsquo;hostilit\u00e9.<\/p>\n<p>3. Les troupes a\u00e9roport\u00e9es ne sont pas prot\u00e9g\u00e9es par le pr\u00e9sent article.<\/p>\n<h4 id=\"section-ii--combatant-and-prisonerofwar-status\">Section II &#8211; Statut de combattant et de prisonnier de guerre<\/h4>\n<h6 id=\"article-43--armed-forces\">Article 43 &#8211; Forces arm\u00e9es<\/h6>\n<p>1. Les forces arm\u00e9es d&rsquo;une Partie \u00e0 un conflit se composent de toutes les forces, tous les groupes et toutes les unit\u00e9s arm\u00e9s et organis\u00e9s qui sont plac\u00e9s sous un commandement responsable de la conduite de ses subordonn\u00e9s devant cette Partie, m\u00eame si celle-ci est repr\u00e9sent\u00e9e par un gouvernement ou une autorit\u00e9 non reconnus par une Partie adverse. Ces forces arm\u00e9es doivent \u00eatre soumises \u00e0 un r\u00e9gime de discipline interne qui assure, notamment, le respect des r\u00e8gles du droit international applicable dans les conflits arm\u00e9s.<\/p>\n<p>2. Les membres des forces arm\u00e9es d&rsquo;une Partie \u00e0 un conflit (autres que le personnel sanitaire et religieux vis\u00e9 \u00e0 l&rsquo;article 33 de la IIIe Convention) sont des combattants, c&rsquo;est-\u00e0-dire ont le droit de participer directement aux hostilit\u00e9s.<\/p>\n<p>3. La Partie \u00e0 un conflit qui incorpore, dans ses forces arm\u00e9es, une organisation paramilitaire ou un service arm\u00e9 charg\u00e9 de faire respecter l&rsquo;ordre, doit le notifier aux autres Parties au conflit.<\/p>\n<h6 id=\"article-44--combatants-and-prisoners-of-war\">Article 44 &#8211; Combattants et prisonniers de guerre<\/h6>\n<p>1. Tout combattant, au sens de l&rsquo;article 43, qui tombe au pouvoir d&rsquo;une Partie adverse est prisonnier de guerre.<\/p>\n<p>2. Bien que tous les combattants soient tenus de respecter les r\u00e8gles du droit international applicable dans les conflits arm\u00e9s, les violations de ces r\u00e8gles ne privent pas un combattant de son droit d&rsquo;\u00eatre consid\u00e9r\u00e9 comme combattant ou, s&rsquo;il tombe au pouvoir d&rsquo;une Partie adverse, de son droit d&rsquo;\u00eatre consid\u00e9r\u00e9 comme prisonnier de guerre, sauf dans les cas pr\u00e9vus aux paragraphes 3 et 4.<\/p>\n<p>3. Pour que la protection de la population civile contre les effets des hostilit\u00e9s soit renforc\u00e9e, les combattants sont tenus de se distinguer de la population civile lorsqu&rsquo;ils prennent part \u00e0 une attaque ou \u00e0 une op\u00e9ration militaire pr\u00e9paratoire d&rsquo;une attaque. Etant donn\u00e9, toutefois, qu&rsquo;il y a des situations dans les conflits arm\u00e9s o\u00f9, en raison de la nature des hostilit\u00e9s, un combattant arm\u00e9 ne peut se distinguer de la population civile, il conserve son statut de combattant \u00e0 condition que, dans de telles situations, il porte ses armes ouvertement :<\/p>\n<p>a) pendant chaque engagement militaire; et<\/p>\n<p>b) pendant le temps o\u00f9 il est expos\u00e9 \u00e0 la vue de l&rsquo;adversaire alors qu&rsquo;il prend part \u00e0 un d\u00e9ploiement militaire qui pr\u00e9c\u00e8de le lancement d&rsquo;une attaque \u00e0 laquelle il doit participer.<\/p>\n<p>Les actes qui r\u00e9pondent aux conditions pr\u00e9vues par le pr\u00e9sent paragraphe ne sont pas consid\u00e9r\u00e9s comme perfides au sens de l&rsquo;article 37, paragraphe 1 c.<\/p>\n<p>4. Tout combattant qui tombe au pouvoir d&rsquo;une Partie adverse, alors qu&rsquo;il ne remplit pas les conditions pr\u00e9vues \u00e0 la deuxi\u00e8me phrase du paragraphe 3, perd son droit \u00e0 \u00eatre consid\u00e9r\u00e9 comme prisonnier de guerre, mais b\u00e9n\u00e9ficie n\u00e9anmoins de protections \u00e9quivalentes \u00e0 tous \u00e9gards \u00e0 celles qui sont accord\u00e9es aux prisonniers de guerre par le IIIe Convention et par le pr\u00e9sent Protocole. Cette protection comprend des protections \u00e9quivalentes \u00e0 celles qui sont accord\u00e9es aux prisonniers de guerre par la IIIe Convention dans le cas o\u00f9 une telle personne est jug\u00e9e et condamn\u00e9e pour toutes infractions qu&rsquo;elle aura commises.<\/p>\n<p>5. Le combattant qui tombe au pouvoir d&rsquo;une Partie adverse alors qu&rsquo;il ne participe pas \u00e0 une attaque ou \u00e0 une op\u00e9ration militaire pr\u00e9paratoire d&rsquo;une attaque ne perd pas, en raison de ses activit\u00e9s ant\u00e9rieures, le droit d&rsquo;\u00eatre consid\u00e9r\u00e9 comme combattant et prisonnier de guerre.<\/p>\n<p>6. Le pr\u00e9sent article ne prive personne du droit d&rsquo;\u00eatre consid\u00e9r\u00e9 comme prisonnier de guerre aux termes de l&rsquo;article 4 de la IIIe Convention.<\/p>\n<p>7. La pr\u00e9sent article n&rsquo;a pas pour objet de modifier la pratique des Etats, g\u00e9n\u00e9ralement accept\u00e9e, concernant le port de l&rsquo;uniforme par des combattants affect\u00e9s aux unit\u00e9s arm\u00e9es r\u00e9guli\u00e8res en uniforme d&rsquo;une Partie au conflit;<\/p>\n<p>8. Outre les cat\u00e9gories de personnes vis\u00e9es \u00e0 l&rsquo;article 13 des Ire et IIe Conventions, tous les membres des forces arm\u00e9es d&rsquo;une Partie au conflit, tels qu&rsquo;ils sont d\u00e9finis \u00e0 l&rsquo;article 43 du pr\u00e9sent Protocole, ont droit \u00e0 la protection accord\u00e9e par lesdites Conventions s&rsquo;ils sont bless\u00e9s ou malades, ou dans le cas de la IIe Convention, s&rsquo;ils sont naufrag\u00e9s en mer ou en d&rsquo;autres eaux.<\/p>\n<h6 id=\"article-45--protection-of-persons-who-have-taken-part-in-hostilities\">Article 45 &#8211; Protection des personnes ayant pris part aux hostilit\u00e9s<\/h6>\n<p>1. Une personne qui prend part \u00e0 des hostilit\u00e9s et tombe au pouvoir d&rsquo;une Partie adverse est pr\u00e9sum\u00e9e \u00eatre prisonnier de guerre et par cons\u00e9quent se trouve prot\u00e9g\u00e9e par la IIIe Convention lorsqu&rsquo;elle revendique le statut de prisonnier de guerre, ou qu&rsquo;il appara\u00eet qu&rsquo;elle a droit au statut de prisonnier de guerre, ou lorsque la Partie dont elle d\u00e9pend revendique pour elle ce statut par voie de notification \u00e0 la Puissance qui la d\u00e9tient ou \u00e0 la Puissance protectrice. S&rsquo;il existe un doute quelconque au sujet de son droit au statut de prisonnier de guerre, cette personne continue \u00e0 b\u00e9n\u00e9ficier de ce statut et, par suite, de la protection de la IIIe Convention et du pr\u00e9sent Protocole, en attendant que son statut soit d\u00e9termin\u00e9 par un tribunal comp\u00e9tent.<\/p>\n<p>2. Si une personne tomb\u00e9e au pouvoir d&rsquo;une Partie adverse n&rsquo;est pas d\u00e9tenue comme prisonnier de guerre et doit \u00eatre jug\u00e9e par cette Partie pour une infraction li\u00e9e aux hostilit\u00e9s, elle est habilit\u00e9e \u00e0 faire valoir son droit au statut de prisonnier de guerre devant un tribunal judiciaire et \u00e0 obtenir que cette question soit tranch\u00e9e. Chaque fois que la proc\u00e9dure applicable le permet, la question doit \u00eatre tranch\u00e9e avant qu&rsquo;il soit statu\u00e9 sur l&rsquo;infraction. Les repr\u00e9sentants de la Puissance protectrice ont le droit d&rsquo;assister aux d\u00e9bats au cours desquels cette question doit \u00eatre tranch\u00e9e, sauf dans le cas exceptionnel o\u00f9 ces d\u00e9bats ont lieu \u00e0 huis clos dans l&rsquo;int\u00e9r\u00eat de la s\u00fbret\u00e9 de l&rsquo;Etat. Dans ce cas, la Puissance d\u00e9tentrice doit en aviser la Puissance protectrice.<\/p>\n<p>3. Toute personne qui, ayant pris part \u00e0 des hostilit\u00e9s, n&rsquo;a pas droit au statut de prisonnier de guerre et ne b\u00e9n\u00e9ficie pas d&rsquo;un traitement plus favorable conform\u00e9ment \u00e0 la IVe Convention a droit, en tout temps, \u00e0 la protection de l&rsquo;article 75 du pr\u00e9sent Protocole. En territoire occup\u00e9, une telle personne, sauf si elle est d\u00e9tenue pour espionnage, b\u00e9n\u00e9ficie \u00e9galement, nonobstant les dispositions de l&rsquo;article 5 de la IVe Convention, des droits de communication pr\u00e9vus par ladite Convention.<\/p>\n<h6 id=\"article-46--spies\">Article 46 &#8211; Espions<\/h6>\n<p>1. Nonobstant toute autre disposition des Conventions ou du pr\u00e9sent Protocole, un membre des forces arm\u00e9es d&rsquo;une Partie au conflit qui tombe au pouvoir d&rsquo;une Partie adverse alors qu&rsquo;il se livre \u00e0 des activit\u00e9s d&rsquo;espionnage n&rsquo;a pas droit au statut de prisonnier de guerre et peut \u00eatre trait\u00e9 en espion.<\/p>\n<p>2. Un membre des forces arm\u00e9es d&rsquo;une Partie au conflit qui recueille ou cherche \u00e0 recueillir, pour le compte de cette Partie, des renseignements dans un territoire contr\u00f4l\u00e9 par une Partie adverse ne sera pas consid\u00e9r\u00e9 comme se livrant \u00e0 des activit\u00e9s d&rsquo;espionnage si, ce faisant, il est rev\u00eatu de l&rsquo;uniforme de ses forces arm\u00e9es.<\/p>\n<p>3. Un membre des forces arm\u00e9es d&rsquo;une Partie au conflit qui est r\u00e9sident d&rsquo;un territoire occup\u00e9 par une Partie adverse, et qui recueille ou cherche \u00e0 recueillir, pour le compte de la Partie dont il d\u00e9pend, des renseignements d&rsquo;int\u00e9r\u00eat militaire dans ce territoire, ne sera pas consid\u00e9r\u00e9 comme se livrant \u00e0 des activit\u00e9s d&rsquo;espionnage, \u00e0 moins que, ce faisant, il n&rsquo;agisse sous de fallacieux pr\u00e9textes ou de fa\u00e7on d\u00e9lib\u00e9r\u00e9ment clandestine. De plus, ce r\u00e9sident ne perd son droit au statut de prisonnier de guerre et ne peut \u00eatre trait\u00e9 en espion qu&rsquo;au seul cas o\u00f9 il est captur\u00e9 alors qu&rsquo;il se livre \u00e0 des activit\u00e9s d&rsquo;espionnage.<\/p>\n<p>4. Un membre des forces arm\u00e9es d&rsquo;une Partie au conflit qui n&rsquo;est pas r\u00e9sident d&rsquo;un territoire occup\u00e9 par une Partie adverse et qui s&rsquo;est livr\u00e9 \u00e0 des activit\u00e9s d&rsquo;espionnage dans ce territoire ne perd son droit au statut de prisonnier de guerre et ne peut \u00eatre trait\u00e9 en espion qu&rsquo;au seul cas o\u00f9 il est captur\u00e9 avant d&rsquo;avoir rejoint les forces arm\u00e9es auxquelles il appartient.<\/p>\n<h6 id=\"article-47--mercenaries\">Article 47 &#8211; Mercenaires<\/h6>\n<p>1. Un mercenaire n&rsquo;a pas droit au statut de combattant ou de prisonnier de guerre.<\/p>\n<p>2. Le terme \u00ab\u00a0mercenaire\u00a0\u00bb s&rsquo;entend de toute personne :<\/p>\n<p>a) qui est sp\u00e9cialement recrut\u00e9e dans le pays ou \u00e0 l&rsquo;\u00e9tranger pour combattre dans un conflit arm\u00e9;<\/p>\n<p>b) qui en fait prend une part directe aux hostilit\u00e9s;<\/p>\n<p>c) qui prend part aux hostilit\u00e9s essentiellement en vue d&rsquo;obtenir un avantage personnel et \u00e0 laquelle est effectivement promise, par une Partie au conflit ou en son nom, une r\u00e9mun\u00e9ration mat\u00e9rielle nettement sup\u00e9rieure \u00e0 celle qui est promise ou pay\u00e9e \u00e0 des combattants ayant un rang et une fonction analogues dans les forces arm\u00e9es de cette Partie;<\/p>\n<p>d) qui n&rsquo;est ni ressortissant d&rsquo;une Partie au conflit, ni r\u00e9sident du territoire contr\u00f4l\u00e9 par une Partie au conflit;<\/p>\n<p>e) qui n&rsquo;est pas membre des forces arm\u00e9es d&rsquo;une Partie au conflit; et<\/p>\n<p>f) qui n&rsquo;a pas \u00e9t\u00e9 envoy\u00e9e par un Etat autre qu&rsquo;une Partie au conflit en mission officielle en tant que membre des forces arm\u00e9es dudit Etat.<\/p>\n<h3>Titre IV &#8211; Population civile<\/h3>\n<h4 id=\"section-i--general-protection-against-effects-of-hostilities\">Section I &#8211; Protection g\u00e9n\u00e9rale contre les effets des hostilit\u00e9s<\/h4>\n<h5 id=\"chapter-1---basic-rule-and-field-of-application\">Chapitre I &#8211; R\u00e8gle fondamentale et champ d&rsquo;application<\/h5>\n<h6 id=\"article-48---basic-rule\">Article 48 &#8211; R\u00e8gle fondamentale<\/h6>\n<p>En vue d&rsquo;assurer le respect et la protection de la population civile et des biens de caract\u00e8re civil, les Parties au conflit doivent en tout temps faire la distinction entre la population civile et les combattants ainsi qu&rsquo;entre les biens de caract\u00e8re civil et les objectifs militaires et, par cons\u00e9quent, ne diriger leurs op\u00e9rations que contre des objectifs militaires.<\/p>\n<h6 id=\"article-49---definition-of-attacks-scope-of-application\">Article 49 &#8211; D\u00e9finition des attaques et champ d&rsquo;application<\/h6>\n<p>1. L&rsquo;expression \u00ab\u00a0attaques\u00a0\u00bb s&rsquo;entend des actes de violence contre l&rsquo;adversaire, que ces actes soient offensifs ou d\u00e9fensifs.<\/p>\n<p>2. Les dispositions du pr\u00e9sent Protocole concernant les attaques s&rsquo;appliquent \u00e0 toutes les attaques, quel que soit le territoire o\u00f9 elles ont lieu, y compris le territoire national appartenant \u00e0 une Partie au conflit mais se trouvant sous le contr\u00f4le d&rsquo;une Partie adverse.<\/p>\n<p>3. Les dispositions de la pr\u00e9sente Section s&rsquo;appliquent \u00e0 toute op\u00e9ration terrestre, a\u00e9rienne ou navale pouvant affecter, sur terre, la population civile, les personnes civiles et les biens de caract\u00e8re civil. Elles s&rsquo;appliquent en outre \u00e0 toutes les attaques navales ou a\u00e9riennes dirig\u00e9es contre des objectifs sur terre, mais n&rsquo;affectent pas autrement les r\u00e8gles du droit international applicable dans les conflits arm\u00e9s sur mer ou dans les airs.<\/p>\n<p>4. Les dispositions de la pr\u00e9sente Section compl\u00e8tent les r\u00e8gles relatives \u00e0 la protection humanitaire \u00e9nonc\u00e9es dans la IVe Convention, en particulier au Titre II, et dans les autres accords internationaux qui lient les Hautes Parties contractantes, ainsi que les autres r\u00e8gles du droit international relatives \u00e0 la protection des civils et des biens de caract\u00e8re civil contre les effets des hostilit\u00e9s sur terre, sur mer et dans les airs.<\/p>\n<h5 id=\"chapter-ii---civilians-and-civilian-population\">Chapitre II &#8211; Personnes civiles et population civile<\/h5>\n<h6 id=\"article-50---definition-of-civilians-and-civilian-population\">Article 50 &#8211; D\u00e9finition des personnes civiles et de la population civile<\/h6>\n<p>1. Est consid\u00e9r\u00e9e comme civile toute personne n&rsquo;appartenant pas \u00e0 l&rsquo;une des cat\u00e9gories vis\u00e9es \u00e0 l&rsquo;article 4 A. 1), 2), 3), et 6) de la IIIe Convention et \u00e0 l&rsquo;article 43 du pr\u00e9sent Protocole. En cas de doute, ladite personne sera consid\u00e9r\u00e9e comme civile.<\/p>\n<p>2. La population civile comprend toutes les personnes civiles.<\/p>\n<p>3. La pr\u00e9sence au sein de la population civile de personnes isol\u00e9es ne r\u00e9pondant pas \u00e0 la d\u00e9finition de personne civile ne prive pas cette population de sa qualit\u00e9.<\/p>\n<h6 id=\"article-51---protection-of-the-civilian-population\">Article 51 &#8211; Protection de la population civile<\/h6>\n<p>1. La population civile et les personnes civiles jouissent d&rsquo;une protection g\u00e9n\u00e9rale contre les dangers r\u00e9sultant d&rsquo;op\u00e9rations militaires. En vue de rendre cette protection effective, les r\u00e8gles suivantes, qui s&rsquo;ajoutent aux autres r\u00e8gles du droit international applicable, doivent \u00eatre observ\u00e9es en toutes circonstances.<\/p>\n<p>2. Ni la population civile en tant que telle ni les personnes civiles ne doivent \u00eatre l&rsquo;objet d&rsquo;attaques. Sont interdits les actes ou menaces de violence dont le but principal est de r\u00e9pandre la terreur parmi la population civile.<\/p>\n<p>3. Les personnes civiles jouissent de la protection accord\u00e9e par la pr\u00e9sente Section, sauf si elles participent directement aux hostilit\u00e9s et pendant la dur\u00e9e de cette participation.<\/p>\n<p>4. Les attaques sans discrimination sont interdites. L&rsquo;expression \u00ab\u00a0attaques sans discrimination\u00a0\u00bb s&rsquo;entend :<\/p>\n<p>a) des attaques qui ne sont pas dirig\u00e9es contre un objectif militaire d\u00e9termin\u00e9;<\/p>\n<p>b) des attaques dans lesquelles on utilise des m\u00e9thodes ou moyens de combat qui ne peuvent pas \u00eatre dirig\u00e9s contre un objectif militaire d\u00e9termin\u00e9; ou<\/p>\n<p>c) des attaques dans lesquelles on utilise des m\u00e9thodes ou moyens de combat dont les effets ne peuvent pas \u00eatre limit\u00e9s comme le prescrit le pr\u00e9sent Protocole;<\/p>\n<p>et qui sont, en cons\u00e9quence, dans chacun de ces cas, propres \u00e0 frapper indistinctement des objectifs militaires et des personnes civiles ou des biens de caract\u00e8re civil.<\/p>\n<p>5. Seront, entre autres, consid\u00e9r\u00e9s comme effectu\u00e9s sans discrimination les types d&rsquo;attaques suivants :<\/p>\n<p>a) les attaques par bombardement, quels que soient les m\u00e9thodes ou moyens utilis\u00e9s, qui traitent comme un objectif militaire unique un certain nombre d&rsquo;objectifs militaires nettement espac\u00e9s et distincts situ\u00e9s dans une ville, un village ou toute autre zone contenant une concentration analogue de personnes civiles ou de biens de caract\u00e8re civil;<\/p>\n<p>b) les attaques dont on peut attendre qu&rsquo;elles causent incidemment des pertes en vies humaines dans la population civile, des blessures aux personnes civiles, des dommages aux biens de caract\u00e8re civil, ou une combinaison de ces pertes et dommages, qui seraient excessifs par rapport \u00e0 l&rsquo;avantage militaire concret et direct attendu.<\/p>\n<p>6. Sont interdites les attaques dirig\u00e9es \u00e0 titre de repr\u00e9sailles contre la population civile ou des personnes civiles.<\/p>\n<p>7. La pr\u00e9sence ou les mouvements de la population civile ou de personnes civiles ne doivent pas \u00eatre utilis\u00e9s pour mettre certains points ou certaines zones \u00e0 l&rsquo;abri d&rsquo;op\u00e9rations militaires, notamment pour tenter de mettre des objectifs militaires \u00e0 l&rsquo;abri d&rsquo;attaques ou de couvrir, favoriser ou g\u00eaner des op\u00e9rations militaires. Les Parties au conflit ne doivent pas diriger les mouvements de la population civile ou des personnes civiles pour tenter de mettre des objectifs militaires \u00e0 l&rsquo;abri des attaques ou de couvrir des op\u00e9rations militaires.<\/p>\n<p>8. Aucune violation de ces interdictions ne dispense les Parties au conflit de leurs obligations juridiques \u00e0 l&rsquo;\u00e9gard de la population civile et des personnes civiles, y compris l&rsquo;obligation de prendre les mesures de pr\u00e9caution pr\u00e9vues par l&rsquo;article 57.<\/p>\n<h5 id=\"chapter-iii---civilian-objects\">Chapitre III &#8211; Biens de caract\u00e8re civil<\/h5>\n<h6 id=\"article-52---general-protection-of-civilian-objects\">Article 52 &#8211; Protection g\u00e9n\u00e9rale des biens de caract\u00e8re civil<\/h6>\n<p>1. Les biens de caract\u00e8re civil ne doivent \u00eatre l&rsquo;objet ni d&rsquo;attaques ni de repr\u00e9sailles. Sont biens de caract\u00e8re civil tous les biens qui ne sont pas des objectifs militaires au sens du paragraphe 2.<\/p>\n<p>2. Les attaques doivent \u00eatre strictement limit\u00e9es aux objectifs militaires. En ce qui concerne les biens, les objectifs militaires sont limit\u00e9s aux biens qui, par leur nature, leur emplacement, leur destination ou leur utilisation apportent une contribution effective \u00e0 l&rsquo;action militaire et dont la destruction totale ou partielle, la capture ou la neutralisation offre en l&rsquo;occurrence un avantage militaire pr\u00e9cis.<\/p>\n<p>3. En cas de doute, un bien qui est normalement affect\u00e9 \u00e0 un usage civil, tel qu&rsquo;un lieu de culte, une maison, un autre type d&rsquo;habitation ou une \u00e9cole, est pr\u00e9sum\u00e9 ne pas \u00eatre utilis\u00e9 en vue d&rsquo;apporter une contribution effective \u00e0 l&rsquo;action militaire.<\/p>\n<h6 id=\"article-53---protection-of-cultural-objects-and-of-places-of-worship\">Article 53 &#8211; Protection des biens culturels et des lieux de culte<\/h6>\n<p>Sans pr\u00e9judice des dispositions de la Convention de La Haye du 14 mai 1954 pour la protection des biens culturels en cas de conflit arm\u00e9 et d&rsquo;autres instruments internationaux pertinents, il est interdit :<\/p>\n<p>a) de commettre tout acte d&rsquo;hostilit\u00e9 dirig\u00e9 contre les monuments historiques, les oeuvres d&rsquo;art ou les lieux de culte qui constituent le patrimoine culturel ou spirituel des peuples;<\/p>\n<p>b) d&rsquo;utiliser ces biens \u00e0 l&rsquo;appui de l&rsquo;effort militaire;<\/p>\n<p>c) de faire de ces biens l&rsquo;objet de repr\u00e9sailles.<\/p>\n<h6 id=\"article-54---protection-of-objects-indispensable-to-the-survival-of-the-civilian-population\">Article 54 &#8211; Protection des biens indispensables \u00e0 la survie de la population civile<\/h6>\n<p>1. Il est interdit d&rsquo;utiliser contre les civils la famine comme m\u00e9thode de guerre.<\/p>\n<p>2. Il est interdit d&rsquo;attaquer, de d\u00e9truire, d&rsquo;enlever ou de mettre hors d&rsquo;usage des biens indispensables \u00e0 la survie de la population civile, tels que des denr\u00e9es alimentaires et les zones agricoles qui les produisent, les r\u00e9coltes, le b\u00e9tail, les installations et r\u00e9serves d&rsquo;eau potable et les ouvrages d&rsquo;irrigation, en vue d&rsquo;en priver, \u00e0 raison de leur valeur de subsistance, la population civile ou la Partie adverse, quel que soit le motif dont on s&rsquo;inspire, que ce soit pour affamer des personnes civiles, provoquer leur d\u00e9placement ou pour toute autre raison.<\/p>\n<p>3. Les interdictions pr\u00e9vues au paragraphe 2 ne s&rsquo;appliquent pas si les biens \u00e9num\u00e9r\u00e9s sont utilis\u00e9s par une Partie adverse :<\/p>\n<p>a) pour la subsistance des seuls membres de ses forces arm\u00e9es;<\/p>\n<p>b) \u00e0 d&rsquo;autres fins que cet approvisionnement, mais comme appui direct d&rsquo;une action militaire, \u00e0 condition toutefois de n&rsquo;engager en aucun cas, contre ces biens, des actions dont on pourrait attendre qu&rsquo;elles laissent \u00e0 la population civile si peu de nourriture ou d&rsquo;eau qu&rsquo;elle serait r\u00e9duite \u00e0 la famine ou forc\u00e9e de se d\u00e9placer.<\/p>\n<p>4. Ces biens ne devront pas \u00eatre l&rsquo;objet de repr\u00e9sailles.<\/p>\n<p>5. Compte tenu des exigences vitales de toute Partie au conflit pour la d\u00e9fense de son territoire national contre l&rsquo;invasion, des d\u00e9rogations aux interdictions pr\u00e9vues au paragraphe 2 sont permises \u00e0 une Partie au conflit sur un tel territoire se trouvant sous son contr\u00f4le si des n\u00e9cessit\u00e9s militaires imp\u00e9rieuses l&rsquo;exigent.<\/p>\n<h6 id=\"article-55---protection-of-the-natural-environment\">Article 55 &#8211; Protection de l&rsquo;environnement naturel<\/h6>\n<p>1. La guerre sera conduite en veillant \u00e0 prot\u00e9ger l&rsquo;environnement naturel contre des dommages \u00e9tendus, durables et graves. Cette protection inclut l&rsquo;interdiction d&rsquo;utiliser des m\u00e9thodes ou moyens de guerre con\u00e7us pour causer ou dont on peut attendre qu&rsquo;ils causent de tels dommages \u00e0 l&rsquo;environnement naturel, compromettant, de ce fait, la sant\u00e9 ou la survie de la population.<\/p>\n<p>2. Les attaques contre l&rsquo;environnement naturel \u00e0 titre de repr\u00e9sailles sont interdites.<\/p>\n<h6 id=\"article-56---protection-of-works-and-installations-containing-dangerous-forces\">Articles 56 &#8211; Protection des ouvrages et installations contenant des forces dangereuses<\/h6>\n<p>1. Les ouvrages d&rsquo;art ou installations contenant des forces dangereuses, \u00e0 savoir les barrages, les digues et les centrales nucl\u00e9aires de production d&rsquo;\u00e9nergie \u00e9lectrique, ne seront pas l&rsquo;objet d&rsquo;attaques, m\u00eame s&rsquo;ils constituent des objectifs militaires, lorsque de telles attaques peuvent provoquer la lib\u00e9ration de ces forces et, en cons\u00e9quence, causer des pertes s\u00e9v\u00e8res dans la population civile. Les autres objectifs militaires situ\u00e9s sur ces ouvrages ou installations ou \u00e0 proximit\u00e9 ne doivent pas \u00eatre l&rsquo;objet d&rsquo;attaques lorsque de telles attaques peuvent provoquer la lib\u00e9ration de forces dangereuses et, en cons\u00e9quence, causer des pertes s\u00e9v\u00e8res dans la population civile.<\/p>\n<p>2. La protection sp\u00e9ciale contre les attaques pr\u00e9vues au paragraphe 1 ne peut cesser :<\/p>\n<p>a) pour les barrages ou les digues, que s&rsquo;ils sont utilis\u00e9s \u00e0 des fins autres que leur fonction normale et pour l&rsquo;appui r\u00e9gulier, important et direct d&rsquo;op\u00e9rations militaires, et si de telles attaques sont le seul moyen pratique de faire cesser cet appui;<\/p>\n<p>b) pour les centrales nucl\u00e9aires de production d&rsquo;\u00e9nergie \u00e9lectrique, que si elles fournissent du courant \u00e9lectrique pour l&rsquo;appui r\u00e9gulier, important et direct d&rsquo;op\u00e9rations militaires, et si de telles attaques sont le seul moyen pratique de faire cesser cet appui;<\/p>\n<p>c) pour les autres objectifs militaires situ\u00e9s sur ces ouvrages ou installations ou \u00e0 proximit\u00e9, que s&rsquo;ils sont utilis\u00e9s pour l&rsquo;appui r\u00e9gulier, important et direct d&rsquo;op\u00e9rations militaires, et si de telles attaques sont le seul moyen pratique de faire cesser cet appui.<\/p>\n<p>3. Dans tous les cas, la population civile et les personnes civiles continuent de b\u00e9n\u00e9ficier de toutes les protections qui leur sont conf\u00e9r\u00e9es par le droit international, y compris des mesures de pr\u00e9caution pr\u00e9vues par l&rsquo;article 57. Si la protection cesse et si l&rsquo;un des ouvrages, l&rsquo;une des installations ou l&rsquo;un des objectifs militaires mentionn\u00e9s au paragraphe 1 est attaqu\u00e9, toutes les pr\u00e9cautions possibles dans la pratique doivent \u00eatre prises pour \u00e9viter que les forces dangereuses soient lib\u00e9r\u00e9es.<\/p>\n<p>4. Il est interdit de faire de l&rsquo;un des ouvrages, de l&rsquo;une des installations ou de l&rsquo;un des objectifs militaires mentionn\u00e9s au paragraphe 1 l&rsquo;objet de repr\u00e9sailles.<\/p>\n<p>5. Les Parties au conflit s&rsquo;efforceront de ne pas placer d&rsquo;objectifs militaires \u00e0 proximit\u00e9 des ouvrages ou installations mentionn\u00e9s au paragraphe 1. N\u00e9anmoins, les installations \u00e9tablies \u00e0 seule fin de d\u00e9fendre les ouvrages ou installations prot\u00e9g\u00e9s contre les attaques sont autoris\u00e9es et ne doivent pas \u00eatre elles-m\u00eames l&rsquo;objet d&rsquo;attaques, \u00e0 condition qu&rsquo;elles ne soient pas utilis\u00e9es dans les hostilit\u00e9s, sauf pour les actions d\u00e9fensives n\u00e9cessaires afin de r\u00e9pondre aux attaques contre les ouvrages ou installations prot\u00e9g\u00e9s et que leur armement soit limit\u00e9 aux armes qui ne peuvent servir qu&rsquo;\u00e0 repousser une action ennemie contre les ouvrages ou installations prot\u00e9g\u00e9s.<\/p>\n<p>6. Les Hautes Parties contractantes et les Parties au conflit sont instamment invit\u00e9es \u00e0 conclure entre elles d&rsquo;autres accords pour assurer une protection suppl\u00e9mentaire des biens contenant des forces dangereuses.<\/p>\n<p>7. Pour faciliter l&rsquo;identification des biens prot\u00e9g\u00e9s par le pr\u00e9sent article, les Parties au conflit pourront les marquer au moyen d&rsquo;un signe sp\u00e9cial consistant en un groupe de trois cercles orange vif dispos\u00e9s sur un m\u00eame axe comme il est sp\u00e9cifi\u00e9 \u00e0 l&rsquo;article 16 de l&rsquo;Annexe I au pr\u00e9sent Protocole. L&rsquo;absence d&rsquo;une telle signalisation ne dispense en rien les Parties au conflit des obligations d\u00e9coulant du pr\u00e9sent article.<\/p>\n<h5 id=\"chapter-iv---precautionary-measures\">Chapitre IV &#8211; Mesures de pr\u00e9caution<\/h5>\n<h6 id=\"article-57---precautions-in-attack\">Article 57 &#8211; Pr\u00e9cautions dans l&rsquo;attaque<\/h6>\n<p>1. Les op\u00e9rations militaires doivent \u00eatre conduites en veillant constamment \u00e0 \u00e9pargner la population civile, les personnes civiles et les biens de caract\u00e8re civil.<\/p>\n<p>2. En ce qui concerne les attaques, les pr\u00e9cautions suivantes doivent \u00eatre prises :<\/p>\n<p>a) ceux qui pr\u00e9parent ou d\u00e9cident une attaque doivent :<\/p>\n<p>i) faire tout ce qui est pratiquement possible pour v\u00e9rifier que les objectifs \u00e0 attaquer ne sont ni des personnes civiles, ni des biens de caract\u00e8re civil, et ne b\u00e9n\u00e9ficient pas d&rsquo;une protection sp\u00e9ciale, mais qu&rsquo;ils sont des objectifs militaires au sens du paragraphe 2 de l&rsquo;article 52, et que les dispositions du pr\u00e9sent Protocole n&rsquo;en interdisent pas l&rsquo;attaque;<\/p>\n<p>ii) prendre toutes les pr\u00e9cautions pratiquement possibles quant au choix des moyens et m\u00e9thodes d&rsquo;attaque en vue d&rsquo;\u00e9viter et, en tout cas, de r\u00e9duire au minimum les pertes en vies humaines dans la population civile, les blessures aux personnes civiles et les dommages aux biens de caract\u00e8re civil qui pourraient \u00eatre caus\u00e9s incidemment;<\/p>\n<p>iii) s&rsquo;abstenir de lancer une attaque dont on peut attendre qu&rsquo;elle cause incidemment des pertes en vies humaines dans la population civile, des blessures aux personnes civiles, des dommages aux biens de caract\u00e8re civil, ou une combinaison de ces pertes et dommages, qui seraient excessifs par rapport \u00e0 l&rsquo;avantage militaire concret et direct attendu;<\/p>\n<p>b) une attaque doit \u00eatre annul\u00e9e ou interrompue lorsqu&rsquo;il appara\u00eet que son objectif n&rsquo;est pas militaire ou qu&rsquo;il b\u00e9n\u00e9ficie d&rsquo;une protection sp\u00e9ciale ou que l&rsquo;on peut attendre qu&rsquo;elle cause incidemment des pertes en vies humaines dans la population civile, des blessures aux personnes civiles, des dommages aux biens de caract\u00e8re civil, ou une combinaison de ces pertes et dommages, qui seraient excessifs par rapport \u00e0 l&rsquo;avantage militaire concret et direct attendu;<\/p>\n<p>c) dans le cas d&rsquo;attaques pouvant affecter la population civile, un avertissement doit \u00eatre donn\u00e9 en temps utile et par des moyens efficaces, \u00e0 moins que les circonstances ne le permettent pas.<\/p>\n<p>3. Lorsque le choix est possible entre plusieurs objectifs militaires pour obtenir un avantage militaire \u00e9quivalent, ce choix doit porter sur l&rsquo;objectif dont on peut penser que l&rsquo;attaque pr\u00e9sente le moins de danger pour les personnes civiles ou pour les biens de caract\u00e8re civil.<\/p>\n<p>4. Dans la conduite des op\u00e9rations militaires sur mer ou dans les airs, chaque Partie au conflit doit prendre, conform\u00e9ment aux droits et aux devoirs qui d\u00e9coulent pour elle des r\u00e8gles du droit international applicable dans les conflits arm\u00e9s, toutes les pr\u00e9cautions raisonnables pour \u00e9viter des pertes en vies humaines dans la population civile et des dommages aux biens de caract\u00e8re civil.<\/p>\n<h6 id=\"article-58---precautions-against-the-effects-of-attacks\">Article 58 &#8211; Pr\u00e9cautions contre les effets des attaques<\/h6>\n<p>Dans toute la mesure de ce qui est pratiquement possible, les Parties au conflit :<\/p>\n<p>a) s&rsquo;efforceront, sans pr\u00e9judice de l&rsquo;article 49 de la IVe Convention, d&rsquo;\u00e9loigner du voisinage des objectifs militaires la population civile, les personnes civiles et les biens de caract\u00e8re civil soumis \u00e0 leur autorit\u00e9;<\/p>\n<p>b) \u00e9viteront de placer des objectifs militaires \u00e0 l&rsquo;int\u00e9rieur ou \u00e0 proximit\u00e9 des zones fortement peupl\u00e9es;<\/p>\n<p>c) prendront les autres pr\u00e9cautions n\u00e9cessaires pour prot\u00e9ger contre les dangers r\u00e9sultant des op\u00e9rations militaires la population civile, les personnes civiles et les biens de caract\u00e8re civil soumis \u00e0 leur autorit\u00e9.<\/p>\n<h5 id=\"chapter-v---localities-and-zones-under-special-protection\">Chapitre V &#8211; Localit\u00e9s et zones sous protection sp\u00e9ciale<\/h5>\n<h6 id=\"article-59---non-defended-localities\">Article 59 &#8211; Localit\u00e9s non d\u00e9fendues<\/h6>\n<p>1. Il est interdit aux Parties au conflit d&rsquo;attaquer, par quelque moyen que ce soit, des localit\u00e9s non d\u00e9fendues.<\/p>\n<p>2. Les autorit\u00e9s comp\u00e9tentes d&rsquo;une Partie au conflit pourront d\u00e9clarer localit\u00e9 non d\u00e9fendue tout lieu habit\u00e9 se trouvant \u00e0 proximit\u00e9 ou \u00e0 l&rsquo;int\u00e9rieur d&rsquo;une zone o\u00f9 les forces arm\u00e9es sont en contact et qui est ouvert \u00e0 l&rsquo;occupation par une Partie adverse. Une telle localit\u00e9 doit remplir les conditions suivantes :<\/p>\n<p>a) tous les combattants ainsi que les armes et le mat\u00e9riel militaire mobiles devront avoir \u00e9t\u00e9 \u00e9vacu\u00e9s;<\/p>\n<p>b) il ne doit pas \u00eatre fait un usage hostile des installations ou des \u00e9tablissements militaires fixes;<\/p>\n<p>c) les autorit\u00e9s et la population ne commettront pas d&rsquo;actes d&rsquo;hostilit\u00e9;<\/p>\n<p>d) aucune activit\u00e9 \u00e0 l&rsquo;appui d&rsquo;op\u00e9rations militaires ne doit \u00eatre entreprise.<\/p>\n<p>3. La pr\u00e9sence, dans cette localit\u00e9, de personnes sp\u00e9cialement prot\u00e9g\u00e9es par les Conventions et le pr\u00e9sent Protocole et de forces de police retenues \u00e0 seule fin de maintenir l&rsquo;ordre public n&rsquo;est pas contraire aux conditions pos\u00e9es au paragraphe 2.<\/p>\n<p>4. La d\u00e9claration faite en vertu du paragraphe 2 doit \u00eatre adress\u00e9e \u00e0 la Partie adverse et doit d\u00e9terminer et indiquer, de mani\u00e8re aussi pr\u00e9cise que possible, les limites de la localit\u00e9 non d\u00e9fendue. La Partie au conflit qui re\u00e7oit la d\u00e9claration doit en accuser r\u00e9ception et traiter la localit\u00e9 comme une localit\u00e9 non d\u00e9fendue \u00e0 moins que les conditions pos\u00e9es au paragraphe 2 ne soient pas effectivement remplies, auquel cas elle doit en informer sans d\u00e9lai la Partie qui aura fait la d\u00e9claration. M\u00eame lorsque les conditions pos\u00e9es au paragraphe 2 ne sont pas remplies, la localit\u00e9 continuera de b\u00e9n\u00e9ficier de la protection pr\u00e9vue par les autres dispositions du pr\u00e9sent Protocole et les autres r\u00e8gles du droit international applicable dans les conflits arm\u00e9s.<\/p>\n<p>5. Les Parties au conflit pourront se mettre d&rsquo;accord sur la cr\u00e9ation des localit\u00e9s non d\u00e9fendues, m\u00eame si ces localit\u00e9s ne remplissent pas les conditions pos\u00e9es au paragraphe 2. L&rsquo;accord devrait d\u00e9terminer et indiquer, de mani\u00e8re aussi pr\u00e9cise que possible, les limites de la localit\u00e9 non d\u00e9fendue; en cas de besoin, il peut fixer les modalit\u00e9s de contr\u00f4le.<\/p>\n<p>6. La Partie au pouvoir de laquelle se trouve une localit\u00e9 faisant l&rsquo;objet d&rsquo;un tel accord doit la marquer, dans la mesure du possible, par des signes, \u00e0 convenir avec l&rsquo;autre Partie, qui doivent \u00eatre plac\u00e9s en des endroits o\u00f9 ils seront clairement visibles, en particulier au p\u00e9rim\u00e8tre et aux limites de la localit\u00e9 et sur les routes principales.<\/p>\n<p>7. Une localit\u00e9 perd son statut de localit\u00e9 non d\u00e9fendue lorsqu&rsquo;elle ne remplit plus les conditions pos\u00e9es au paragraphe 2 ou dans l&rsquo;accord mentionn\u00e9 au paragraphe 5. Dans une telle \u00e9ventualit\u00e9, la localit\u00e9 continue de b\u00e9n\u00e9ficier de la protection pr\u00e9vue par les autres dispositions du pr\u00e9sent Protocole et les autres r\u00e8gles du droit international applicable dans les conflits arm\u00e9s.<\/p>\n<h6 id=\"article-60---demilitarized-zones\">Article 60 &#8211; Zones d\u00e9militaris\u00e9es<\/h6>\n<p>1. Il est interdit aux Parties au conflit d&rsquo;\u00e9tendre leurs op\u00e9rations militaires aux zones auxquelles elles auront conf\u00e9r\u00e9 par accord le statut de zone d\u00e9militaris\u00e9e si cette extension est contraire aux dispositions d&rsquo;un tel accord.<\/p>\n<p>2. Cet accord sera expr\u00e8s; il pourra \u00eatre conclu verbalement ou par \u00e9crit, directement ou par l&rsquo;entremise d&rsquo;une Puissance protectrice ou d&rsquo;une organisation humanitaire impartiale, et consister en des d\u00e9clarations r\u00e9ciproques et concordantes. Il pourra \u00eatre conclu aussi bien en temps de paix qu&rsquo;apr\u00e8s l&rsquo;ouverture des hostilit\u00e9s et devrait d\u00e9terminer et indiquer, de mani\u00e8re aussi pr\u00e9cise que possible, les limites de la zone d\u00e9militaris\u00e9e; il fixera, en cas de besoin, les modalit\u00e9s de contr\u00f4le.<\/p>\n<p>3. L&rsquo;objet d&rsquo;un tel accord sera normalement une zone remplissant les conditions suivantes :<\/p>\n<p>a) tous les combattants, ainsi que les armes et le mat\u00e9riel militaire mobiles, devront avoir \u00e9t\u00e9 \u00e9vacu\u00e9s;<\/p>\n<p>b) il ne sera pas fait un usage hostile des installations ou des \u00e9tablissements militaires fixes;<\/p>\n<p>c) les autorit\u00e9s et la population ne commettront pas d&rsquo;actes d&rsquo;hostilit\u00e9;<\/p>\n<p>d) toute activit\u00e9 li\u00e9e \u00e0 l&rsquo;effort militaire devra avoir cess\u00e9.<\/p>\n<p>Les Parties au conflit s&rsquo;entendront au sujet de l&rsquo;interpr\u00e9tation \u00e0 donner \u00e0 la condition pos\u00e9e \u00e0 l&rsquo;alin\u00e9a d et au sujet des personnes, autres que celles mentionn\u00e9es au paragraphe 4, \u00e0 admettre dans la zone d\u00e9militaris\u00e9e.<\/p>\n<p>4. La pr\u00e9sence, dans cette zone, de personnes sp\u00e9cialement prot\u00e9g\u00e9es par les Conventions et par le pr\u00e9sent Protocole et de forces de police retenues \u00e0 seule fin de maintenir l&rsquo;ordre public n&rsquo;est pas contraire aux conditions pos\u00e9es au paragraphe 3.<\/p>\n<p>5. La Partie au pouvoir de laquelle se trouve une telle zone doit la marquer, dans la mesure du possible, par des signes \u00e0 convenir avec l&rsquo;autre Partie, qui doivent \u00eatre plac\u00e9s en des endroits o\u00f9 ils seront clairement visibles, en particulier au p\u00e9rim\u00e8tre et aux limites de la zone et sur les routes principales.<\/p>\n<p>6. Si les combats se rapprochent d&rsquo;une zone d\u00e9militaris\u00e9e, et si les Parties au conflit ont conclu un accord \u00e0 cet effet, aucune d&rsquo;elles ne pourra utiliser cette zone \u00e0 des fins li\u00e9es \u00e0 la conduite des op\u00e9rations militaires, ni abroger unilat\u00e9ralement son statut.<\/p>\n<p>7. En cas de violation substantielle par l&rsquo;une des Parties au conflit des dispositions des paragraphes 3 ou 6, l&rsquo;autre Partie sera lib\u00e9r\u00e9e des obligations d\u00e9coulant de l&rsquo;accord conf\u00e9rant \u00e0 la zone le statut de zone d\u00e9militaris\u00e9e. Dans une telle \u00e9ventualit\u00e9, la zone perdra son statut, mais continuera de b\u00e9n\u00e9ficier de la protection pr\u00e9vue par les autres dispositions du pr\u00e9sent Protocole et les autres r\u00e8gles du droit international applicable dans les conflits arm\u00e9s.<\/p>\n<h5 id=\"chapter-vi---civil-defence\">Chapitre VI &#8211; Protection civile<\/h5>\n<h6 id=\"article-61---definitions-and-scope\">Article 61 &#8211; D\u00e9finition et champ d&rsquo;application<\/h6>\n<p>Aux fins du pr\u00e9sent Protocole :<\/p>\n<p>a) l&rsquo;expression \u00ab\u00a0protection civile\u00a0\u00bb s&rsquo;entend de l&rsquo;accomplissement de toutes les t\u00e2ches humanitaires, ou de plusieurs d&rsquo;entre elles, mentionn\u00e9es ci-apr\u00e8s, destin\u00e9es \u00e0 prot\u00e9ger la population civile contre les dangers des hostilit\u00e9s ou des catastrophes et \u00e0 l&rsquo;aider \u00e0 surmonter leurs effets imm\u00e9diats ainsi qu&rsquo;\u00e0 assurer les conditions n\u00e9cessaires \u00e0 sa survie. Ces t\u00e2ches sont les suivantes :<\/p>\n<p>i) service de l&rsquo;alerte;<\/p>\n<p>ii) \u00e9vacuation;<\/p>\n<p>iii) mise \u00e0 disposition et organisation d&rsquo;abris;<\/p>\n<p>iv) mise en oeuvre des mesures d&rsquo;obscurcissement;<\/p>\n<p>v) sauvetage;<\/p>\n<p>vi) services sanitaires y compris premiers secours et assistance religieuse;<\/p>\n<p>vii) lutte contre le feu;<\/p>\n<p>viii) rep\u00e9rage et signalisation des zones dangereuses;<\/p>\n<p>ix) d\u00e9contamination et autres mesures de protection analogues;<\/p>\n<p>x) h\u00e9bergement et approvisionnements d&rsquo;urgence;<\/p>\n<p>xi) aide en cas d&rsquo;urgence pour le r\u00e9tablissement et le maintien de l&rsquo;ordre dans les zones sinistr\u00e9es;<\/p>\n<p>xii) r\u00e9tablissement d&rsquo;urgence des services d&rsquo;utilit\u00e9 publique indispensables;<\/p>\n<p>xiii) services fun\u00e9raires d&rsquo;urgence;<\/p>\n<p>xiv) aide \u00e0 la sauvegarde des biens essentiels \u00e0 la survie;<\/p>\n<p>xv) activit\u00e9s compl\u00e9mentaires n\u00e9cessaires \u00e0 l&rsquo;accomplissement de l&rsquo;une quelconque des t\u00e2ches mentionn\u00e9es ci-dessus, comprenant la planification et l&rsquo;organisation mais ne s&rsquo;y limitant pas;<\/p>\n<p>b) l&rsquo;expression \u00ab\u00a0organismes de protection civile\u00a0\u00bb s&rsquo;entend des \u00e9tablissements et autres unit\u00e9s qui sont mis sur pied ou autoris\u00e9s par les autorit\u00e9s comp\u00e9tentes d&rsquo;une Partie au conflit pour accomplir l&rsquo;une quelconque des t\u00e2ches mentionn\u00e9es \u00e0 l&rsquo;alin\u00e9a a et qui sont exclusivement affect\u00e9s et utilis\u00e9s \u00e0 ces t\u00e2ches;<\/p>\n<p>c) le terme \u00ab\u00a0personnel\u00a0\u00bb des organismes de protection civile s&rsquo;entend des personnes qu&rsquo;une Partie au conflit affecte exclusivement \u00e0 l&rsquo;accomplissement des t\u00e2ches \u00e9num\u00e9r\u00e9es \u00e0 l&rsquo;alin\u00e9a a, y compris le personnel assign\u00e9 exclusivement \u00e0 l&rsquo;administration de ces organismes par l&rsquo;autorit\u00e9 comp\u00e9tente de cette Partie;<\/p>\n<p>d) le terme \u00ab\u00a0mat\u00e9riel\u00a0\u00bb des organismes de protection civile s&rsquo;entend de l&rsquo;\u00e9quipement, des approvisionnements et des moyens de transport que ces organismes utilisent pour accomplir les t\u00e2ches \u00e9num\u00e9r\u00e9es \u00e0 l&rsquo;alin\u00e9a a.<\/p>\n<h6 id=\"article-62---general-protection\">Article 62 &#8211; Protection g\u00e9n\u00e9rale<\/h6>\n<p>1. Les organismes civils de protection civile ainsi que leur personnel doivent \u00eatre respect\u00e9s et prot\u00e9g\u00e9s, conform\u00e9ment aux dispositions du pr\u00e9sent Protocole et notamment aux dispositions de la pr\u00e9sente Section. Ils ont le droit de s&rsquo;acquitter de leurs t\u00e2ches de protection civile, sauf en cas de n\u00e9cessit\u00e9 militaire imp\u00e9rieuse.<\/p>\n<p>2. Les dispositions du paragraphe 1 s&rsquo;appliquent \u00e9galement aux civils qui, bien que n&rsquo;appartenant pas \u00e0 des organismes civils de protection civile, r\u00e9pondent \u00e0 un appel des autorit\u00e9s comp\u00e9tentes et accomplissent sous leur contr\u00f4le des t\u00e2ches de protection civile.<\/p>\n<p>3. Les b\u00e2timents et le mat\u00e9riel utilis\u00e9s \u00e0 des fins de protection civile ainsi que les abris destin\u00e9s \u00e0 la population civile sont r\u00e9gis par l&rsquo;article 52. Les biens utilis\u00e9s \u00e0 des fins de protection civile ne peuvent \u00eatre ni d\u00e9truits ni d\u00e9tourn\u00e9s de leur destination, sauf par la Partie \u00e0 laquelle ils appartiennent.<\/p>\n<h6 id=\"article-63---civil-defence-in-occupied-territories\">Article 63 &#8211; Protection civile dans les territoires occup\u00e9s<\/h6>\n<p>1. Dans les territoires occup\u00e9s, les organismes civils de protection civile recevront des autorit\u00e9s les facilit\u00e9s n\u00e9cessaires \u00e0 l&rsquo;accomplissement de leurs t\u00e2ches. En aucune circonstance leur personnel ne doit \u00eatre astreint \u00e0 des activit\u00e9s qui entraveraient l&rsquo;ex\u00e9cution convenable de ces t\u00e2ches. La Puissance occupante ne pourra apporter \u00e0 la structure ou au personnel de ces organismes aucun changement qui pourrait porter pr\u00e9judice \u00e0 l&rsquo;accomplissement efficace de leur mission. Ces organismes civils de protection civile ne seront pas oblig\u00e9s d&rsquo;accorder priorit\u00e9 aux ressortissants ou aux int\u00e9r\u00eats de cette Puissance.<\/p>\n<p>2. La Puissance occupante ne doit pas obliger, contraindre ou inciter les organismes civils de protection civile \u00e0 accomplir leurs t\u00e2ches d&rsquo;une fa\u00e7on pr\u00e9judiciable en quoi que ce soit aux int\u00e9r\u00eats de la population civile.<\/p>\n<p>3. La Puissance occupante peut, pour des raisons de s\u00e9curit\u00e9, d\u00e9sarmer le personnel de protection civile.<\/p>\n<p>4. La Puissance occupante ne doit ni d\u00e9tourner de leur usage propre ni r\u00e9quisitionner les b\u00e2timents ou le mat\u00e9riel appartenant \u00e0 des organismes de protection civile ou utilis\u00e9s par ceux-ci lorsque ce d\u00e9tournement ou cette r\u00e9quisition portent pr\u00e9judice \u00e0 la population civile.<\/p>\n<p>5. La Puissance occupante peut r\u00e9quisitionner ou d\u00e9tourner ces moyens, \u00e0 condition de continuer \u00e0 observer la r\u00e8gle g\u00e9n\u00e9rale \u00e9tablie au paragraphe 4 et sous r\u00e9serve des conditions particuli\u00e8res suivantes :<\/p>\n<p>a) que les b\u00e2timents ou le mat\u00e9riel soient n\u00e9cessaires pour d&rsquo;autres besoins de la population civile; et<\/p>\n<p>b) que la r\u00e9quisition ou le d\u00e9tournement ne dure qu&rsquo;autant que cette n\u00e9cessit\u00e9 existe.<\/p>\n<p>6. La Puissance occupante ne doit ni d\u00e9tourner ni r\u00e9quisitionner les abris mis \u00e0 la disposition de la population civile ou n\u00e9cessaires aux besoins de cette population.<\/p>\n<h6 id=\"article-64---civilian-civil-defence-organizations\">Article 64 &#8211; Organismes civils de protection civile d&rsquo;Etats neutres ou d&rsquo;autres Etats non Parties au conflit et organismes internationaux de coordination<\/h6>\n<p>1. Les articles 62, 63, 65 et 66 s&rsquo;appliquent \u00e9galement au personnel et au mat\u00e9riel des organismes civils de protection civile d&rsquo;Etats neutres ou d&rsquo;autres Etats non Parties au conflit qui accomplissent des t\u00e2ches de protection civile \u00e9num\u00e9r\u00e9es \u00e0 l&rsquo;article 61 sur le territoire d&rsquo;une Partie au conflit, avec le consentement et sous le contr\u00f4le de cette Partie. Notification de cette assistance sera donn\u00e9e d\u00e8s que possible \u00e0 toute Partie adverse int\u00e9ress\u00e9e. En aucune circonstance cette activit\u00e9 ne sera consid\u00e9r\u00e9e comme une ing\u00e9rence dans le conflit. Toutefois, cette activit\u00e9 devrait \u00eatre exerc\u00e9e en tenant d\u00fbment compte des int\u00e9r\u00eats en mati\u00e8re de s\u00e9curit\u00e9 des Parties au conflit int\u00e9ress\u00e9es.<\/p>\n<p>2. Les Parties au conflit qui re\u00e7oivent l&rsquo;assistance mentionn\u00e9e au paragraphe 1 et les Hautes Parties contractantes qui l&rsquo;accordent devraient faciliter, quand il y a lieu, la coordination internationale de ces actions de protection civile. Dans ce cas, les dispositions du pr\u00e9sent Chapitre s&rsquo;appliquent aux organismes internationaux comp\u00e9tents.<\/p>\n<p>3. Dans les territoires occup\u00e9s, la Puissance occupante ne peut exclure ou restreindre les activit\u00e9s des organismes civils de protection civile d&rsquo;Etats neutres ou d&rsquo;autres Etats non Parties au conflit et d&rsquo;organismes internationaux de coordination que si elle peut assurer l&rsquo;accomplissement ad\u00e9quat des t\u00e2ches de protection civile par ses propres moyens ou par ceux du territoire occup\u00e9.<\/p>\n<h6 id=\"article-65---cessation-of-protection\">Article 65 &#8211; Cessation de la protection<\/h6>\n<p>1. La protection \u00e0 laquelle ont droit les organismes civils de protection civile, leur personnel, leurs b\u00e2timents, leurs abris et leur mat\u00e9riel ne pourra cesser que s&rsquo;ils commettent ou sont utilis\u00e9s pour commettre, en dehors de leurs t\u00e2ches propres, des actes nuisibles \u00e0 l&rsquo;ennemi. Toutefois, la protection cessera seulement apr\u00e8s qu&rsquo;une sommation fixant, chaque fois qu&rsquo;il y aura lieu, un d\u00e9lai raisonnable sera demeur\u00e9e sans effet.<\/p>\n<p>2. Ne seront pas consid\u00e9r\u00e9s comme actes nuisibles \u00e0 l&rsquo;ennemi :<\/p>\n<p>a) le fait d&rsquo;ex\u00e9cuter des t\u00e2ches de protection civile sous la direction ou la surveillance d&rsquo;autorit\u00e9s militaires;<\/p>\n<p>b) le fait que le personnel civil de protection civile coop\u00e8re avec du personnel militaire dans l&rsquo;accomplissement de t\u00e2ches de protection civile, ou que des militaires soient attach\u00e9s \u00e0 des organismes civils de protection civile;<\/p>\n<p>c) le fait que l&rsquo;accomplissement des t\u00e2ches de protection civile puisse incidemment profiter \u00e0 des victimes militaires, en particulier \u00e0 celles qui sont hors de combat.<\/p>\n<p>3. Ne sera pas consid\u00e9r\u00e9 non plus comme acte nuisible \u00e0 l&rsquo;ennemi le port d&rsquo;armes l\u00e9g\u00e8res individuelles par le personnel civil de protection civile, en vue du maintien de l&rsquo;ordre ou pour sa propre protection. Toutefois, dans les zones o\u00f9 des combats terrestres se d\u00e9roulent ou semblent devoir se d\u00e9rouler, les Parties au conflit prendront les dispositions appropri\u00e9es pour limiter ces armes aux armes de poing, telles que les pistolets ou revolvers, afin de faciliter la distinction entre le personnel de protection civile et les combattants. M\u00eame si le personnel de protection civile porte d&rsquo;autres armes l\u00e9g\u00e8res individuelles dans ces zones, il doit \u00eatre respect\u00e9 et prot\u00e9g\u00e9 d\u00e8s qu&rsquo;il aura \u00e9t\u00e9 reconnu comme tel.<\/p>\n<p>4. Le fait pour les organismes civils de protection civile d&rsquo;\u00eatre organis\u00e9s sur le mod\u00e8le militaire ainsi que le caract\u00e8re obligatoire du service exig\u00e9 de leur personnel ne les privera pas non plus de la protection conf\u00e9r\u00e9e par le pr\u00e9sent Chapitre.<\/p>\n<h6 id=\"article-66---identification\">Article 66 &#8211; Identification<\/h6>\n<p>1. Chaque Partie au conflit doit s&rsquo;efforcer de faire en sorte que ses organismes de protection civile, leur personnel, leurs b\u00e2timents et leur mat\u00e9riel puissent \u00eatre identifi\u00e9s lorsqu&rsquo;ils sont exclusivement consacr\u00e9s \u00e0 l&rsquo;accomplissement de t\u00e2ches de protection civile. Les abris mis \u00e0 la disposition de la population civile devraient \u00eatre identifiables d&rsquo;une mani\u00e8re analogue.<\/p>\n<p>2. Chaque Partie au conflit doit s&rsquo;efforcer \u00e9galement d&rsquo;adopter et de mettre en oeuvre des m\u00e9thodes et des proc\u00e9dures qui permettront d&rsquo;identifier les abris civils, ainsi que le personnel, les b\u00e2timents et le mat\u00e9riel de protection civile qui portent ou arborent le signe distinctif international de la protection civile.<\/p>\n<p>3. Dans les territoires occup\u00e9s et dans les zones o\u00f9 des combats se d\u00e9roulent ou semblent devoir se d\u00e9rouler, le personnel civil de protection civile se fera en r\u00e8gle g\u00e9n\u00e9rale reconna\u00eetre au moyen du signe distinctif international de la protection civile et d&rsquo;une carte d&rsquo;identit\u00e9 attestant son statut.<\/p>\n<p>4. Le signe distinctif international de la protection civile consiste en un triangle \u00e9quilat\u00e9ral bleu sur fond orange quand il est utilis\u00e9 pour la protection des organismes de protection civile, de leurs b\u00e2timents, de leur personnel et de leur mat\u00e9riel ou pour la protection des abris civils.<\/p>\n<p>5. En plus du signe distinctif, les Parties au conflit pourront se mettre d&rsquo;accord sur l&rsquo;utilisation de signaux distinctifs \u00e0 des fins d&rsquo;identification des services de protection civile.<\/p>\n<p>6. L&rsquo;application des dispositions des paragraphes 1 \u00e0 4 est r\u00e9gie par le Chapitre V de l&rsquo;Annexe I au pr\u00e9sent Protocole.<\/p>\n<p>7. En temps de paix, le signe d\u00e9crit au paragraphe 4 peut, avec le consentement des autorit\u00e9s nationales comp\u00e9tentes, \u00eatre utilis\u00e9 \u00e0 des fins d&rsquo;identification des services de protection civile.<\/p>\n<p>8. Les Hautes Parties contractantes et les Parties au conflit prendront les mesures n\u00e9cessaires pour contr\u00f4ler l&rsquo;usage du signe distinctif international de la protection civile et pour en pr\u00e9venir et r\u00e9primer l&rsquo;usage abusif.<\/p>\n<p>9. L&rsquo;identification du personnel sanitaire et religieux, des unit\u00e9s sanitaires et des moyens de transport sanitaire de la protection civile est \u00e9galement r\u00e9gie par l&rsquo;article 18.<\/p>\n<h6 id=\"article-67---members-of-the-armed-forces-and-military-units-assigned-to-civil-defence-organizations\">Article 67 &#8211; Membres des forces arm\u00e9es et unit\u00e9s militaires affect\u00e9s aux organismes de protection civile<\/h6>\n<p>1. Les membres des forces arm\u00e9es et les unit\u00e9s militaires affect\u00e9s aux organismes de protection civile seront respect\u00e9s et prot\u00e9g\u00e9s, \u00e0 condition :<\/p>\n<p>a) que ce personnel et ces unit\u00e9s soient affect\u00e9s en permanence \u00e0 l&rsquo;accomplissement de toute t\u00e2che vis\u00e9e \u00e0 l&rsquo;article 61 et s&rsquo;y consacrent exclusivement;<\/p>\n<p>b) que, s&rsquo;il a re\u00e7u cette affectation, ce personnel n&rsquo;accomplisse pas d&rsquo;autres t\u00e2ches militaires pendant le conflit;<\/p>\n<p>c) que ce personnel se distingue nettement des autres membres des forces arm\u00e9es en portant bien en vue le signe distinctif international de la protection civile, qui doit \u00eatre aussi grand qu&rsquo;il conviendra, et que ce personnel soit muni de la carte d&rsquo;identit\u00e9 vis\u00e9e au Chapitre V de l&rsquo;Annexe I au pr\u00e9sent Protocole, attestant son statut;<\/p>\n<p>d) que ce personnel et ces unit\u00e9s soient dot\u00e9s seulement d&rsquo;armes l\u00e9g\u00e8res individuelles en vue du maintien de l&rsquo;ordre ou pour leur propre d\u00e9fense. Les dispositions de l&rsquo;article 65, paragraphe 3, s&rsquo;appliqueront \u00e9galement dans ce cas;<\/p>\n<p>e) que ce personnel ne participe pas directement aux hostilit\u00e9s et qu&rsquo;il ne commette pas, ou ne soit pas utilis\u00e9 pour commettre, en dehors de ses t\u00e2ches de protection civile, des actes nuisibles \u00e0 la Partie adverse;<\/p>\n<p>f) que ce personnel et ces unit\u00e9s remplissent leurs t\u00e2ches de protection civile uniquement dans le territoire national de leur Partie.<\/p>\n<p>La non-observation des conditions \u00e9nonc\u00e9es \u00e0 l&rsquo;alin\u00e9a e par tout membre des forces arm\u00e9es qui est li\u00e9 par les conditions prescrites aux alin\u00e9as a et b est interdite.<\/p>\n<p>2. Les membres du personnel militaire servant dans les organismes de protection civile seront, s&rsquo;ils tombent au pouvoir d&rsquo;une Partie adverse, des prisonniers de guerre. En territoire occup\u00e9 ils peuvent, mais dans le seul int\u00e9r\u00eat de la population civile de ce territoire, \u00eatre employ\u00e9s \u00e0 des t\u00e2ches de protection civile dans la mesure o\u00f9 il en est besoin, \u00e0 condition toutefois, si ce travail est dangereux, qu&rsquo;ils soient volontaires.<\/p>\n<p>3. Les b\u00e2timents et les \u00e9l\u00e9ments importants du mat\u00e9riel et des moyens de transport des unit\u00e9s militaires affect\u00e9es aux organismes de protection civile doivent \u00eatre marqu\u00e9s nettement du signe distinctif international de la protection civile. Ce signe doit \u00eatre aussi grand qu&rsquo;il conviendra.<\/p>\n<p>4. Les b\u00e2timents et le mat\u00e9riel des unit\u00e9s militaires affect\u00e9es en permanence aux organismes de protection civile et affect\u00e9s exclusivement \u00e0 l&rsquo;accomplissement des t\u00e2ches de protection civile, s&rsquo;ils tombent au pouvoir d&rsquo;une Partie adverse, resteront r\u00e9gis par le droit de la guerre. Cependant, ils ne peuvent pas \u00eatre d\u00e9tourn\u00e9s de leur destination tant qu&rsquo;ils sont n\u00e9cessaires \u00e0 l&rsquo;accomplissement de t\u00e2ches de protection civile, sauf en cas de n\u00e9cessit\u00e9 militaire imp\u00e9rieuse, \u00e0 moins que des dispositions pr\u00e9alables n&rsquo;aient \u00e9t\u00e9 prises pour pourvoir de fa\u00e7on ad\u00e9quate aux besoins de la population civile.<\/p>\n<h4 id=\"section-ii---relief-in-favour-of-the-civilian-population\">Section II &#8211; Secours en faveur de la population civile<\/h4>\n<h6 id=\"article-68---field-of-application\">Article 68 &#8211; Champ d&rsquo;application<\/h6>\n<p>Les dispositions de la pr\u00e9sente Section s&rsquo;appliquent \u00e0 la population civile au sens du pr\u00e9sent Protocole et compl\u00e8tent les articles 23, 55, 59, 60, 61 et 62 et les autres dispositions pertinentes de la IVe Convention.<\/p>\n<h6 id=\"article-69---basic-needs-in-occupied-territories\">Article 69 &#8211; Besoins essentiels dans les territoires occup\u00e9s<\/h6>\n<p>1. En plus des obligations \u00e9num\u00e9r\u00e9es \u00e0 l&rsquo;article 55 de la IVe Convention relatives \u00e0 l&rsquo;approvisionnement en vivres et en m\u00e9dicaments, la Puissance occupante assurera aussi dans toute la mesure de ses moyens et sans aucune distinction de caract\u00e8re d\u00e9favorable la fourniture de v\u00eatements, de mat\u00e9riel de couchage, de logements d&rsquo;urgence, des autres approvisionnements essentiels \u00e0 la survie de la population civile du territoire occup\u00e9 et des objets n\u00e9cessaires au culte.<\/p>\n<p>2. Les actions de secours en faveur de la population civile du territoire occup\u00e9 sont r\u00e9gies par les articles 59, 60, 61, 62, 108, 109, 110 et 111 de la IVe Convention, ainsi que par l&rsquo;article 71 du pr\u00e9sent Protocole, et seront men\u00e9es sans d\u00e9lai.<\/p>\n<h6 id=\"article-70---relief-actions\">Article 70 &#8211; Actions de secours<\/h6>\n<p>1. Lorsque la population civile d&rsquo;un territoire sous le contr\u00f4le d&rsquo;une Partie au conflit, autre qu&rsquo;un territoire occup\u00e9, est insuffisamment approvisionn\u00e9e en mat\u00e9riel et denr\u00e9es mentionn\u00e9s \u00e0 l&rsquo;article 69, des actions de secours de caract\u00e8re humanitaire et impartial et conduites sans aucune distinction de caract\u00e8re d\u00e9favorable seront entreprises, sous r\u00e9serve de l&rsquo;agr\u00e9ment des Parties concern\u00e9es par ces actions de secours. Les offres de secours remplissant les conditions ci-dessus ne seront consid\u00e9r\u00e9es ni comme une ing\u00e9rence dans le conflit arm\u00e9, ni comme des actes hostiles. Lors de la distribution de ces envois de secours, priorit\u00e9 sera donn\u00e9e aux personnes qui, tels les enfants, les femmes enceintes ou en couches et les m\u00e8res qui allaitent, doivent faire l&rsquo;objet, selon la IVe Convention ou le pr\u00e9sent Protocole, d&rsquo;un traitement de faveur ou d&rsquo;une protection particuli\u00e8re.<\/p>\n<p>2. Les Parties au conflit et chaque Haute Partie contractante autoriseront et faciliteront le passage rapide et sans encombre de tous les envois, des \u00e9quipements et du personnel de secours fournis conform\u00e9ment aux prescriptions de la pr\u00e9sente Section, m\u00eame si cette aide est destin\u00e9e \u00e0 la population civile de la Partie adverse.<\/p>\n<p>3. Les Parties au conflit et chaque Haute Partie contractante autorisant le passage de secours, d&rsquo;\u00e9quipement et de personnel, conform\u00e9ment au paragraphe 2:<\/p>\n<p>a) disposeront du droit de prescrire les r\u00e9glementations techniques, y compris les v\u00e9rifications, auxquelles un tel passage est subordonn\u00e9;<\/p>\n<p>b) pourront subordonner leur autorisation \u00e0 la condition que la distribution de l&rsquo;assistance soit effectu\u00e9e sous le contr\u00f4le sur place d&rsquo;une Puissance protectrice;<\/p>\n<p>c) ne d\u00e9tourneront en aucune mani\u00e8re les envois de secours de leur destination ni n&rsquo;en retarderont l&rsquo;acheminement, sauf dans des cas de n\u00e9cessit\u00e9 urgente, dans l&rsquo;int\u00e9r\u00eat de la population civile concern\u00e9e.<\/p>\n<p>4. Les Parties au conflit assureront la protection des envois de secours et en faciliteront la distribution rapide.<\/p>\n<p>5. Les Parties au conflit et chaque Haute Partie contractante int\u00e9ress\u00e9e encourageront et faciliteront une coordination internationale efficace des actions de secours mentionn\u00e9es au paragraphe 1.<\/p>\n<h6 id=\"article-71---personnel-participating-in-relief-actions\">Article 71 &#8211; Personnel participant aux actions de secours<\/h6>\n<p>1. En cas de n\u00e9cessit\u00e9 l&rsquo;aide fournie dans une action de secours pourra comprendre du personnel de secours, notamment pour le transport et la distribution des envois de secours; la participation de ce personnel sera soumise \u00e0 l&rsquo;agr\u00e9ment de la Partie sur le territoire de laquelle il exercera son activit\u00e9.<\/p>\n<p>2. Ce personnel sera respect\u00e9 et prot\u00e9g\u00e9.<\/p>\n<p>3. Chaque Partie qui re\u00e7oit des envois de secours assistera, dans toute la mesure du possible, le personnel mentionn\u00e9 au paragraphe 1 dans l&rsquo;accomplissement de sa mission de secours. Les activit\u00e9s de ce personnel de secours ne peuvent \u00eatre limit\u00e9es et ses d\u00e9placements temporairement restreints qu&rsquo;en cas de n\u00e9cessit\u00e9 militaire imp\u00e9rieuse.<\/p>\n<p>4. En aucune circonstance le personnel de secours ne devra outrepasser les limites de sa mission aux termes du pr\u00e9sent Protocole. Il doit en particulier tenir compte des exigences de s\u00e9curit\u00e9 de la Partie sur le territoire de laquelle il exerce ses fonctions. Il peut \u00eatre mis fin \u00e0 la mission de tout membre du personnel de secours qui ne respecterait pas ces conditions.<\/p>\n<h4 id=\"section-iii---treatment-of-persons-in-the-power-of-a-party-to-the-conflict\">Section III &#8211; Traitement des personnes au pouvoir d&rsquo;une Partie au conflit<\/h4>\n<h5 id=\"chapter-1---field-of-application-and-protection-of-persons-and-objects\">Chapitre I &#8211; Champ d&rsquo;application et protection des personnes et des biens<\/h5>\n<h6 id=\"article-72---field-of-application\">Article 72 &#8211; Champ d&rsquo;application<\/h6>\n<p>Les dispositions de la pr\u00e9sente Section compl\u00e8tent les normes relatives \u00e0 la protection humanitaire des personnes civiles et des biens de caract\u00e8re civil au pouvoir d&rsquo;une Partie au conflit \u00e9nonc\u00e9es dans la IVe Convention, en particulier aux Titres I et III, ainsi que les autres normes applicables du droit international qui r\u00e9gissent la protection des droits fondamentaux de l&rsquo;homme pendant un conflit arm\u00e9 de caract\u00e8re international.<\/p>\n<h6 id=\"article-73---refugees-and-stateless-persons\">Article 73 &#8211; R\u00e9fugi\u00e9s et apatrides<\/h6>\n<p>Les personnes qui, avant le d\u00e9but des hostilit\u00e9s, sont consid\u00e9r\u00e9es comme apatrides ou r\u00e9fugi\u00e9s au sens des instruments internationaux pertinents accept\u00e9s par les Parties int\u00e9ress\u00e9es ou de la l\u00e9gislation nationale de l&rsquo;Etat d&rsquo;accueil ou de r\u00e9sidence, seront, en toutes circonstances et sans aucune distinction de caract\u00e8re d\u00e9favorable, des personnes prot\u00e9g\u00e9es au sens des Titres I et III de la IVe Convention.<\/p>\n<h6 id=\"article-74---reunion-of-dispersed-families\">Article 74 &#8211; Regroupement des familles dispers\u00e9es<\/h6>\n<p>Les Hautes Parties contractantes et les Parties au conflit faciliteront dans toute la mesure du possible le regroupement des familles dispers\u00e9es en raison de conflits arm\u00e9s et encourageront notamment l&rsquo;action des organisations humanitaires qui se consacrent \u00e0 cette t\u00e2che conform\u00e9ment aux dispositions des Conventions et du pr\u00e9sent Protocole et conform\u00e9ment \u00e0 leurs r\u00e8gles de s\u00e9curit\u00e9 respectives.<\/p>\n<h6 id=\"article-75---fundamental-guarantees\">Article 75 &#8211; Garanties fondamentales<\/h6>\n<p>1. Dans la mesure o\u00f9 elles sont affect\u00e9es par une situation vis\u00e9e \u00e0 l&rsquo;article premier du pr\u00e9sent Protocole, les personnes qui sont au pouvoir d&rsquo;une Partie au conflit et qui ne b\u00e9n\u00e9ficient pas d&rsquo;un traitement plus favorable en vertu des Conventions et du pr\u00e9sent Protocole seront trait\u00e9es avec humanit\u00e9 en toutes circonstances et b\u00e9n\u00e9ficieront au moins des protections pr\u00e9vues par le pr\u00e9sent article sans aucune distinction de caract\u00e8re d\u00e9favorable fond\u00e9e sur la race, la couleur, le sexe, la langue, la religion ou la croyance, les opinions politiques ou autres, l&rsquo;origine nationale ou sociale, la fortune, la naissance ou une autre situation, ou tout autre crit\u00e8re analogue. Chacune des Parties respectera la personne, l&rsquo;honneur, les convictions et les pratiques religieuses de toutes ces personnes.<\/p>\n<p>2. Sont et demeureront prohib\u00e9s en tout temps et en tout lieu les actes suivants, qu&rsquo;ils soient commis par des agents civils ou militaires :<\/p>\n<p>a) les atteintes port\u00e9es \u00e0 la vie, \u00e0 la sant\u00e9 et au bien-\u00eatre physique ou mental des personnes, notamment :<\/p>\n<p>i) le meurtre;<\/p>\n<p>ii) la torture sous toutes ses formes, qu&rsquo;elle soit physique ou mentale;<\/p>\n<p>iii) les peines corporelles; et<\/p>\n<p>iv) les mutilations;<\/p>\n<p>b) les atteintes \u00e0 la dignit\u00e9 de la personne, notamment les traitements humiliants et d\u00e9gradants, la prostitution forc\u00e9e et toute forme d&rsquo;attentat \u00e0 la pudeur;<\/p>\n<p>c) la prise d&rsquo;otages;<\/p>\n<p>d) les peines collectives; et<\/p>\n<p>e) la menace de commettre l&rsquo;un quelconque des actes pr\u00e9cit\u00e9s.<\/p>\n<p>3. Toute personne arr\u00eat\u00e9e, d\u00e9tenue ou intern\u00e9e pour des actes en relation avec le conflit arm\u00e9 sera inform\u00e9e sans retard, dans une langue qu&rsquo;elle comprend, des raisons pour lesquelles ces mesures ont \u00e9t\u00e9 prises. Sauf en cas d&rsquo;arrestation ou de d\u00e9tention du chef d&rsquo;une infraction p\u00e9nale, cette personne sera lib\u00e9r\u00e9e dans les plus brefs d\u00e9lais possibles et, en tout cas, d\u00e8s que les circonstances justifiant l&rsquo;arrestation, la d\u00e9tention ou l&rsquo;internement auront cess\u00e9 d&rsquo;exister.<\/p>\n<p>4. Aucune condamnation ne sera prononc\u00e9e ni aucune peine ex\u00e9cut\u00e9e \u00e0 l&rsquo;encontre d&rsquo;une personne reconnue coupable d&rsquo;une infraction p\u00e9nale commise en relation avec le conflit arm\u00e9 si ce n&rsquo;est en vertu d&rsquo;un jugement pr\u00e9alable rendu par un tribunal impartial et r\u00e9guli\u00e8rement constitu\u00e9, qui se conforme aux principes g\u00e9n\u00e9ralement reconnus d&rsquo;une proc\u00e9dure judiciaire r\u00e9guli\u00e8re comprenant les garanties suivantes :<\/p>\n<p>a) la proc\u00e9dure disposera que tout pr\u00e9venu doit \u00eatre inform\u00e9 sans d\u00e9lai des d\u00e9tails de l&rsquo;infraction qui lui est imput\u00e9e et assurera au pr\u00e9venu avant et pendant son proc\u00e8s tous les droits et moyens n\u00e9cessaires \u00e0 sa d\u00e9fense;<\/p>\n<p>b) nul ne peut \u00eatre puni pour une infraction si ce n&rsquo;est sur la base d&rsquo;une responsabilit\u00e9 p\u00e9nale individuelle;<\/p>\n<p>c) nul ne sera accus\u00e9 ou condamn\u00e9 pour des actions ou omissions qui ne constituaient pas un acte d\u00e9lictueux d&rsquo;apr\u00e8s le droit national ou international qui lui \u00e9tait applicable au moment o\u00f9 elles ont \u00e9t\u00e9 commises. De m\u00eame, il ne sera inflig\u00e9 aucune peine plus forte que celle qui \u00e9tait applicable au moment o\u00f9 l&rsquo;infraction a \u00e9t\u00e9 commise. Si, post\u00e9rieurement \u00e0 cette infraction, la loi pr\u00e9voit l&rsquo;application d&rsquo;une peine plus l\u00e9g\u00e8re, le d\u00e9linquant doit en b\u00e9n\u00e9ficier;<\/p>\n<p>d) toute personne accus\u00e9e d&rsquo;une infraction est pr\u00e9sum\u00e9e innocente jusqu&rsquo;\u00e0 ce que sa culpabilit\u00e9 ait \u00e9t\u00e9 l\u00e9galement \u00e9tablie;<\/p>\n<p>e) toute personne accus\u00e9e d&rsquo;une infraction a le droit d&rsquo;\u00eatre jug\u00e9e en sa pr\u00e9sence;<\/p>\n<p>f) nul ne peut \u00eatre forc\u00e9 de t\u00e9moigner contre lui-m\u00eame ou de s&rsquo;avouer coupable;<\/p>\n<p>g) toute personne accus\u00e9e d&rsquo;une infraction a le droit d&rsquo;interroger ou de faire interroger les t\u00e9moins \u00e0 charge et d&rsquo;obtenir la comparution et l&rsquo;interrogatoire des t\u00e9moins \u00e0 d\u00e9charge dans les m\u00eames conditions que les t\u00e9moins \u00e0 charge;<\/p>\n<p>h) aucune personne ne peut \u00eatre poursuivie ou punie par la m\u00eame Partie pour une infraction ayant d\u00e9j\u00e0 fait l&rsquo;objet d&rsquo;un jugement d\u00e9finitif d&rsquo;acquittement ou de condamnation rendu conform\u00e9ment au m\u00eame droit et \u00e0 la m\u00eame proc\u00e9dure judiciaire;<\/p>\n<p>i) toute personne accus\u00e9e d&rsquo;une infraction a droit \u00e0 ce que le jugement soit rendu publiquement;<\/p>\n<p>j) toute personne condamn\u00e9e sera inform\u00e9e, au moment de sa condamnation, de ses droits de recours judiciaires et autres ainsi que des d\u00e9lais dans lesquels ils doivent \u00eatre exerc\u00e9s.<\/p>\n<p>5. Les femmes priv\u00e9es de libert\u00e9 pour des motifs en relation avec le conflit arm\u00e9 seront gard\u00e9es dans des locaux s\u00e9par\u00e9s de ceux des hommes. Elles seront plac\u00e9es sous la surveillance imm\u00e9diate de femmes. Toutefois, si des familles sont arr\u00eat\u00e9es, d\u00e9tenues ou intern\u00e9es, l&rsquo;unit\u00e9 de ces familles sera pr\u00e9serv\u00e9e autant que possible pour leur logement.<\/p>\n<p>6. Les personnes arr\u00eat\u00e9es, d\u00e9tenues ou intern\u00e9es pour des motifs en relation avec le conflit arm\u00e9 b\u00e9n\u00e9ficieront des protections accord\u00e9es par le pr\u00e9sent article jusqu&rsquo;\u00e0 leur lib\u00e9ration d\u00e9finitive, leur rapatriement ou leur \u00e9tablissement, m\u00eame apr\u00e8s la fin du conflit arm\u00e9.<\/p>\n<p>7. Pour que ne subsiste aucun doute en ce qui concerne la poursuite et le jugement des personnes accus\u00e9es de crimes de guerre ou de crimes contre l&rsquo;humanit\u00e9, les principes suivants seront appliqu\u00e9s :<\/p>\n<p>a) les personnes qui sont accus\u00e9es de tels crimes devraient \u00eatre d\u00e9f\u00e9r\u00e9es aux fins de poursuite et de jugement conform\u00e9ment aux r\u00e8gles du droit international applicable; et<\/p>\n<p>b) toute personne qui ne b\u00e9n\u00e9ficie pas d&rsquo;un traitement plus favorable en vertu des Conventions ou du pr\u00e9sent Protocole se verra accorder le traitement pr\u00e9vu par le pr\u00e9sent article, que les crimes dont elle est accus\u00e9e constituent ou non des infractions graves aux Conventions ou au pr\u00e9sent Protocole.<\/p>\n<p>8. Aucune disposition du pr\u00e9sent article ne peut \u00eatre interpr\u00e9t\u00e9e comme limitant ou portant atteinte \u00e0 toute autre disposition plus favorable accordant, en vertu des r\u00e8gles du droit international applicable, une plus grande protection aux personnes couvertes par le paragraphe 1.<\/p>\n<h5 id=\"chapter-ii---measures-in-favour-of-women-and-children\">Chapitre II &#8211; Mesures en faveur des femmes et des enfants<\/h5>\n<h6 id=\"article-76---protection-of-women\">Article 76 &#8211; Protection des femmes<\/h6>\n<p>1. Les femmes doivent faire l&rsquo;objet d&rsquo;un respect particulier et seront prot\u00e9g\u00e9es, notamment contre le viol, la contrainte \u00e0 la prostitution et toute autre forme d&rsquo;attentat \u00e0 la pudeur.<\/p>\n<p>2. Les cas des femmes enceintes et des m\u00e8res d&rsquo;enfants en bas \u00e2ge d\u00e9pendant d&rsquo;elles qui sont arr\u00eat\u00e9es, d\u00e9tenues ou intern\u00e9es pour des raisons li\u00e9es au conflit arm\u00e9 seront examin\u00e9s en priorit\u00e9 absolue.<\/p>\n<p>3. Dans toute la mesure du possible, les Parties au conflit s&rsquo;efforceront d&rsquo;\u00e9viter que la peine de mort soit prononc\u00e9e contre les femmes enceintes ou les m\u00e8res d&rsquo;enfants en bas \u00e2ge d\u00e9pendant d&rsquo;elles pour une infraction commise en relation avec le conflit arm\u00e9. Une condamnation \u00e0 mort contre ces femmes pour une telle infraction ne sera pas ex\u00e9cut\u00e9e.<\/p>\n<h6 id=\"article-77---protection-of-children\">Article 77 &#8211; Protection des enfants<\/h6>\n<p>1. Les enfants doivent faire l&rsquo;objet d&rsquo;un respect particulier et doivent \u00eatre prot\u00e9g\u00e9s contre toute forme d&rsquo;attentat \u00e0 la pudeur. Les Parties au conflit leur apporteront les soins et l&rsquo;aide dont ils ont besoin du fait de leur \u00e2ge ou pour toute autre raison.<\/p>\n<p>2. Les Parties au conflit prendront toutes les mesures possibles dans la pratique pour que les enfants de moins de quinze ans ne participent pas directement aux hostilit\u00e9s, notamment en s&rsquo;abstenant de les recruter dans leurs forces arm\u00e9es. Lorsqu&rsquo;elles incorporent des personnes de plus de quinze ans mais de moins de dix-huit ans, les Parties au conflit s&rsquo;efforceront de donner la priorit\u00e9 aux plus \u00e2g\u00e9es.<\/p>\n<p>3. Si, dans des cas exceptionnels et malgr\u00e9 les dispositions du paragraphe 2, des enfants qui n&rsquo;ont pas quinze ans r\u00e9volus participent directement aux hostilit\u00e9s et tombent au pouvoir d&rsquo;une Partie adverse, ils continueront \u00e0 b\u00e9n\u00e9ficier de la protection sp\u00e9ciale accord\u00e9e par le pr\u00e9sent article, qu&rsquo;ils soient ou non prisonniers de guerre.<\/p>\n<p>4. S&rsquo;ils sont arr\u00eat\u00e9s, d\u00e9tenus ou intern\u00e9s pour des raisons li\u00e9es au conflit arm\u00e9, les enfants seront gard\u00e9s dans des locaux s\u00e9par\u00e9s de ceux des adultes, sauf dans le cas de familles log\u00e9es en tant qu&rsquo;unit\u00e9s familiales comme le pr\u00e9voit le paragraphe 5 de l&rsquo;article 75.<\/p>\n<p>5. Une condamnation \u00e0 mort pour une infraction li\u00e9e au conflit arm\u00e9 ne sera pas ex\u00e9cut\u00e9e contre les personnes qui n&rsquo;avaient pas dix-huit ans au moment de l&rsquo;infraction.<\/p>\n<h6 id=\"article-78---evacuation-of-children\">Article 78 &#8211; Evacuation des enfants<\/h6>\n<p>1. Aucune Partie au conflit ne doit proc\u00e9der \u00e0 l&rsquo;\u00e9vacuation, vers un pays \u00e9tranger, d&rsquo;enfants autres que ses propres ressortissants, \u00e0 moins qu&rsquo;il ne s&rsquo;agisse d&rsquo;une \u00e9vacuation temporaire rendue n\u00e9cessaire par des raisons imp\u00e9rieuses tenant \u00e0 la sant\u00e9 ou \u00e0 un traitement m\u00e9dical des enfants ou, sauf dans un territoire occup\u00e9, \u00e0 leur s\u00e9curit\u00e9. Lorsqu&rsquo;on peut atteindre les parents ou les tuteurs, leur consentement \u00e9crit \u00e0 cette \u00e9vacuation est n\u00e9cessaire. Si on ne peut pas les atteindre, l&rsquo;\u00e9vacuation ne peut se faire qu&rsquo;avec le consentement \u00e9crit des personnes \u00e0 qui la loi ou la coutume attribue principalement la garde des enfants. La Puissance protectrice contr\u00f4lera toute \u00e9vacuation de cette nature, d&rsquo;entente avec les Parties int\u00e9ress\u00e9es, c&rsquo;est-\u00e0-dire la Partie qui proc\u00e8de \u00e0 l&rsquo;\u00e9vacuation, la Partie qui re\u00e7oit les enfants et toute Partie dont les ressortissants sont \u00e9vacu\u00e9s. Dans tous les cas, toutes les Parties au conflit prendront toutes les pr\u00e9cautions possibles dans la pratique pour \u00e9viter de compromettre l&rsquo;\u00e9vacuation.<\/p>\n<p>2. Lorsqu&rsquo;il est proc\u00e9d\u00e9 \u00e0 une \u00e9vacuation dans les conditions du paragraphe 1, l&rsquo;\u00e9ducation de chaque enfant \u00e9vacu\u00e9, y compris son \u00e9ducation religieuse et morale telle que la d\u00e9sirent ses parents, devra \u00eatre assur\u00e9e d&rsquo;une fa\u00e7on aussi continue que possible.<\/p>\n<p>3. Afin de faciliter le retour dans leur famille et dans leur pays des enfants \u00e9vacu\u00e9s conform\u00e9ment aux dispositions du pr\u00e9sent article, les autorit\u00e9s de la Partie qui a proc\u00e9d\u00e9 \u00e0 l&rsquo;\u00e9vacuation et, lorsqu&rsquo;il conviendra, les autorit\u00e9s du pays d&rsquo;accueil, \u00e9tabliront, pour chaque enfant, une fiche accompagn\u00e9e de photographies qu&rsquo;elles feront parvenir \u00e0 l&rsquo;Agence centrale de recherches du Comit\u00e9 international de la Croix-Rouge. Cette fiche portera, chaque fois que cela sera possible et ne risquera pas de porter pr\u00e9judice \u00e0 l&rsquo;enfant, les renseignements suivants :<\/p>\n<p>a) le(s) nom(s) de l&rsquo;enfant;<\/p>\n<p>b) le(s) pr\u00e9nom(s) de l&rsquo;enfant;<\/p>\n<p>c) le sexe de l&rsquo;enfant;<\/p>\n<p>d) le lieu et la date de naissance (ou, si cette date n&rsquo;est pas connue, l&rsquo;\u00e2ge approximatif);<\/p>\n<p>e) les nom et pr\u00e9nom du p\u00e8re;<\/p>\n<p>f) les nom et pr\u00e9nom de la m\u00e8re et \u00e9ventuellement son nom de jeune fille;<\/p>\n<p>g) les proches parents de l&rsquo;enfant;<\/p>\n<p>h) la nationalit\u00e9 de l&rsquo;enfant;<\/p>\n<p>i) la langue maternelle de l&rsquo;enfant et toute autre langue qu&rsquo;il parle;<\/p>\n<p>j) l&rsquo;adresse de la famille de l&rsquo;enfant;<\/p>\n<p>k) tout num\u00e9ro d&rsquo;identification donn\u00e9 \u00e0 l&rsquo;enfant;<\/p>\n<p>l) l&rsquo;\u00e9tat de sant\u00e9 de l&rsquo;enfant;<\/p>\n<p>m) le groupe sanguin de l&rsquo;enfant;<\/p>\n<p>n) d&rsquo;\u00e9ventuels signes particuliers;<\/p>\n<p>o) la date et le lieu o\u00f9 l&rsquo;enfant a \u00e9t\u00e9 trouv\u00e9;<\/p>\n<p>p) la date \u00e0 laquelle et le lieu o\u00f9 l&rsquo;enfant a quitt\u00e9 son pays;<\/p>\n<p>q) \u00e9ventuellement la religion de l&rsquo;enfant;<\/p>\n<p>r) l&rsquo;adresse actuelle de l&rsquo;enfant dans le pays d&rsquo;accueil;<\/p>\n<p>s) si l&rsquo;enfant meurt avant son retour, la date, le lieu et les circonstances de sa mort et le lieu de sa s\u00e9pulture.<\/p>\n<h5 id=\"chapter-iii---journalists\">Chapitre III &#8211; Journalistes<\/h5>\n<h6 id=\"article-79---measures-of-protection-for-journalists\">Article 79 &#8211; Mesures de protection des journalistes<\/h6>\n<p>1. Les journalistes qui accomplissent des missions professionnelles p\u00e9rilleuses dans des zones de conflit arm\u00e9 seront consid\u00e9r\u00e9s comme des personnes civiles au sens de l&rsquo;article 50, paragraphe 1.<\/p>\n<p>2. Ils seront prot\u00e9g\u00e9s en tant que tels conform\u00e9ment aux Conventions et au pr\u00e9sent Protocole, \u00e0 la condition de n&rsquo;entreprendre aucune action qui porte atteinte \u00e0 leur statut de personnes civiles et sans pr\u00e9judice du droit des correspondants de guerre accr\u00e9dit\u00e9s aupr\u00e8s des forces arm\u00e9es de b\u00e9n\u00e9ficier du statut pr\u00e9vu par l&rsquo;article 4 A.4, de la IIIe Convention.<\/p>\n<p>3. Ils pourront obtenir une carte d&rsquo;identit\u00e9 conforme au mod\u00e8le joint \u00e0 l&rsquo;Annexe II au pr\u00e9sent Protocole. Cette carte, qui sera d\u00e9livr\u00e9e par le gouvernement de l&rsquo;Etat dont ils sont les ressortissants, ou sur le territoire duquel ils r\u00e9sident ou dans lequel se trouve l&rsquo;agence ou l&rsquo;organe de presse qui les emploie, attestera de la qualit\u00e9 de journaliste de son d\u00e9tenteur.<\/p>\n<h3>Titre V &#8211; Ex\u00e9cution des Conventions et du pr\u00e9sent Protocole<\/h3>\n<h4 id=\"section-1---general-provisions\">Section I &#8211; Dispositions g\u00e9n\u00e9rales<\/h4>\n<h6 id=\"article-80---measures-for-execution\">Article 80 &#8211; Mesures d&rsquo;ex\u00e9cution<\/h6>\n<p>1. Les Hautes Parties contractantes et les Parties au conflit prendront sans d\u00e9lai toutes les mesures n\u00e9cessaires pour ex\u00e9cuter les obligations qui leur incombent en vertu des Conventions et du pr\u00e9sent Protocole.<\/p>\n<p>2. Les Hautes Parties contractantes et les Parties au conflit donneront des ordres et des instructions propres \u00e0 assurer le respect des Conventions et du pr\u00e9sent Protocole et en surveilleront l&rsquo;ex\u00e9cution.<\/p>\n<h6 id=\"article-81---activities-of-the-Red-Cross-and-other-humanitarian-organizations\">Article 81 &#8211; Activit\u00e9s de la Croix-Rouge et d&rsquo;autres organisations humanitaires<\/h6>\n<p>1. Les Parties au conflit accorderont au Comit\u00e9 international de la Croix-Rouge toutes les facilit\u00e9s en leur pouvoir pour lui permettre d&rsquo;assumer les t\u00e2ches humanitaires qui lui sont attribu\u00e9es par les Conventions et le pr\u00e9sent Protocole afin d&rsquo;assurer protection et assistance aux victimes des conflits; le Comit\u00e9 international de la Croix-Rouge pourra \u00e9galement exercer toutes autres activit\u00e9s humanitaires en faveur de ces victimes, avec le consentement des Parties au conflit.<\/p>\n<p>2. Les Parties au conflit accorderont \u00e0 leurs organisations respectives de la Croix-Rouge (Croissant- Rouge, Lion-et-Soleil-Rouge) les facilit\u00e9s n\u00e9cessaires \u00e0 l&rsquo;exercice de leurs activit\u00e9s humanitaires en faveur des victimes du conflit, conform\u00e9ment aux dispositions des Conventions et du pr\u00e9sent Protocole et aux principes fondamentaux de la Croix-Rouge formul\u00e9s par les Conf\u00e9rences internationales de la Croix-Rouge.<\/p>\n<p>3. Les Hautes Parties contractantes et les Parties au conflit faciliteront, dans toute la mesure du possible, l&rsquo;aide que des organisations de la Croix-Rouge (Croissant-Rouge, Lion-et-Soleil-Rouge) et la Ligue des Soci\u00e9t\u00e9s de la Croix-Rouge apporteront aux victimes des conflits conform\u00e9ment aux dispositions des Conventions et du pr\u00e9sent Protocole et aux principes fondamentaux de la Croix-Rouge formul\u00e9s par les Conf\u00e9rences internationales de la Croix-Rouge.<\/p>\n<p>4. Les Hautes Parties contractantes et les Parties en conflit accorderont, autant que possible, des facilit\u00e9s semblables \u00e0 celles qui sont mentionn\u00e9es dans les paragraphes 2 et 3 aux autres organisations humanitaires vis\u00e9es par les Conventions et le pr\u00e9sent Protocole, qui sont d\u00fbment autoris\u00e9es par les Parties au conflit int\u00e9ress\u00e9es et qui exercent leurs activit\u00e9s humanitaires conform\u00e9ment aux dispositions des Conventions et du pr\u00e9sent Protocole.<\/p>\n<h6 id=\"article-82---legal-advisers-in-armed-forces\">Article 82 &#8211; Conseillers juridiques dans les forces arm\u00e9es<\/h6>\n<p>Les Hautes Parties contractantes en tout temps, et les Parties au conflit en p\u00e9riode de conflit arm\u00e9, veilleront \u00e0 ce que des conseillers juridiques soient disponibles, lorsqu&rsquo;il y aura lieu, pour conseiller les commandants militaires, \u00e0 l&rsquo;\u00e9chelon appropri\u00e9, quant \u00e0 l&rsquo;application des Conventions et du pr\u00e9sent Protocole et quant \u00e0 l&rsquo;enseignement appropri\u00e9 \u00e0 dispenser aux forces arm\u00e9es \u00e0 ce sujet.<\/p>\n<h6 id=\"article-83---dissemination\">Article 83 &#8211; Diffusion<\/h6>\n<p>1. Les Hautes Parties contractantes s&rsquo;engagent \u00e0 diffuser le plus largement possible, en temps de paix comme en p\u00e9riode de conflit arm\u00e9, les Conventions et le pr\u00e9sent Protocole dans leurs pays respectifs et notamment \u00e0 en incorporer l&rsquo;\u00e9tude dans les programmes d&rsquo;instruction militaire et \u00e0 en encourager l&rsquo;\u00e9tude par la population civile, de telle mani\u00e8re que ces instruments soient connus des forces arm\u00e9es et de la population civile.<\/p>\n<p>2. Les autorit\u00e9s militaires ou civiles qui, en p\u00e9riode de conflit arm\u00e9, assumeraient des responsabilit\u00e9s dans l&rsquo;application des Conventions et du pr\u00e9sent Protocole devront avoir une pleine connaissance du texte de ces instruments.<\/p>\n<h6 id=\"article-84---rules-of-application\">Article 84 &#8211; Lois d&rsquo;application<\/h6>\n<p>Les Hautes Parties contractantes se communiqueront aussi rapidement que possible par l&rsquo;entremise du d\u00e9positaire et, le cas \u00e9ch\u00e9ant, par l&rsquo;entremise des Puissances protectrices, leurs traductions officielles du pr\u00e9sent Protocole, ainsi que les lois et r\u00e8glements qu&rsquo;elles pourront \u00eatre amen\u00e9es \u00e0 adopter pour en assurer l&rsquo;application.<\/p>\n<h4 id=\"section-ii---repression-of-breaches-of-the-conventions-and-of-this-protocol\">Section II &#8211; R\u00e9pression des infractions aux Conventions ou au pr\u00e9sent Protocole<\/h4>\n<h6 id=\"article-85---repression-of-breaches-of-this-protocol\">Article 85 &#8211; R\u00e9pression des infractions au pr\u00e9sent Protocole<\/h6>\n<p>1. Les dispositions des Conventions relatives \u00e0 la r\u00e9pression des infractions et des infractions graves, compl\u00e9t\u00e9es par la pr\u00e9sente Section, s&rsquo;appliquent \u00e0 la r\u00e9pression des infractions et des infractions graves au pr\u00e9sent Protocole.<\/p>\n<p>2. Les actes qualifi\u00e9s d&rsquo;infractions graves dans les Conventions constituent des infractions graves au pr\u00e9sent Protocole s&rsquo;ils sont commis contre des personnes au pouvoir d&rsquo;une Partie adverse prot\u00e9g\u00e9es par les articles 44, 45 et 73 du pr\u00e9sent Protocole, ou contre des bless\u00e9s, des malades ou des naufrag\u00e9s de la Partie adverse prot\u00e9g\u00e9s par le pr\u00e9sent Protocole, ou contre le personnel sanitaire ou religieux, des unit\u00e9s sanitaires ou des moyens de transport sanitaire qui sont sous le contr\u00f4le de la Partie adverse et prot\u00e9g\u00e9s par le pr\u00e9sent Protocole.<\/p>\n<p>3. Outre les infractions graves d\u00e9finies \u00e0 l&rsquo;article 11, les actes suivants, lorsqu&rsquo;ils sont commis intentionnellement, en violation des dispositions pertinentes du pr\u00e9sent Protocole, et qu&rsquo;ils entra\u00eenent la mort ou causent des atteintes graves \u00e0 l&rsquo;int\u00e9grit\u00e9 physique ou \u00e0 la sant\u00e9, sont consid\u00e9r\u00e9s comme des infractions graves au pr\u00e9sent Protocole :<\/p>\n<p>a) soumettre la population civile ou des personnes civiles \u00e0 une attaque;<\/p>\n<p>b) lancer une attaque sans discrimination atteignant la population civile ou des biens de caract\u00e8re civil, en sachant que cette attaque causera des pertes en vies humaines, des blessures aux personnes civiles ou des dommages aux biens de caract\u00e8re civil, qui sont excessifs au sens de l&rsquo;article 57, paragraphe 2 a iii;<\/p>\n<p>c) lancer une attaque contre des ouvrages ou installations contenant des forces dangereuses, en sachant que cette attaque causera des pertes en vies humaines, des blessures aux personnes civiles ou des dommages aux biens de caract\u00e8re civil, qui sont excessifs au sens de l&rsquo;article 57, paragraphe 2 a iii;<\/p>\n<p>d) soumettre \u00e0 une attaque des localit\u00e9s non d\u00e9fendues et des zones d\u00e9militaris\u00e9es;<\/p>\n<p>e) soumettre une personne \u00e0 une attaque en la sachant hors de combat;<\/p>\n<p>f) utiliser perfidement, en violation de l&rsquo;article 37, le signe distinctif de la croix rouge, du croissant rouge ou du lion-et-soleil rouge ou d&rsquo;autres signes protecteurs reconnus par les Conventions ou par le pr\u00e9sent Protocole.<\/p>\n<p>4. Outre les infractions graves d\u00e9finies aux paragraphes pr\u00e9c\u00e9dents et dans les Conventions, les actes suivants sont consid\u00e9r\u00e9s comme des infractions graves au Protocole lorsqu&rsquo;ils sont commis intentionnellement et en violation des Conventions ou du pr\u00e9sent Protocole :<\/p>\n<p>a) le transfert par la Puissance occupante d&rsquo;une Partie de sa population civile dans le territoire qu&rsquo;elle occupe, ou la d\u00e9portation ou le transfert \u00e0 l&rsquo;int\u00e9rieur ou hors du territoire occup\u00e9 de la totalit\u00e9 ou d&rsquo;une Partie de la population de ce territoire, en violation de l&rsquo;article 49 de la IVe Convention;<\/p>\n<p>b) tout retard injustifi\u00e9 dans le rapatriement des prisonniers de guerre ou des civils;<\/p>\n<p>c) les pratiques de l&rsquo;apartheid et les autres pratiques inhumaines et d\u00e9gradantes, fond\u00e9es sur la discrimination raciale, qui donnent lieu \u00e0 des outrages \u00e0 la dignit\u00e9 personnelle;<\/p>\n<p>d) le fait de diriger des attaques contre les monuments historiques, les oeuvres d&rsquo;art ou les lieux de culte clairement reconnus qui constituent le patrimoine culturel ou spirituel des peuples et auxquels une protection sp\u00e9ciale a \u00e9t\u00e9 accord\u00e9e en vertu d&rsquo;un arrangement particulier, par exemple dans le cadre d&rsquo;une organisation internationale comp\u00e9tente, provoquant ainsi leur destruction sur une grande \u00e9chelle, alors qu&rsquo;il n&rsquo;existe aucune preuve de violation par la Partie adverse de l&rsquo;article 53, alin\u00e9a b, et que les monuments historiques, oeuvres d&rsquo;art et lieux de culte en question ne sont pas situ\u00e9s \u00e0 proximit\u00e9 imm\u00e9diate d&rsquo;objectifs militaires;<\/p>\n<p>e) le fait de priver une personne prot\u00e9g\u00e9e par les Conventions ou vis\u00e9e au paragraphe 2 du pr\u00e9sent article de son droit d&rsquo;\u00eatre jug\u00e9e r\u00e9guli\u00e8rement et impartialement.<\/p>\n<p>5. Sous r\u00e9serve de l&rsquo;application des Conventions et du pr\u00e9sent Protocole, les infractions graves \u00e0 ces instruments sont consid\u00e9r\u00e9es comme des crimes de guerre.<\/p>\n<h6 id=\"article-86---failure-to-act\">Article 86 &#8211; Omissions<\/h6>\n<p>1. Les Hautes Parties contractantes et les Parties au conflit doivent r\u00e9primer les infractions graves et prendre les mesures n\u00e9cessaires pour faire cesser toutes les autres infractions aux Conventions ou au pr\u00e9sent Protocole qui r\u00e9sultent d&rsquo;une omission contraire \u00e0 un devoir d&rsquo;agir.<\/p>\n<p>2. Le fait qu&rsquo;une infraction aux Conventions ou au pr\u00e9sent Protocole a \u00e9t\u00e9 commise par un subordonn\u00e9 n&rsquo;exon\u00e8re pas ses sup\u00e9rieurs de leur responsabilit\u00e9 p\u00e9nale ou disciplinaire, selon le cas, s&rsquo;ils savaient ou poss\u00e9daient des informations leur permettant de conclure, dans les circonstances du moment, que ce subordonn\u00e9 commettait ou allait commettre une telle infraction, et s&rsquo;ils n&rsquo;ont pas pris toutes les mesures pratiquement possibles en leur pouvoir pour emp\u00eacher ou r\u00e9primer cette infraction.<\/p>\n<h6 id=\"article-87---duty-of-commanders\">Article 87 &#8211; Devoirs des commandants<\/h6>\n<p>1. Les Hautes Parties contractantes et les Parties au conflit doivent charger les commandants militaires, en ce qui concerne les membres des forces arm\u00e9es plac\u00e9s sous leur commandement et les autres personnes sous leur autorit\u00e9, d&#8217;emp\u00eacher que soient commises des infractions aux Conventions et au pr\u00e9sent Protocole et, au besoin, de les r\u00e9primer et de les d\u00e9noncer aux autorit\u00e9s comp\u00e9tentes.<\/p>\n<p>2. En vue d&#8217;emp\u00eacher que des infractions soient commises et de les r\u00e9primer, les Hautes Parties contractantes et les Parties au conflit doivent exiger que les commandants, selon leur niveau de responsabilit\u00e9, s&rsquo;assurent que les membres des forces arm\u00e9es plac\u00e9s sous leur commandement connaissent leurs obligations aux termes des Conventions et du pr\u00e9sent Protocole.<\/p>\n<p>3. Les Hautes Parties contractantes et les Parties au conflit doivent exiger de tout commandant qui a appris que des subordonn\u00e9s ou d&rsquo;autres personnes sous son autorit\u00e9 vont commettre ou ont commis une infraction aux Conventions ou au pr\u00e9sent Protocole qu&rsquo;il mette en oeuvre les mesures qui sont n\u00e9cessaires pour emp\u00eacher de telles violations des Conventions ou du pr\u00e9sent Protocole et, lorsqu&rsquo;il conviendra, prenne l&rsquo;initiative d&rsquo;une action disciplinaire ou p\u00e9nale \u00e0 l&rsquo;encontre des auteurs des violations.<\/p>\n<h6 id=\"article-88---mutual-assistance-in-criminal-matters\">Article 88 &#8211; Entraide judiciaire en mati\u00e8re p\u00e9nale<\/h6>\n<p>1. Les Hautes Parties contractantes s&rsquo;accorderont l&rsquo;entraide judiciaire la plus large possible dans toute proc\u00e9dure relative aux infractions graves aux Conventions ou au pr\u00e9sent Protocole.<\/p>\n<p>2. Sous r\u00e9serve des droits et des obligations \u00e9tablis par les Conventions et par l&rsquo;article 85, paragraphe 1, du pr\u00e9sent Protocole, et lorsque les circonstances le permettent, les Hautes Parties contractantes coop\u00e9reront en mati\u00e8re d&rsquo;extradition. Elles prendront d\u00fbment en consid\u00e9ration la demande de l&rsquo;Etat sur le territoire duquel l&rsquo;infraction all\u00e9gu\u00e9e s&rsquo;est produite.<\/p>\n<p>3. Dans tous les cas, la loi applicable est celle de la Haute Partie contractante requise. Toutefois, les dispositions des paragraphes pr\u00e9c\u00e9dents n&rsquo;affectent pas les obligations d\u00e9coulant des dispositions de tout autre trait\u00e9 de caract\u00e8re bilat\u00e9ral ou multilat\u00e9ral qui r\u00e9git ou r\u00e9gira en tout ou en partie le domaine de l&rsquo;entraide judiciaire en mati\u00e8re p\u00e9nale.<\/p>\n<h6 id=\"article-89---co-operation\">Article 89 &#8211; Coop\u00e9ration<\/h6>\n<p>Dans les cas de violations graves des Conventions ou du pr\u00e9sent Protocole, les Hautes Parties contractantes s&rsquo;engagent \u00e0 agir, tant conjointement que s\u00e9par\u00e9ment, en coop\u00e9ration avec l&rsquo;Organisation des Nations Unies et conform\u00e9ment \u00e0 la Charte des Nations Unies.<\/p>\n<h6 id=\"article-90---international-fact-finding-commission\">Article 90 &#8211; Commission internationale d&rsquo;\u00e9tablissement des faits<\/h6>\n<p>1. a) Il sera constitu\u00e9 une Commission internationale d&rsquo;\u00e9tablissement des faits, d\u00e9nomm\u00e9e ci- apr\u00e8s \u00ab\u00a0la Commission\u00a0\u00bb, compos\u00e9e de quinze membres de haute moralit\u00e9 et d&rsquo;une impartialit\u00e9 reconnue.<\/p>\n<p>b) Quand vingt Hautes Parties contractantes au moins seront convenues d&rsquo;accepter la comp\u00e9tence de la Commission conform\u00e9ment au paragraphe 2, et ult\u00e9rieurement \u00e0 des intervalles de cinq ans, le d\u00e9positaire convoquera une r\u00e9union des repr\u00e9sentants de ces Hautes Parties contractantes, en vue d&rsquo;\u00e9lire les membres de la Commission. A cette r\u00e9union, les membres de la Commission seront \u00e9lus au scrutin secret sur une liste de personnes pour l&rsquo;\u00e9tablissement de laquelle chacune de ces Hautes Parties contractantes pourra proposer un nom.<\/p>\n<p>c) Les membres de la Commission serviront \u00e0 titre personnel et exerceront leur mandat jusqu&rsquo;\u00e0 l&rsquo;\u00e9lection des nouveaux membres \u00e0 la r\u00e9union suivante.<\/p>\n<p>d) Lors de l&rsquo;\u00e9lection, les Hautes Parties contractantes s&rsquo;assureront que chacune des personnes \u00e0 \u00e9lire \u00e0 la Commission poss\u00e8de les qualifications requises et veilleront \u00e0 ce qu&rsquo;une repr\u00e9sentation g\u00e9ographique \u00e9quitable soit assur\u00e9e dans l&rsquo;ensemble de la Commission.<\/p>\n<p>e) Dans le cas o\u00f9 un si\u00e8ge deviendrait vacant, la Commission y pourvoira en tenant d\u00fbment compte des dispositions des alin\u00e9as pr\u00e9c\u00e9dents.<\/p>\n<p>f) Le d\u00e9positaire mettra \u00e0 la disposition de la Commission les services administratifs n\u00e9cessaires \u00e0 l&rsquo;accomplissement de ses fonctions.<\/p>\n<p>2. a) Les Hautes Parties contractantes peuvent au moment de la signature, de la ratification ou de l&rsquo;adh\u00e9sion au Protocole, ou ult\u00e9rieurement \u00e0 tout autre moment, d\u00e9clarer reconna\u00eetre de plein droit et sans accord sp\u00e9cial, \u00e0 l&rsquo;\u00e9gard de toute autre Haute Partie contractante qui accepte la m\u00eame obligation, la comp\u00e9tence de la Commission pour enqu\u00eater sur les all\u00e9gations d&rsquo;une telle autre Partie, comme l&rsquo;y autorise le pr\u00e9sent article.<\/p>\n<p>b) Les d\u00e9clarations vis\u00e9es ci-dessus seront remises au d\u00e9positaire qui en communiquera des copies aux Hautes Parties contractantes.<\/p>\n<p>c) La Commission sera comp\u00e9tente pour :<\/p>\n<p>i) enqu\u00eater sur tout fait pr\u00e9tendu \u00eatre une infraction grave au sens des Conventions et du pr\u00e9sent Protocole ou une autre violation grave des Conventions ou du pr\u00e9sent Protocole;<\/p>\n<p>ii) faciliter, en pr\u00eatant ses bons offices, le retour \u00e0 l&rsquo;observation des dispositions des Conventions et du pr\u00e9sent Protocole.<\/p>\n<p>d) Dans d&rsquo;autres situations, la Commission n&rsquo;ouvrira une enqu\u00eate \u00e0 la demande d&rsquo;une Partie au conflit qu&rsquo;avec le consentement de l&rsquo;autre ou des autres Parties int\u00e9ress\u00e9es.<\/p>\n<p>e) Sous r\u00e9serve des dispositions ci-dessus du pr\u00e9sent paragraphe, les dispositions des articles 52 de la Ire Convention, 53 de la IIe Convention, 132 de la IIIe Convention et 149 de la IVe Convention demeurent applicables \u00e0 toute violation all\u00e9gu\u00e9e des Conventions et s&rsquo;appliquent aussi \u00e0 toute violation all\u00e9gu\u00e9e du pr\u00e9sent Protocole.<\/p>\n<p>3. a) A moins que les Parties int\u00e9ress\u00e9es n&rsquo;en disposent autrement d&rsquo;un commun accord, toutes les enqu\u00eates seront effectu\u00e9es par une Chambre compos\u00e9e de sept membres nomm\u00e9s comme suit :<\/p>\n<p>i) cinq membres de la Commission, qui ne doivent \u00eatre ressortissants d&rsquo;aucune Partie au conflit, seront nomm\u00e9s par le Pr\u00e9sident de la Commission, sur la base d&rsquo;une repr\u00e9sentation \u00e9quitable des r\u00e9gions g\u00e9ographiques, apr\u00e8s consultation des Parties au conflit;<\/p>\n<p>ii) deux membres ad hoc, qui ne doivent \u00eatre ressortissants d&rsquo;aucune Partie au conflit, seront nomm\u00e9s respectivement par chacune de celles-ci.<\/p>\n<p>b) D\u00e8s la r\u00e9ception d&rsquo;une demande d&rsquo;enqu\u00eate, le Pr\u00e9sident de la Commission fixera un d\u00e9lai convenable pour la constitution d&rsquo;une Chambre. Si l&rsquo;un au moins des deux membres ad hoc n&rsquo;a pas \u00e9t\u00e9 nomm\u00e9 dans le d\u00e9lai fix\u00e9, le Pr\u00e9sident proc\u00e9dera imm\u00e9diatement \u00e0 la nomination ou aux nominations n\u00e9cessaires pour compl\u00e9ter la composition de la Chambre.<\/p>\n<p>4. a) La Chambre constitu\u00e9e conform\u00e9ment aux dispositions du paragraphe 3 en vue de proc\u00e9der \u00e0 une enqu\u00eate invitera les Parties au conflit \u00e0 l&rsquo;assister et \u00e0 produire des preuves. Elle pourra aussi rechercher les autres preuves qu&rsquo;elle jugera pertinentes et proc\u00e9der \u00e0 une enqu\u00eate sur place.<\/p>\n<p>b) Tous les \u00e9l\u00e9ments de preuve seront communiqu\u00e9s aux Parties concern\u00e9es qui auront le droit de pr\u00e9senter leurs observations \u00e0 la Commission.<\/p>\n<p>c) Chaque Partie concern\u00e9e aura le droit de discuter les preuves.<\/p>\n<p>5. a) La Commission pr\u00e9sentera aux Parties concern\u00e9es un rapport sur les r\u00e9sultats de l&rsquo;enqu\u00eate de la Chambre avec les recommandations qu&rsquo;elle jugerait appropri\u00e9es.<\/p>\n<p>b) Si la Chambre n&rsquo;est pas en mesure de rassembler des preuves qui suffisent \u00e0 \u00e9tayer des conclusions objectives et impartiales, la Commission fera conna\u00eetre les raisons de cette impossibilit\u00e9.<\/p>\n<p>c) La Commission ne communiquera pas publiquement ses conclusions, \u00e0 moins que toutes les Parties au conflit le lui aient demand\u00e9.<\/p>\n<p>6. La Commission \u00e9tablira son r\u00e8glement int\u00e9rieur, y compris les r\u00e8gles concernant la pr\u00e9sidence de la Commission et de la Chambre. Ce r\u00e8glement pr\u00e9voira que les fonctions du Pr\u00e9sident de la Commission seront exerc\u00e9es en tout temps et que, en cas d&rsquo;enqu\u00eate, elles seront exerc\u00e9es par une personne qui ne soit pas ressortissante d&rsquo;une des Parties au conflit.<\/p>\n<p>7. Les d\u00e9penses administratives de la Commission seront couvertes par des contributions des Hautes Parties contractantes qui auront fait la d\u00e9claration pr\u00e9vue au paragraphe 2 et par des contributions volontaires. La ou les Parties au conflit qui demandent une enqu\u00eate avanceront les fonds n\u00e9cessaires pour couvrir les d\u00e9penses occasionn\u00e9es par une Chambre et seront rembours\u00e9es par la ou les Parties contre lesquelles les all\u00e9gations sont port\u00e9es \u00e0 concurrence de cinquante pour cent des frais de la Chambre. Si des all\u00e9gations contraires sont pr\u00e9sent\u00e9es \u00e0 la Chambre, chaque Partie avancera cinquante pour cent des fonds n\u00e9cessaires.<\/p>\n<h6 id=\"article-91---responsibility\">Article 91 &#8211; Responsabilit\u00e9<\/h6>\n<p>La Partie au conflit qui violerait les dispositions des Conventions ou du pr\u00e9sent Protocole sera tenue \u00e0 indemnit\u00e9, s&rsquo;il y a lieu. Elle sera responsable de tous actes commis par les personnes faisant Partie de ses forces arm\u00e9es.<\/p>\n<h3>Titre VI &#8211; Dispositions finales<\/h3>\n<h6 id=\"article-92---signature\">Article 92 &#8211; Signature<\/h6>\n<p>Le pr\u00e9sent Protocole sera ouvert \u00e0 la signature des Parties aux Conventions six mois apr\u00e8s la signature de l&rsquo;Acte final et restera ouvert durant une p\u00e9riode de douze mois.<\/p>\n<h6 id=\"article-93---ratification\">Article 93 &#8211; Ratification<\/h6>\n<p>Le pr\u00e9sent Protocole sera ratifi\u00e9 d\u00e8s que possible. Les instruments de ratification seront d\u00e9pos\u00e9s aupr\u00e8s du Conseil f\u00e9d\u00e9ral suisse, d\u00e9positaire des Conventions.<\/p>\n<h6 id=\"article-94---accession\">Article 94 &#8211; Adh\u00e9sion<\/h6>\n<p>Le pr\u00e9sent Protocole sera ouvert \u00e0 l&rsquo;adh\u00e9sion de toute Partie aux Conventions non signataire du pr\u00e9sent Protocole. Les instruments d&rsquo;adh\u00e9sion seront d\u00e9pos\u00e9s aupr\u00e8s du d\u00e9positaire.<\/p>\n<h6 id=\"article-95---entry-into-force\">Article 95 &#8211; Entr\u00e9e en vigueur<\/h6>\n<p>1. Le pr\u00e9sent Protocole entrera en vigueur six mois apr\u00e8s le d\u00e9p\u00f4t de deux instruments de ratification ou d&rsquo;adh\u00e9sion.<\/p>\n<p>2. Pour chacune des Parties aux Conventions qui le ratifiera ou y adh\u00e9rera ult\u00e9rieurement, le pr\u00e9sent Protocole entrera en vigueur six mois apr\u00e8s le d\u00e9p\u00f4t par cette Partie de son instrument de ratification ou d&rsquo;adh\u00e9sion.<\/p>\n<h6 id=\"article-96---treaty-relations-upon-entry-into-force-of-this-protocol\">Article 96 &#8211; Rapports conventionnels d\u00e8s l&rsquo;entr\u00e9e en vigueur du pr\u00e9sent Protocole<\/h6>\n<p>1. Lorsque les Parties aux Conventions sont \u00e9galement Parties au pr\u00e9sent Protocole, les Conventions s&rsquo;appliquent telles qu&rsquo;elles sont compl\u00e9t\u00e9es par le pr\u00e9sent Protocole.<\/p>\n<p>2. Si l&rsquo;une des Parties au conflit n&rsquo;est pas li\u00e9e par le pr\u00e9sent Protocole, les Parties au pr\u00e9sent Protocole resteront n\u00e9anmoins li\u00e9es par celui-ci dans leurs rapports r\u00e9ciproques. Elles seront li\u00e9es en outre par le pr\u00e9sent Protocole envers ladite Partie, si celle-ci en accepte et en applique les dispositions.<\/p>\n<p>3. L&rsquo;autorit\u00e9 repr\u00e9sentant un peuple engag\u00e9 contre une Haute Partie contractante dans un conflit arm\u00e9 du caract\u00e8re mentionn\u00e9 \u00e0 l&rsquo;article premier, paragraphe 4, peut s&rsquo;engager \u00e0 appliquer les Conventions et le pr\u00e9sent Protocole relativement \u00e0 ce conflit en adressant une d\u00e9claration unilat\u00e9rale au d\u00e9positaire. Apr\u00e8s r\u00e9ception par le d\u00e9positaire, cette d\u00e9claration aura, en relation avec ce conflit, les effets suivants :<\/p>\n<p>a) les Conventions et le pr\u00e9sent Protocole prennent imm\u00e9diatement effet pour ladite autorit\u00e9 en sa qualit\u00e9 de Partie au conflit;<\/p>\n<p>b) ladite autorit\u00e9 exerce les m\u00eames droits et s&rsquo;acquitte des m\u00eames obligations qu&rsquo;une Haute Partie contractante aux Conventions et au pr\u00e9sent Protocole; et<\/p>\n<p>c) les Conventions et le pr\u00e9sent Protocole lient d&rsquo;une mani\u00e8re \u00e9gale toutes les Parties au conflit.<\/p>\n<h6 id=\"article-97---amendment\">Article 97 &#8211; Amendement<\/h6>\n<p>1. Toute Haute Partie contractante pourra proposer des amendements au pr\u00e9sent Protocole. le texte de tout projet d&rsquo;amendement sera communiqu\u00e9 au d\u00e9positaire qui, apr\u00e8s consultation de l&rsquo;ensemble des Hautes Parties contractantes et du Comit\u00e9 international de la Croix-Rouge, d\u00e9cidera s&rsquo;il convient de convoquer une conf\u00e9rence pour examiner le ou les amendements propos\u00e9s.<\/p>\n<p>2. Le d\u00e9positaire invitera \u00e0 cette conf\u00e9rence les Hautes Parties contractantes ainsi que les Parties aux Conventions, signataires ou non du pr\u00e9sent Protocole.<\/p>\n<h6 id=\"article-98---revision-of-annex-i\">Article 98 &#8211; R\u00e9vision de l&rsquo;Annexe I<\/h6>\n<p>1. Quatre ans au plus tard apr\u00e8s l&rsquo;entr\u00e9e en vigueur du pr\u00e9sent Protocole et, ult\u00e9rieurement, \u00e0 des intervalles d&rsquo;au moins quatre ans, le Comit\u00e9 international de la Croix-Rouge consultera les Hautes Parties contractantes au sujet de l&rsquo;Annexe I au pr\u00e9sent Protocole et, s&rsquo;il le juge n\u00e9cessaire, pourra proposer une r\u00e9union d&rsquo;experts techniques en vue de revoir l&rsquo;Annexe I et de proposer les amendements qui para\u00eetraient souhaitables. A moins que, dans les six mois suivant la communication aux Hautes Parties contractantes d&rsquo;une proposition relative \u00e0 une telle r\u00e9union, le tiers de ces Parties s&rsquo;y oppose, le Comit\u00e9 international de la Croix-Rouge convoquera cette r\u00e9union, \u00e0 laquelle il invitera \u00e9galement les observateurs des organisations internationales concern\u00e9es. Une telle r\u00e9union sera \u00e9galement convoqu\u00e9e par le Comit\u00e9 international de la Croix-Rouge, en tout temps, \u00e0 la demande du tiers des Hautes Parties contractantes.<\/p>\n<p>2. Le d\u00e9positaire convoquera une conf\u00e9rence des Hautes Parties contractantes et des Parties aux Conventions pour examiner les amendements propos\u00e9s par la r\u00e9union d&rsquo;experts techniques si, \u00e0 la suite de ladite r\u00e9union, le Comit\u00e9 international de la Croix-Rouge ou le tiers des Hautes Parties contractantes le demande.<\/p>\n<p>3. Les amendements \u00e0 l&rsquo;Annexe I pourront \u00eatre adopt\u00e9s par ladite conf\u00e9rence \u00e0 la majorit\u00e9 des deux tiers des Hautes Parties contractantes pr\u00e9sentes et votantes.<\/p>\n<p>4. Le d\u00e9positaire communiquera aux Hautes Parties contractantes et aux Parties aux Conventions tout amendement ainsi adopt\u00e9. L&rsquo;amendement sera consid\u00e9r\u00e9 comme accept\u00e9 \u00e0 l&rsquo;expiration d&rsquo;une p\u00e9riode d&rsquo;un an \u00e0 compter de la communication sauf si, au cours de cette p\u00e9riode, une d\u00e9claration de non-acceptation de l&rsquo;amendement est communiqu\u00e9e au d\u00e9positaire par le tiers au moins des Hautes Parties contractantes.<\/p>\n<p>5. Un amendement consid\u00e9r\u00e9 comme ayant \u00e9t\u00e9 accept\u00e9 conform\u00e9ment au paragraphe 4 entrera en vigueur trois mois apr\u00e8s la date d&rsquo;acceptation pour toutes les Hautes Parties contractantes, \u00e0 l&rsquo;exception de celles qui auront fait une d\u00e9claration de non-acceptation conform\u00e9ment \u00e0 ce m\u00eame paragraphe. Toute Partie qui fait une telle d\u00e9claration peut \u00e0 tout moment la retirer, auquel cas l&rsquo;amendement entrera en vigueur pour cette Partie trois mois apr\u00e8s le retrait.<\/p>\n<p>6. Le d\u00e9positaire fera conna\u00eetre aux Hautes Parties contractantes et aux Parties aux Conventions l&rsquo;entr\u00e9e en vigueur de tout amendement, les Parties li\u00e9es par cet amendement, la date de son entr\u00e9e en vigueur pour chacune des Parties, les d\u00e9clarations de non-acceptation faites conform\u00e9ment au paragraphe 4 et les retraits de telles d\u00e9clarations.<\/p>\n<h6 id=\"article-99---denunciation\">Article 99 &#8211; D\u00e9nonciation<\/h6>\n<p>1. Au cas o\u00f9 une Haute Partie contractante d\u00e9noncerait le pr\u00e9sent Protocole, la d\u00e9nonciation ne produira ses effets qu&rsquo;une ann\u00e9e apr\u00e8s r\u00e9ception de l&rsquo;instrument de d\u00e9nonciation. Si toutefois, \u00e0 l&rsquo;expiration de cette ann\u00e9e, la Partie d\u00e9non\u00e7ante se trouve dans une situation vis\u00e9e par l&rsquo;article premier, l&rsquo;effet de la d\u00e9nonciation demeurera suspendu jusqu&rsquo;\u00e0 la fin du conflit arm\u00e9 ou de l&rsquo;occupation et, en tout cas, aussi longtemps que les op\u00e9rations de lib\u00e9ration d\u00e9finitive, de rapatriement ou d&rsquo;\u00e9tablissement des personnes prot\u00e9g\u00e9es par les Conventions ou par le pr\u00e9sent Protocole ne seront pas termin\u00e9es.<\/p>\n<p>2. La d\u00e9nonciation sera notifi\u00e9e par \u00e9crit au d\u00e9positaire qui informera toutes les Hautes Parties contractantes de cette notification.<\/p>\n<p>3. La d\u00e9nonciation n&rsquo;aura d&rsquo;effet qu&rsquo;\u00e0 l&rsquo;\u00e9gard de la Partie d\u00e9non\u00e7ante.<\/p>\n<p>4. Aucune d\u00e9nonciation notifi\u00e9e aux termes du paragraphe 1 n&rsquo;aura d&rsquo;effet sur les obligations d\u00e9j\u00e0 contract\u00e9es du fait du conflit arm\u00e9 au titre du pr\u00e9sent Protocole par la Partie d\u00e9non\u00e7ante pour tout acte commis avant que ladite d\u00e9nonciation devienne effective.<\/p>\n<h6 id=\"article-100---notifications\">Article 100 &#8211; Notifications<\/h6>\n<p>Le d\u00e9positaire informera les Hautes Parties contractantes ainsi que les Parties aux Conventions, qu&rsquo;elles soient signataires ou non du pr\u00e9sent Protocole :<\/p>\n<p>a) des signatures appos\u00e9es au pr\u00e9sent Protocole et des instruments de ratification et d&rsquo;adh\u00e9sion d\u00e9pos\u00e9s conform\u00e9ment aux articles 93 et 94;<\/p>\n<p>b) de la date \u00e0 laquelle le pr\u00e9sent Protocole entrera en vigueur conform\u00e9ment \u00e0 l&rsquo;article 95;<\/p>\n<p>c) des communications et d\u00e9clarations re\u00e7ues conform\u00e9ment aux articles 84, 90 et 97;<\/p>\n<p>d) des d\u00e9clarations re\u00e7ues conform\u00e9ment \u00e0 l&rsquo;article 96, paragraphe 3, qui seront communiqu\u00e9es par les voies les plus rapides;<\/p>\n<p>e) des d\u00e9nonciations notifi\u00e9es conform\u00e9ment \u00e0 l&rsquo;article 99.<\/p>\n<h6 id=\"article-101---registration\">Article 101 &#8211; Enregistrement<\/h6>\n<p>1. Apr\u00e8s son entr\u00e9e en vigueur, le pr\u00e9sent Protocole sera transmis par le d\u00e9positaire au Secr\u00e9tariat des Nations Unies aux fins d&rsquo;enregistrement et de publication, conform\u00e9ment \u00e0 l&rsquo;article 102 de la Charte des Nations Unies.<\/p>\n<p>2. Le d\u00e9positaire informera \u00e9galement le Secr\u00e9tariat des Nations Unies de toutes les ratifications, adh\u00e9sions et d\u00e9nonciations qu&rsquo;il pourra recevoir au sujet du pr\u00e9sent Protocole.<\/p>\n<h6 id=\"article-102---authentic-texts\">Article 102 &#8211; Textes authentiques<\/h6>\n<p>L&rsquo;original du pr\u00e9sent Protocole, dont les textes anglais, arabe, chinois, espagnol, fran\u00e7ais et russe sont \u00e9galement authentiques, sera d\u00e9pos\u00e9 aupr\u00e8s du d\u00e9positaire qui fera parvenir des copies certifi\u00e9es conformes \u00e0 toutes les Parties aux Conventions.<\/p>\n<h3>Annexe I<\/h3>\n<h3>R\u00e8glement relatif \u00e0 l&rsquo;identification<\/h3>\n<h5>Chapitre I &#8211; Cartes d&rsquo;identit\u00e9<\/h5>\n<h6>Article premier &#8211; Carte d&rsquo;identit\u00e9 du personnel sanitaire et religieux, civil et permanent<\/h6>\n<p>1. La carte d&rsquo;identit\u00e9 du personnel sanitaire et religieux, civil et permanent, pr\u00e9vue \u00e0 l&rsquo;article 18, paragraphe 3, du Protocole, devrait :<\/p>\n<p>a) porter le signe distinctif et \u00eatre de dimensions telles qu&rsquo;elle puisse \u00eatre mise dans la poche;<\/p>\n<p>b) \u00eatre faite d&rsquo;une mati\u00e8re aussi durable que possible;<\/p>\n<p>c) \u00eatre r\u00e9dig\u00e9e dans la langue nationale ou officielle (elle peut l&rsquo;\u00eatre, en outre, dans d&rsquo;autres langues);<\/p>\n<p>d) indiquer le nom et la date de naissance du titulaire (ou, \u00e0 d\u00e9faut de cette date, son \u00e2ge au moment de la d\u00e9livrance de la carte) ainsi que son num\u00e9ro d&rsquo;immatriculation s&rsquo;il en a un;<\/p>\n<p>e) indiquer en quelle qualit\u00e9 le titulaire a droit \u00e0 la protection des Conventions et du Protocole;<\/p>\n<p>f) porter la photographie du titulaire, ainsi que sa signature ou l&#8217;empreinte de son pouce, ou les deux;<\/p>\n<p>g) porter le timbre et la signature de l&rsquo;autorit\u00e9 comp\u00e9tente;<\/p>\n<p>h) indiquer la date d&rsquo;\u00e9mission et d&rsquo;expiration de la carte.<\/p>\n<p>2. La carte d&rsquo;identit\u00e9 doit \u00eatre uniforme sur tout le territoire de chaque Haute Partie contractante et, autant que possible, \u00eatre du m\u00eame type pour toutes les Parties au conflit. Les Parties au conflit peuvent s&rsquo;inspirer du mod\u00e8le en une seule langue de la figure 1. Au d\u00e9but des hostilit\u00e9s, les Parties au conflit doivent se communiquer un sp\u00e9cimen de la carte d&rsquo;identit\u00e9 qu&rsquo;elles utilisent si cette carte diff\u00e8re du mod\u00e8le de la figure 1. La carte d&rsquo;identit\u00e9 est \u00e9tablie, si possible, en deux exemplaires, dont l&rsquo;un est conserv\u00e9 par l&rsquo;autorit\u00e9 \u00e9mettrice, qui devrait tenir un contr\u00f4le des cartes qu&rsquo;elle a d\u00e9livr\u00e9es.<\/p>\n<p>3. En aucun cas, le personnel sanitaire et religieux, civil et permanent, ne peut \u00eatre priv\u00e9 de cartes d&rsquo;identit\u00e9. En cas de perte d&rsquo;une carte, le titulaire a le droit d&rsquo;obtenir un duplicata.<\/p>\n<h6>Article 2 &#8211; Carte d&rsquo;identit\u00e9 du personnel sanitaire et religieux, civil et temporaire<\/h6>\n<p>1. La carte d&rsquo;identit\u00e9 du personnel sanitaire et religieux, civil et temporaire, devrait, si possible, \u00eatre analogue \u00e0 celle qui est pr\u00e9vue \u00e0 l&rsquo;article premier du pr\u00e9sent R\u00e8glement. Les Parties au conflit peuvent s&rsquo;inspirer du mod\u00e8le de la figure 1.<\/p>\n<p>2. Lorsque les circonstances emp\u00eachent de d\u00e9livrer au personnel sanitaire et religieux, civil et temporaire, des cartes d&rsquo;identit\u00e9 analogues \u00e0 celle qui est d\u00e9crite \u00e0 l&rsquo;article premier du pr\u00e9sent R\u00e8glement, ce personnel peut recevoir un certificat, sign\u00e9 par l&rsquo;autorit\u00e9 comp\u00e9tente, attestant que la personne \u00e0 laquelle il est d\u00e9livr\u00e9 a re\u00e7u une affectation en tant que personnel temporaire, et indiquant, si possible, la dur\u00e9e de cette affectation et le droit du titulaire au port du signe distinctif. Ce certificat doit indiquer le nom et la date de naissance du titulaire (ou, \u00e0 d\u00e9faut de cette date, son \u00e2ge au moment de la d\u00e9livrance du certificat), la fonction du titulaire ainsi que son num\u00e9ro d&rsquo;immatriculation s&rsquo;il en a un. Il doit porter sa signature ou l&#8217;empreinte de son pouce, ou les deux.<\/p>\n<p>Fig. 1 : Mod\u00e8le de carte d&rsquo;identit\u00e9 (format : 74 mm x 105 mm)<\/p>\n<h5>Chapitre II &#8211; Le signe distinctif<\/h5>\n<h6>Article 3 &#8211; Forme et nature<\/h6>\n<p>1. Le signe distinctif (rouge sur fond blanc) doit \u00eatre aussi grand que le justifient les circonstances. les Hautes Parties contractantes peuvent s&rsquo;inspirer pour la forme de la croix, du croissant ou du lion et soleil, des mod\u00e8les de la figure 2.<\/p>\n<p>2. De nuit ou par visibilit\u00e9 r\u00e9duite, le signe distinctif pourra \u00eatre \u00e9clair\u00e9 ou illumin\u00e9; il pourra \u00e9galement \u00eatre fait de mat\u00e9riaux le rendant reconnaissable par des moyens techniques de d\u00e9tection.<\/p>\n<p>Fig. 2 : Signes distinctifs en rouge sur fond blanc<\/p>\n<h6>Article 4 &#8211; Utilisation<\/h6>\n<p>1. Le signe distinctif est, dans la mesure du possible, appos\u00e9 sur des drapeaux ou sur une surface plane visibles de toutes les directions possibles et d&rsquo;aussi loin que possible.<\/p>\n<p>2. Sous r\u00e9serve des instructions de l&rsquo;autorit\u00e9 comp\u00e9tente, le personnel sanitaire et religieux s&rsquo;acquittant de ses t\u00e2ches sur le champ de bataille doit \u00eatre \u00e9quip\u00e9, dans la mesure du possible, de coiffures et de v\u00eatements munis du signe distinctif.<\/p>\n<h5>Chapitre III &#8211; Signaux distinctifs<\/h5>\n<h6>Article 5 &#8211; Utilisation facultative<\/h6>\n<p>1. Sous r\u00e9serve des dispositions de l&rsquo;article 6 du pr\u00e9sent R\u00e8glement, les signaux d\u00e9finis dans le pr\u00e9sent Chapitre pour l&rsquo;usage exclusif des unit\u00e9s et moyens de transport sanitaires ne doivent pas \u00eatre utilis\u00e9s \u00e0 d&rsquo;autres fins. L&#8217;emploi de tous les signaux vis\u00e9s au pr\u00e9sent Chapitre est facultatif.<\/p>\n<p>2. Les a\u00e9ronefs sanitaires temporaires qui, faute de temps ou en raison de leurs caract\u00e9ristiques, ne peuvent pas \u00eatre marqu\u00e9s du signe distinctif, peuvent utiliser les signaux distinctifs autoris\u00e9s dans le pr\u00e9sent Chapitre. Toutefois la m\u00e9thode de signalisation la plus efficace d&rsquo;un a\u00e9ronef sanitaire en vue de son identification et de sa reconnaissance est l&#8217;emploi d&rsquo;un signal visuel, soit le signe distinctif, soit le signal lumineux d\u00e9fini \u00e0 l&rsquo;article 6, soit les deux, compl\u00e9t\u00e9 par les autres signaux mentionn\u00e9s aux articles 7 et 8 du pr\u00e9sent R\u00e8glement.<\/p>\n<h6>Article 6 &#8211; Signal lumineux<\/h6>\n<p>1. Le signal lumineux, consistant en un feu bleu scintillant, est pr\u00e9vu \u00e0 l&rsquo;usage des a\u00e9ronefs sanitaires pour signaler leur identit\u00e9. Aucun autre a\u00e9ronef ne peut utiliser ce signal. La couleur bleue recommand\u00e9e s&rsquo;obtient au moyen des coordonn\u00e9es trichromatiques ci-apr\u00e8s :<\/p>\n<p>limite des verts y = 0,065 + 0,805x limite des blancs y = 0,400 &#8211; x limite des pourpres x = 0,133 + 0,600y<\/p>\n<p>La fr\u00e9quence recommand\u00e9e des \u00e9clats lumineux bleus est de 60 \u00e0 100 \u00e9clats par minute.<\/p>\n<p>2. Les a\u00e9ronefs sanitaires devraient \u00eatre \u00e9quip\u00e9s des feux n\u00e9cessaires pour rendre le signal lumineux visible dans toutes les directions possibles.<\/p>\n<p>3. En l&rsquo;absence d&rsquo;accord sp\u00e9cial entre les Parties au conflit, r\u00e9servant l&rsquo;usage des feux bleus scintillants \u00e0 l&rsquo;identification des v\u00e9hicules et des navires et embarcations sanitaires, l&#8217;emploi de ces signaux pour d&rsquo;autres v\u00e9hicules ou navires n&rsquo;est pas interdit.<\/p>\n<h6>Article 7 &#8211; Signal radio<\/h6>\n<p>1. Le signal radio consiste en un message radiot\u00e9l\u00e9phonique ou radiot\u00e9l\u00e9graphique, pr\u00e9c\u00e9d\u00e9 d&rsquo;un signal distinctif de priorit\u00e9, qui doit \u00eatre d\u00e9fini et approuv\u00e9 par une Conf\u00e9rence administrative mondiale des radiocommunications de l&rsquo;Union internationale des t\u00e9l\u00e9communications. Ce signal est \u00e9mis trois fois avant l&rsquo;indicatif d&rsquo;appel du transport sanitaire en cause. Le message est \u00e9mis en anglais \u00e0 intervalles appropri\u00e9s, sur une ou plusieurs fr\u00e9quences sp\u00e9cifi\u00e9es comme il est pr\u00e9vu au paragraphe 3. Le signal de priorit\u00e9 est exclusivement r\u00e9serv\u00e9 aux unit\u00e9s et moyens de transport sanitaires.<\/p>\n<p>2. Le message radio, pr\u00e9c\u00e9d\u00e9 du signal distinctif de priorit\u00e9 vis\u00e9 au paragraphe 1, contient les \u00e9l\u00e9ments suivants :<\/p>\n<p>a) indicatif d&rsquo;appel du moyen de transport sanitaire;<\/p>\n<p>b) position du moyen de transport sanitaire;<\/p>\n<p>c) nombre et type des moyens de transport sanitaire;<\/p>\n<p>d) itin\u00e9raire choisi;<\/p>\n<p>e) dur\u00e9e en route et heure de d\u00e9part et d&rsquo;arriv\u00e9e pr\u00e9vues, selon le cas;<\/p>\n<p>f) autres informations telles que l&rsquo;altitude de vol, les fr\u00e9quences radio\u00e9lectriques veill\u00e9es, les langages conventionnels, les modes et codes des syst\u00e8mes de radar secondaires de surveillance.<\/p>\n<p>3. Pour faciliter les communications vis\u00e9es aux paragraphes 1 et 2, ainsi que les communications vis\u00e9es aux articles 22, 23, 25, 26, 27, 28, 29, 30 et 31 du Protocole, les Hautes Parties contractantes, les Parties \u00e0 un conflit ou l&rsquo;une des Parties \u00e0 un conflit, agissant d&rsquo;un commun accord ou isol\u00e9ment, peuvent d\u00e9finir, conform\u00e9ment au Tableau de r\u00e9partition des bandes de fr\u00e9quences figurant dans le R\u00e8glement des radiocommunications annex\u00e9 \u00e0 la Convention internationale des t\u00e9l\u00e9communications, et publier les fr\u00e9quences nationales qu&rsquo;elles choisissent pour ces communications. Ces fr\u00e9quences doivent \u00eatre notifi\u00e9es \u00e0 l&rsquo;Union internationale des t\u00e9l\u00e9communications, conform\u00e9ment \u00e0 la proc\u00e9dure approuv\u00e9e par une Conf\u00e9rence administrative mondiale des radiocommunications.<\/p>\n<h6>Article 8 &#8211; Identification par moyens \u00e9lectroniques<\/h6>\n<p>1. Le syst\u00e8me de radar secondaire de surveillance (SSR), tel qu&rsquo;il est sp\u00e9cifi\u00e9 \u00e0 l&rsquo;Annexe 10 de la Convention de Chicago du 7 d\u00e9cembre 1944 relative \u00e0 l&rsquo;Aviation civile internationale mise \u00e0 jour p\u00e9riodiquement, peut \u00eatre utilis\u00e9 pour identifier et suivre le cheminement d&rsquo;un a\u00e9ronef sanitaire. Le mode et le code SSR \u00e0 r\u00e9server \u00e0 l&rsquo;usage exclusif des a\u00e9ronefs sanitaires doivent \u00eatre d\u00e9finis par les Hautes Parties contractantes, les Parties au conflit ou une des Parties au conflit, agissant d&rsquo;un commun accord ou isol\u00e9ment, conform\u00e9ment \u00e0 des proc\u00e9dures \u00e0 recommander par l&rsquo;Organisation de l&rsquo;Aviation civile internationale.<\/p>\n<p>2. Les Parties au conflit peuvent, par accord sp\u00e9cial, adopter pour leur usage entre elles un syst\u00e8me \u00e9lectronique analogue pour l&rsquo;identification des v\u00e9hicules sanitaires et des navires et embarcations sanitaires.<\/p>\n<h5>Chapitre IV &#8211; Communications<\/h5>\n<h6>Article 9 &#8211; Radiocommunications<\/h6>\n<p>Le signal de priorit\u00e9 pr\u00e9vu par l&rsquo;article 7 du pr\u00e9sent R\u00e8glement pourra pr\u00e9c\u00e9der les radiocommunications appropri\u00e9es des unit\u00e9s sanitaires et des moyens de transport sanitaire pour l&rsquo;application des proc\u00e9dures mises en oeuvre conform\u00e9ment aux articles 22, 23, 25, 26, 27, 28, 29, 30 et 31 du Protocole.<\/p>\n<h6>Article 10 &#8211; Utilisation des codes internationaux<\/h6>\n<p>Les unit\u00e9s et moyens de transport sanitaires peuvent aussi utiliser les codes et signaux \u00e9tablis par l&rsquo;Union internationale des t\u00e9l\u00e9communications, l&rsquo;Organisation de l&rsquo;Aviation civile internationale et l&rsquo;Organisation intergouvernementale consultative de la navigation maritime. Ces codes et signaux sont alors utilis\u00e9s conform\u00e9ment aux normes, pratiques et proc\u00e9dures \u00e9tablies par ces Organisations.<\/p>\n<h6>Article 11 &#8211; Autres moyens de communication<\/h6>\n<p>Lorsqu&rsquo;une radiocommunication bilat\u00e9rale n&rsquo;est pas possible, les signaux pr\u00e9vus par le code international de signaux adopt\u00e9 par l&rsquo;Organisation intergouvernementale consultative de la navigation maritime, ou dans l&rsquo;Annexe pertinente de la Convention de Chicago du 7 d\u00e9cembre 1944 relative \u00e0 l&rsquo;Aviation civile internationale, mise \u00e0 jour p\u00e9riodiquement, peuvent \u00eatre employ\u00e9s.<\/p>\n<h6>Article 12 &#8211; Plans de vol<\/h6>\n<p>Les accords et notifications relatifs aux plans de vol vis\u00e9s \u00e0 l&rsquo;article 29 du Protocole doivent, autant que possible, \u00eatre formul\u00e9s conform\u00e9ment aux proc\u00e9dures \u00e9tablies par l&rsquo;Organisation de l&rsquo;Aviation civile internationale.<\/p>\n<h6>Article 13 &#8211; Signaux et proc\u00e9dures pour l&rsquo;interception des a\u00e9ronefs sanitaires<\/h6>\n<p>Si un a\u00e9ronef intercepteur est employ\u00e9 pour identifier un a\u00e9ronef sanitaire en vol, ou le sommer d&rsquo;atterrir, en application des articles 30 et 31 du Protocole, les proc\u00e9dures normalis\u00e9es d&rsquo;interception visuelle et radio, prescrites \u00e0 l&rsquo;Annexe 2 de la Convention de Chicago du 7 d\u00e9cembre 1944 relative \u00e0 l&rsquo;Aviation civile internationale, mise \u00e0 jour p\u00e9riodiquement, devraient \u00eatre utilis\u00e9es par l&rsquo;a\u00e9ronef intercepteur et l&rsquo;a\u00e9ronef sanitaire.<\/p>\n<h5>Chapitre V &#8211; Protection civile<\/h5>\n<h6>Article 14 &#8211; Carte d&rsquo;identit\u00e9<\/h6>\n<p>1. La carte d&rsquo;identit\u00e9 du personnel de la protection civile vis\u00e9 \u00e0 l&rsquo;article 66, paragraphe 3, du Protocole, est r\u00e9gie par les dispositions pertinentes de l&rsquo;article premier du pr\u00e9sent R\u00e8glement.<\/p>\n<p>2. La carte d&rsquo;identit\u00e9 du personnel de la protection civile pourra se conformer au mod\u00e8le repr\u00e9sent\u00e9 \u00e0 la figure 3.<\/p>\n<p>3. Si le personnel de la protection civile est autoris\u00e9 \u00e0 porter des armes l\u00e9g\u00e8res individuelles, les cartes d&rsquo;identit\u00e9 devraient le mentionner.<\/p>\n<p>Fig. 3 : Mod\u00e8le de carte d&rsquo;identit\u00e9 du personnel de la protection civile (format : 74 mm x 105 mm)<\/p>\n<h6>Article 15 &#8211; Signe distinctif international<\/h6>\n<p>1. Le signe distinctif international de la protection civile, pr\u00e9vu \u00e0 l&rsquo;article 66, paragraphe 4, du Protocole est un triangle \u00e9quilat\u00e9ral bleu sur fond orange. Il est repr\u00e9sent\u00e9 \u00e0 la figure 4 ci-apr\u00e8s :<\/p>\n<p>Fig. 4 : Triangle bleu sur fond orange<\/p>\n<p>2. Il est recommand\u00e9 :<\/p>\n<p>a) si le triangle bleu se trouve sur un drapeau, un brassard ou un dossard, que le drapeau, le brassard ou le dossard en constituent le fond orange,<\/p>\n<p>b) que l&rsquo;un des sommets du triangle soit tourn\u00e9 vers le haut, \u00e0 la verticale,<\/p>\n<p>c) qu&rsquo;aucun des sommets du triangle ne touche le bord du fond orange.<\/p>\n<p>3. Le signe distinctif international doit \u00eatre aussi grand que le justifient les circonstances. Le signe doit, dans la mesure du possible, \u00eatre appos\u00e9 sur des drapeaux ou sur une surface plane visibles de toutes les directions possibles et d&rsquo;aussi loin que possible. Sous r\u00e9serve des instructions de l&rsquo;autorit\u00e9 comp\u00e9tente, le personnel de la protection civile doit \u00eatre \u00e9quip\u00e9, dans la mesure du possible, de coiffures et de v\u00eatements munis du signe distinctif international. De nuit, ou par visibilit\u00e9 r\u00e9duite, le signe peut \u00eatre \u00e9clair\u00e9 ou illumin\u00e9; il pourra \u00e9galement \u00eatre fait de mat\u00e9riaux le rendant reconnaissable par des moyens techniques de d\u00e9tection.<\/p>\n<h5>Chapitre VI &#8211; Ouvrages et installations contenant des forces dangereuses<\/h5>\n<h6>Article 16 &#8211; Signe sp\u00e9cial international<\/h6>\n<p>1. Le signe sp\u00e9cial international pour les ouvrages et installations contenant des forces dangereuses, pr\u00e9vu au paragraphe 7 de l&rsquo;article 56 du Protocole, consiste en un groupe de trois cercles orange vif de m\u00eame dimension dispos\u00e9s sur un m\u00eame axe, la distance entre les cercles \u00e9tant \u00e9gale au rayon, conform\u00e9ment \u00e0 la figure 5 ci-apr\u00e8s.<\/p>\n<p>2. Le signe doit \u00eatre aussi grand que le justifient les circonstances. Le signe pourra, lorsqu&rsquo;il est appos\u00e9 sur une grande surface, \u00eatre r\u00e9p\u00e9t\u00e9 aussi souvent que le justifient les circonstances. Dans la mesure du possible, il doit \u00eatre appos\u00e9 sur des drapeaux ou sur des surfaces planes de fa\u00e7on \u00e0 \u00eatre rendu visible de toutes les directions possibles et d&rsquo;aussi loin que possible.<\/p>\n<p>3. Sur un drapeau, la distance entre les limites ext\u00e9rieures du signe et les c\u00f4t\u00e9s adjacents du drapeau sera \u00e9gale au rayon des cercles. Le drapeau sera rectangulaire et le fond blanc.<\/p>\n<p>4. De nuit ou par visibilit\u00e9 r\u00e9duite, le signe pourra \u00eatre \u00e9clair\u00e9 ou illumin\u00e9; il pourra \u00e9galement \u00eatre fait de mat\u00e9riaux le rendant reconnaissable par des moyens techniques de d\u00e9tection.<\/p>\n<p>Fig. 5 : Signe sp\u00e9cial international pour les ouvrages et installations contenant des forces dangereuses<\/p>\n<h3>Annexe II<\/h3>\n<p>Carte d&rsquo;identit\u00e9 de journaliste en mission p\u00e9rilleuse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ADOPT\u00c9 08 juin 1977 PAR la Conf\u00e9rence diplomatique sur la r\u00e9affirmation et le d\u00e9veloppement du droit international humanitaire Entr\u00e9e en vigueur : le 7 d\u00e9cembre 1978, conform\u00e9ment aux dispositions de l&rsquo;Article 95 Pr\u00e9ambule Les Hautes Parties contractantes Proclamant leur d\u00e9sir ardent de voir la paix r\u00e9gner entre les peuples, Rappelant que tout Etat a le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6351","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I) | \u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I) | \u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646\" \/>\n<meta property=\"og:description\" content=\"ADOPT\u00c9 08 juin 1977 PAR la Conf\u00e9rence diplomatique sur la r\u00e9affirmation et le d\u00e9veloppement du droit international humanitaire Entr\u00e9e en vigueur : le 7 d\u00e9cembre 1978, conform\u00e9ment aux dispositions de l&rsquo;Article 95 Pr\u00e9ambule Les Hautes Parties contractantes Proclamant leur d\u00e9sir ardent de voir la paix r\u00e9gner entre les peuples, Rappelant que tout Etat a le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NHRCLB\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T16:20:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nhrclb\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"178 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr\\\/protocol-additional-geneva-conventions-12-august-1949\",\"url\":\"https:\\\/\\\/nhrclb.org\\\/fr\\\/protocol-additional-geneva-conventions-12-august-1949\",\"name\":\"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I) | \u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr#website\"},\"datePublished\":\"2026-03-20T10:06:32+00:00\",\"dateModified\":\"2026-04-05T16:20:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr\\\/protocol-additional-geneva-conventions-12-august-1949#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhrclb.org\\\/fr\\\/protocol-additional-geneva-conventions-12-august-1949\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr\\\/protocol-additional-geneva-conventions-12-august-1949#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/nhrclb.org\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr#website\",\"url\":\"https:\\\/\\\/nhrclb.org\\\/fr\",\"name\":\"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646\",\"description\":\"\u0645\u0624\u0633\u0633\u0629 \u0648\u0637\u0646\u064a\u0629 \u0645\u0633\u062a\u0642\u0644\u0629 \u0644\u062d\u0645\u0627\u064a\u0629 \u0648\u062a\u0639\u0632\u064a\u0632 \u062d\u0642\u0648\u0642 \u0627\u0644\u0627\u0646\u0633\u0627\u0646 \u0648\u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 \u0645\u0646\u0634\u0627\u0629 \u0628\u0645\u0648\u062c\u0628 \u0627\u0644\u0642\u0627\u0646\u0648\u0646 62\\\/ 2016\",\"publisher\":{\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr#organization\"},\"alternateName\":\"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0627\u0646\u0633\u0627\u0646 \u0627\u0644\u0645\u062a\u0636\u0645\u0646\u0629 \u0644\u062c\u0646\u0629 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 - \u0627\u0644\u062c\u0645\u0647\u0648\u0631\u064a\u0629 \u0627\u0644\u0644\u0628\u0646\u0627\u0646\u064a\u0629\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhrclb.org\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr#organization\",\"name\":\"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0627\u0644\u0645\u062a\u0636\u0645\u0646\u0629 \u0644\u062c\u0646\u0629 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 - \u0644\u0628\u0646\u0627\u0646\",\"url\":\"https:\\\/\\\/nhrclb.org\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nhrclb.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/NHRC-CPT-Logo.png\",\"contentUrl\":\"https:\\\/\\\/nhrclb.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/NHRC-CPT-Logo.png\",\"width\":1017,\"height\":761,\"caption\":\"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0627\u0644\u0645\u062a\u0636\u0645\u0646\u0629 \u0644\u062c\u0646\u0629 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 - \u0644\u0628\u0646\u0627\u0646\"},\"image\":{\"@id\":\"https:\\\/\\\/nhrclb.org\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NHRCLB\",\"https:\\\/\\\/x.com\\\/nhrclb\",\"https:\\\/\\\/www.instagram.com\\\/nhrc_lb\",\"https:\\\/\\\/www.youtube.com\\\/@lebanonsnhrccpt2364\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/145354751@N08\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I) | \u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949","og_locale":"fr_FR","og_type":"article","og_title":"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I) | \u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646","og_description":"ADOPT\u00c9 08 juin 1977 PAR la Conf\u00e9rence diplomatique sur la r\u00e9affirmation et le d\u00e9veloppement du droit international humanitaire Entr\u00e9e en vigueur : le 7 d\u00e9cembre 1978, conform\u00e9ment aux dispositions de l&rsquo;Article 95 Pr\u00e9ambule Les Hautes Parties contractantes Proclamant leur d\u00e9sir ardent de voir la paix r\u00e9gner entre les peuples, Rappelant que tout Etat a le [&hellip;]","og_url":"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949","og_site_name":"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646","article_publisher":"https:\/\/www.facebook.com\/NHRCLB","article_modified_time":"2026-04-05T16:20:19+00:00","twitter_card":"summary_large_image","twitter_site":"@nhrclb","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"178 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949","url":"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949","name":"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I) | \u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646","isPartOf":{"@id":"https:\/\/nhrclb.org\/fr#website"},"datePublished":"2026-03-20T10:06:32+00:00","dateModified":"2026-04-05T16:20:19+00:00","breadcrumb":{"@id":"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhrclb.org\/fr\/protocol-additional-geneva-conventions-12-august-1949#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/nhrclb.org\/fr"},{"@type":"ListItem","position":2,"name":"Protocole additionnel aux Conventions de Gen\u00e8ve du 12 ao\u00fbt 1949 relatif \u00e0 la protection des victimes des conflits arm\u00e9s internationaux (Protocole I)"}]},{"@type":"WebSite","@id":"https:\/\/nhrclb.org\/fr#website","url":"https:\/\/nhrclb.org\/fr","name":"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 - \u0644\u0628\u0646\u0627\u0646","description":"\u0645\u0624\u0633\u0633\u0629 \u0648\u0637\u0646\u064a\u0629 \u0645\u0633\u062a\u0642\u0644\u0629 \u0644\u062d\u0645\u0627\u064a\u0629 \u0648\u062a\u0639\u0632\u064a\u0632 \u062d\u0642\u0648\u0642 \u0627\u0644\u0627\u0646\u0633\u0627\u0646 \u0648\u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 \u0645\u0646\u0634\u0627\u0629 \u0628\u0645\u0648\u062c\u0628 \u0627\u0644\u0642\u0627\u0646\u0648\u0646 62\/ 2016","publisher":{"@id":"https:\/\/nhrclb.org\/fr#organization"},"alternateName":"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0627\u0646\u0633\u0627\u0646 \u0627\u0644\u0645\u062a\u0636\u0645\u0646\u0629 \u0644\u062c\u0646\u0629 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 - \u0627\u0644\u062c\u0645\u0647\u0648\u0631\u064a\u0629 \u0627\u0644\u0644\u0628\u0646\u0627\u0646\u064a\u0629","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhrclb.org\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nhrclb.org\/fr#organization","name":"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0627\u0644\u0645\u062a\u0636\u0645\u0646\u0629 \u0644\u062c\u0646\u0629 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 - \u0644\u0628\u0646\u0627\u0646","url":"https:\/\/nhrclb.org\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nhrclb.org\/fr#\/schema\/logo\/image\/","url":"https:\/\/nhrclb.org\/wp-content\/uploads\/2024\/01\/NHRC-CPT-Logo.png","contentUrl":"https:\/\/nhrclb.org\/wp-content\/uploads\/2024\/01\/NHRC-CPT-Logo.png","width":1017,"height":761,"caption":"\u0627\u0644\u0647\u064a\u0626\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0627\u0644\u0645\u062a\u0636\u0645\u0646\u0629 \u0644\u062c\u0646\u0629 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 - \u0644\u0628\u0646\u0627\u0646"},"image":{"@id":"https:\/\/nhrclb.org\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NHRCLB","https:\/\/x.com\/nhrclb","https:\/\/www.instagram.com\/nhrc_lb","https:\/\/www.youtube.com\/@lebanonsnhrccpt2364","https:\/\/www.flickr.com\/photos\/145354751@N08"]}]}},"_links":{"self":[{"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/pages\/6351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/comments?post=6351"}],"version-history":[{"count":1,"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/pages\/6351\/revisions"}],"predecessor-version":[{"id":6352,"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/pages\/6351\/revisions\/6352"}],"wp:attachment":[{"href":"https:\/\/nhrclb.org\/fr\/wp-json\/wp\/v2\/media?parent=6351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}